{"id":273,"date":"2013-12-12T13:51:55","date_gmt":"2013-12-12T13:51:55","guid":{"rendered":"https:\/\/blogs.ua.es\/aikido\/?p=273"},"modified":"2016-02-19T14:42:59","modified_gmt":"2016-02-19T14:42:59","slug":"una-nueva-etapa-curso-en-alicante","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/aikido\/una-nueva-etapa-curso-en-alicante\/","title":{"rendered":"Una Nueva Etapa. Curso en Alicante"},"content":{"rendered":"<p><strong>Un post de Fidel P\u00e9rez<br \/>\npublicado en el <em><a title=\"Una Nueva Etapa. Curso en Alicante\" href=\"http:\/\/aikikai.org.es\/blog\/?p=898\">Blog de Aetaiki &#8211; Aikikai de Espa\u00f1a<\/a><\/em><\/strong><\/p>\n<p style=\"text-align: justify\">Los d\u00edas 16 y 17 de noviembre de 2013 <a title=\"Curso Nacional de Aikido en Alicante. Tom\u00e1s S\u00e1nchez Shihan, 7\u00ba Dan\" href=\"https:\/\/blogs.ua.es\/aikido\/2013\/11\/10\/curso-nacional-de-aikido-en-alicante-tomas-sanchez-shihan-7o-dan\/\" target=\"_blank\">tuvimos el place de contar con el maestro Tom\u00e1s S\u00e1nchez, 7\u00ba dan Aikikai<\/a>, en Alicante para impartir un curso y realizar ex\u00e1menes de paso de grado dan. Este fue un curso especial, debido a los \u00faltimos acontecimientos que han rodeado al Aikido AETAIKI en la regi\u00f3n levantina.\u00a0 Cre\u00edamos que la secesi\u00f3n de alg\u00fan grupo de la zona que antes formaba parte de la Asociaci\u00f3n podr\u00eda influir negativamente, \u00a0sin embargo estos resultaron ser temores infundados y\u00a0 una vez m\u00e1s el respaldo que tiene Tom\u00e1s S\u00e1nchez Shihan volvi\u00f3 a quedar de manifiesto.\u00a0 Hubo una gran afluencia de aikidokas provenientes de la mayor parte de la geograf\u00eda nacional. Esto incluso con el mal tiempo que hizo durante ese fin de semana, y que dejo poco transitables algunas carreteras. <!--more-->Al final, fuimos casi 50 practicantes los que disfrutamos de sus ense\u00f1anzas.<\/p>\n<p><a href=\"http:\/\/aikikai.org.es\/blog\/wp-content\/uploads\/2013\/12\/tsalic145.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Foto de grupo curso de Tom\u00e1s S\u00e1nchez Shihan en Alicante, 16 y 17 de Noviembre de 2013\" src=\"http:\/\/aikikai.org.es\/blog\/wp-content\/uploads\/2013\/12\/tsalic145.jpg\" alt=\"Foto de grupo curso de Tom\u00e1s S\u00e1nchez Shihan en Alicante, 16 y 17 de Noviembre de 2013\" width=\"944\" height=\"316\" \/><\/a><\/p>\n<p style=\"text-align: justify\">El trabajo desarrollado no defraud\u00f3, y fue el que estamos acostumbrados: intensidad, marcialidad, y calidad t\u00e9cnica; todo al mismo tiempo. Los que all\u00ed est\u00e1bamos trabajamos tratamos de responder a esas premisas, sabiendo que nuestras capacidades t\u00e9cnica y de sacrificio se demuestran en cada curso. De las t\u00e9cnicas practicadas que fueron muchas, tanto de de manos libres, como con armas, todos tomamos buena nota, pero especialmente los que se examinaban porque como es habitual luego fueron preguntadas.<\/p>\n<p style=\"text-align: justify\"><a title=\"tsalic143\" href=\"http:\/\/aikikai.org.es\/blog\/wp-content\/uploads\/2013\/12\/tsalic143.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" title=\"Tribunal de examen en Alicante, 16 y 17 de Noviembre de 2013\" src=\"http:\/\/aikikai.org.es\/blog\/wp-content\/uploads\/2013\/12\/tsalic143-150x150.jpg\" alt=\"Tribunal de examen en Alicante, 16 y 17 de Noviembre de 2013\" width=\"150\" height=\"150\" \/><\/a>El domingo por la ma\u00f1ana, a las pruebas de paso de grado se presentaron diez personas: cuatro de Alicante, uno de Alcoy, dos de Madrid, uno de Castell\u00f3n, y dos de C\u00f3rdoba. Todos ellos aspirantes a primer dan, excepto uno de los cordobeses que se presentaba a segundo dan. En cuanto a la representaci\u00f3n por sexos, el 20% fueron mujeres.\u00a0 El aprobado fue general, aunque \u2013claro- algunos con mejor nota que otros.<\/p>\n<p style=\"text-align: justify\"><a title=\"tsalic144\" href=\"http:\/\/aikikai.org.es\/blog\/wp-content\/uploads\/2013\/12\/tsalic144.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Fidel P\u00e9rez, nuevo cargo como delegado Aetaiki - Aikikai de Espa\u00f1a para la zona de Levante\" src=\"http:\/\/aikikai.org.es\/blog\/wp-content\/uploads\/2013\/12\/tsalic144-150x150.jpg\" alt=\"Fidel P\u00e9rez, nuevo cargo como delegado Aetaiki - Aikikai de Espa\u00f1a para la zona de Levante\" width=\"150\" height=\"150\" \/><\/a>Un momento emotivo para m\u00ed fue cuando se me comunico durante el curso mi nuevo cargo como delegado para la zona de Levante. \u201cMe llena de orgullo y satisfacci\u00f3n\u2026. \u201c. Bromas aparte, es un cargo que acept\u00e9 encantado sabiendo la responsabilidad que entra\u00f1a; especialmente ante la nueva etapa que <a title=\"La asociaci\u00f3n AETAIKI \u2013 Aikikai de Espa\u00f1a\" href=\"https:\/\/blogs.ua.es\/aikido\/la-asociacion-aetaiki-aikikai-de-espana\/\" target=\"_blank\">la Asociaci\u00f3n<\/a> est\u00e1 comenzando, y que pone nuestras miras hacia el Aikikai de Tokyo.<\/p>\n<p style=\"text-align: justify\">Dado el \u00e9xito alcanzado, el maestro Tom\u00e1s se comprometi\u00f3 a seguir visitando Alicante para impartir cursos cada dos a\u00f1os, como hasta ahora lo hab\u00eda hecho. Ya falta menos para el pr\u00f3ximo curso en 2015, el cual todos esperamos con impaciencia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><span style=\"line-height: 1.4em\">Agradecer enormemente su presencia a Tom\u00e1s S\u00e1nchez y a todos aquellos que se desplazaron hasta Alicante para asistir al curso.\u00a0 Tambi\u00e9n\u00a0 aprovecho la ocasi\u00f3n para desearos unas felices navidades y un pr\u00f3spero a\u00f1o nuevo.<\/span><\/p>\n<p style=\"text-align: right\"><a href=\"https:\/\/aikidosanvicente.wordpress.com\/about\/#fidel_perez_aikido_san_vicente_alicante\"><strong>Fidel P\u00e9rez Sebasti\u00e1n\u00a0<\/strong><\/a><br \/>\n<strong>5\u00ba Dan AIKIKAI,\u00a0<em>Shidoin<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un post de Fidel P\u00e9rez publicado en el Blog de Aetaiki &#8211; Aikikai de Espa\u00f1a Los d\u00edas 16 y 17 de noviembre de 2013 tuvimos el place de contar con el maestro Tom\u00e1s S\u00e1nchez, 7\u00ba dan Aikikai, en Alicante para &hellip; <a href=\"https:\/\/blogs.ua.es\/aikido\/una-nueva-etapa-curso-en-alicante\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3230,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,121721,835],"tags":[],"class_list":["post-273","post","type-post","status-publish","format-standard","hentry","category-blog","category-cronica","category-cursos"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/posts\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/users\/3230"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/comments?post=273"}],"version-history":[{"count":24,"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/posts\/273\/revisions"}],"predecessor-version":[{"id":980,"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/posts\/273\/revisions\/980"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/media?parent=273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/categories?post=273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/aikido\/wp-json\/wp\/v2\/tags?post=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}