{"id":271,"date":"2014-01-11T21:06:32","date_gmt":"2014-01-11T20:06:32","guid":{"rendered":"https:\/\/blogs.ua.es\/alcoy5\/?p=271"},"modified":"2014-01-12T13:18:42","modified_gmt":"2014-01-12T12:18:42","slug":"nicho-en-el-que-destaca-la-profesion","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alcoy5\/2014\/01\/11\/nicho-en-el-que-destaca-la-profesion\/","title":{"rendered":"Nicho en el que destaca la profesi\u00f3n"},"content":{"rendered":"<p style=\"text-align: center\"><a href=\"https:\/\/blogs.ua.es\/alcoy5\/files\/2014\/01\/DSC_0235.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-152\" alt=\"DSC_0235\" src=\"https:\/\/blogs.ua.es\/alcoy5\/files\/2014\/01\/DSC_0235-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/alcoy5\/files\/2014\/01\/DSC_0235-300x225.jpg 300w, https:\/\/blogs.ua.es\/alcoy5\/files\/2014\/01\/DSC_0235.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left\">Este nicho situado en el <a title=\"cementerio de Alcoy\" href=\"https:\/\/maps.google.es\/maps?ie=UTF-8&amp;q=cementerio+de+alcoy&amp;fb=1&amp;gl=es&amp;hq=cementerio&amp;hnear=0xd61864e204bb377:0x3270bc5ab4510472,Alcoy,+Alicante&amp;ei=bI_RUsOiMcS50QWGzYC4Ag&amp;ved=0CLYBEMgT\" target=\"_blank\">cementerio de Alcoy<\/a> destaca por la imagen impresa en la que se observa al finado ejerciendo su profesi\u00f3n de fot\u00f3grafo, para que quede constancia como dato relevante para su recuerdo. Tambi\u00e9n destaca el texto impreso, con letra blanca sobre el granito negro: &#8220;Tu lucha fue la nuestra, tu perdida la gran pena, no nos olvides nunca, nosotros no lo haremos&#8221;. En muy pocas inscripciones se colocan las comas, sin embargo, en esta dedicatoria existen tres, aunque no hay punto final ni acentos.<\/p>\n<p style=\"text-align: left\">No obstante, falta una coma en la leyenda: &#8220;tu esposa hijos y familia&#8221;. La graf\u00eda utilizada pertenece al sistema operativo Windows, muy moderno para el a\u00f1o del fallecimiento, 2003.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este nicho situado en el cementerio de Alcoy destaca por la imagen impresa en la que se observa al finado ejerciendo su profesi\u00f3n de fot\u00f3grafo, para que quede constancia como dato relevante para su recuerdo. Tambi\u00e9n destaca el texto impreso, &hellip; <a href=\"https:\/\/blogs.ua.es\/alcoy5\/2014\/01\/11\/nicho-en-el-que-destaca-la-profesion\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3365,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274049],"tags":[3394,282277,490094,426178],"class_list":["post-271","post","type-post","status-publish","format-standard","hentry","category-inscripciones-y-placas-en-cementerios","tag-alcoy","tag-cementerio","tag-granito","tag-nicho"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/posts\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/users\/3365"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/posts\/271\/revisions"}],"predecessor-version":[{"id":319,"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/posts\/271\/revisions\/319"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/media?parent=271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/categories?post=271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alcoy5\/wp-json\/wp\/v2\/tags?post=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}