{"id":142,"count":1,"description":"","link":"https:\/\/blogs.ua.es\/alicante1\/tag\/san-vicente-del-raspeig\/","name":"San Vicente del Raspeig","slug":"san-vicente-del-raspeig","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante1\/wp-json\/wp\/v2\/tags\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/alicante1\/wp-json\/wp\/v2\/posts?tags=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}