{"id":148,"date":"2013-12-07T17:22:59","date_gmt":"2013-12-07T17:22:59","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante3\/?p=148"},"modified":"2013-12-18T09:00:43","modified_gmt":"2013-12-18T09:00:43","slug":"jose-antonio-primo-de-rivera","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante3\/2013\/12\/07\/jose-antonio-primo-de-rivera\/","title":{"rendered":"Jos\u00e9 Antonio Primo de Rivera"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante3\/files\/2013\/12\/Primo-de-Rivera.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-149\" alt=\"Primo de Rivera\" src=\"https:\/\/blogs.ua.es\/alicante3\/files\/2013\/12\/Primo-de-Rivera.jpg\" width=\"450\" height=\"253\" srcset=\"https:\/\/blogs.ua.es\/alicante3\/files\/2013\/12\/Primo-de-Rivera.jpg 450w, https:\/\/blogs.ua.es\/alicante3\/files\/2013\/12\/Primo-de-Rivera-300x168.jpg 300w, https:\/\/blogs.ua.es\/alicante3\/files\/2013\/12\/Primo-de-Rivera-150x84.jpg 150w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>Fotograf\u00eda tomada en el cementerio de Alicante<\/p>\n<p>Fecha: 6\/12\/2013<\/p>\n<p>Jos\u00e9 Antonio Primo de Rivera (1903-1936), hijo del dictador Miguel Primo de Rivera y creador de la Falange Espa\u00f1ola, fue apresado al comienzo de la Guerra Civil Espa\u00f1ola y condenado a muerte por el bando republicano. <a href=\"https:\/\/www.youtube.com\/watch?v=xJLIhhXR-uM\">Los falangistas<\/a><\/p>\n<p>La premonitoria sentencia de Jos\u00e9 Antonio Primo de Rivera nos hiela la sangre.<\/p>\n<p>Bibliograf\u00eda: Biograf\u00eda y vidas. <em>Jos\u00e9 Antonio Primo de Rivera <\/em>[en l\u00ednea]. 2004-2013, [consulta: 7\/12\/2013]. Enlace web: <a href=\"http:\/\/www.biografiasyvidas.com\/biografia\/p\/primo.htm\">http:\/\/www.biografiasyvidas.com\/biografia\/p\/primo.htm<\/a><\/p>\n<p>Youtube.es.<i>\u00a0Los falangistas\u00a0<\/i>[en l\u00ednea]. [Consulta: 6\/12\/2013]. Enlace web:\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=xJLIhhXR-uM\">https:\/\/www.youtube.com\/watch?v=xJLIhhXR-uM<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotograf\u00eda tomada en el cementerio de Alicante Fecha: 6\/12\/2013 Jos\u00e9 Antonio Primo de Rivera (1903-1936), hijo del dictador Miguel Primo de Rivera y creador de la Falange Espa\u00f1ola, fue apresado al comienzo de la Guerra Civil Espa\u00f1ola y condenado a muerte por el bando republicano. Los falangistas La premonitoria sentencia de Jos\u00e9 Antonio Primo de [&hellip;]<\/p>\n","protected":false},"author":3334,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274049],"tags":[329416],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-inscripciones-y-placas-en-cementerios","tag-jose-antonio-primo-de-rivera"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/users\/3334"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"predecessor-version":[{"id":341,"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/posts\/148\/revisions\/341"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante3\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}