{"id":178,"date":"2013-12-25T01:44:21","date_gmt":"2013-12-25T00:44:21","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante4\/?p=178"},"modified":"2013-12-25T16:02:23","modified_gmt":"2013-12-25T15:02:23","slug":"calle-de-montescon","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante4\/2013\/12\/25\/calle-de-montescon\/","title":{"rendered":"calle de Montesc\u00f3n"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante4\/files\/2013\/12\/Calle-Monteg\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-179\" alt=\"Calle Monteg\u00f3n\" src=\"https:\/\/blogs.ua.es\/alicante4\/files\/2013\/12\/Calle-Monteg\u00f3n-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/alicante4\/files\/2013\/12\/Calle-Monteg\u00f3n-300x225.jpg 300w, https:\/\/blogs.ua.es\/alicante4\/files\/2013\/12\/Calle-Monteg\u00f3n.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> \u00a0 Esta fotograf\u00eda muestra las placas de la Calle de Monteg\u00f3n, la \u00a0primera con el nombre de la calle y la segunda con la explicaci\u00f3n. Una calle que ha soportado todo el peso de la circulaci\u00f3n la peque\u00f1a calle dedicada a Monteg\u00f3n. La placa est\u00e1 localizada en la Calle de Monteg\u00f3n en Alicante. Referencia bibliogr\u00e1fica: http:\/\/books.google.es\/books?isbn=8484547299. La fecha de la fotograf\u00eda es Alicante 13 de diciembre de 2013. La fecha de la de la visita a la Web es Elche 25 de diciembre de 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Esta fotograf\u00eda muestra las placas de la Calle de Monteg\u00f3n, la \u00a0primera con el nombre de la calle y la segunda con la explicaci\u00f3n. Una calle que ha soportado todo el peso de la circulaci\u00f3n la peque\u00f1a calle dedicada &hellip; <a href=\"https:\/\/blogs.ua.es\/alicante4\/2013\/12\/25\/calle-de-montescon\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3255,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274164,676],"tags":[180,6350,578532,578820],"class_list":["post-178","post","type-post","status-publish","format-standard","hentry","category-inscripciones-y-placas-oficiales","category-sin-categoria","tag-alicante","tag-calle","tag-montegon","tag-san-anton"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/users\/3255"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts\/178\/revisions"}],"predecessor-version":[{"id":183,"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts\/178\/revisions\/183"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/media?parent=178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/categories?post=178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags?post=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}