{"id":1022349,"count":1,"description":"","link":"https:\/\/blogs.ua.es\/alicante4\/tag\/heliodoro-guillen\/","name":"Heliodoro Guillen","slug":"heliodoro-guillen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags\/1022349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts?tags=1022349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}