{"id":1114009,"count":1,"description":"","link":"https:\/\/blogs.ua.es\/alicante4\/tag\/golfin\/","name":"Golf\u00edn","slug":"golfin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags\/1114009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts?tags=1114009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}