{"id":3409,"count":1,"description":"","link":"https:\/\/blogs.ua.es\/alicante4\/tag\/jovenes\/","name":"j\u00f3venes","slug":"jovenes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags\/3409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/alicante4\/wp-json\/wp\/v2\/posts?tags=3409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}