{"id":154,"date":"2013-12-19T12:25:04","date_gmt":"2013-12-19T12:25:04","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante6\/?p=154"},"modified":"2014-01-14T13:52:09","modified_gmt":"2014-01-14T13:52:09","slug":"graffiti-en-muros-5","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante6\/2013\/12\/19\/graffiti-en-muros-5\/","title":{"rendered":"Graffiti en muros"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/pintor.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-157\" alt=\"pintor\" src=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/pintor-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/pintor-225x300.jpg 225w, https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/pintor.jpg 451w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Este <em>graffiti<\/em> se encuentra representado sobre una puerta, vemos un ni\u00f1o de espaldas, dibujando una paisaje, en el cual podemos ver una casa con una arcoiris, flores, animales. Representa los t\u00edpicos paisajes que realizan todos los ni\u00f1os de corta edad.<\/p>\n<p>Se encuentra en\u00a0Avd. Poeta Carmelo Calvo. N\u00ba 2, fotografiado el 28 de noviembre de 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Este graffiti se encuentra representado sobre una puerta, vemos un ni\u00f1o de espaldas, dibujando una paisaje, en el cual podemos ver una casa con una arcoiris, flores, animales. Representa los t\u00edpicos paisajes que realizan todos los ni\u00f1os de corta edad. Se encuentra en\u00a0Avd. Poeta Carmelo Calvo. N\u00ba 2, fotografiado el 28 de noviembre de [&hellip;]<\/p>\n","protected":false},"author":3247,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278411],"tags":[180,1360,199219,288694,285700],"class_list":["post-154","post","type-post","status-publish","format-standard","hentry","category-grafities-iconograficos","tag-alicante","tag-arte","tag-fachada","tag-graffiti","tag-iconografico"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/users\/3247"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/comments?post=154"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/154\/revisions"}],"predecessor-version":[{"id":428,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/154\/revisions\/428"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/media?parent=154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/categories?post=154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/tags?post=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}