{"id":209,"date":"2013-12-19T15:34:24","date_gmt":"2013-12-19T15:34:24","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante6\/?p=209"},"modified":"2014-01-06T23:05:46","modified_gmt":"2014-01-06T23:05:46","slug":"graffiti-en-muros-12","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante6\/2013\/12\/19\/graffiti-en-muros-12\/","title":{"rendered":"Graffiti en muros"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/rostros.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-210\" alt=\"rostros\" src=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/rostros-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/rostros-300x225.jpg 300w, https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/rostros.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En este muro se aprecian diferentes caricaturas, el primero es un rostro que aparece entre una nube rodeado de una serie de flores y ramas que podr\u00eda reflejar la naturaleza. El segundo rostro mas caracter\u00edstico de una persona, desarrolla una cierta similitud con personajes de videojuegos, este personaje tambi\u00e9n aparece en el centro de una nube y a su alrededor el <em>graffiti<\/em> de distintas letras. No teniendo de precedente ninguna tem\u00e1tica en concreto.<\/p>\n<p>Se encuentra situado en\u00a0C\/ del Capit\u00e1n Boaccio, fotografiado el 28 de noviembre de 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; En este muro se aprecian diferentes caricaturas, el primero es un rostro que aparece entre una nube rodeado de una serie de flores y ramas que podr\u00eda reflejar la naturaleza. El segundo rostro mas caracter\u00edstico de una persona, desarrolla una cierta similitud con personajes de videojuegos, este personaje tambi\u00e9n aparece en el centro de [&hellip;]<\/p>\n","protected":false},"author":3247,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278411],"tags":[180,288694,285700,502392,502670],"class_list":["post-209","post","type-post","status-publish","format-standard","hentry","category-grafities-iconograficos","tag-alicante","tag-graffiti","tag-iconografico","tag-muros","tag-rostros-y-caras"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/users\/3247"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/comments?post=209"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/209\/revisions"}],"predecessor-version":[{"id":408,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/209\/revisions\/408"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/media?parent=209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/categories?post=209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/tags?post=209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}