{"id":388,"date":"2014-01-05T12:12:08","date_gmt":"2014-01-05T12:12:08","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante6\/?p=388"},"modified":"2014-01-05T12:14:36","modified_gmt":"2014-01-05T12:14:36","slug":"graffiti-en-muros-18","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante6\/2014\/01\/05\/graffiti-en-muros-18\/","title":{"rendered":"Graffiti en muros"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11828.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-389\" alt=\"\" src=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11828-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11828-225x300.jpg 225w, https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11828.jpg 450w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11829.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-390\" alt=\"\" src=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11829-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11829-225x300.jpg 225w, https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11829.jpg 450w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Esta representaci\u00f3n es una ejemplo de arte urbano donde la iconograf\u00eda y los elementos textuales conjugan, dando un conjunto muy original y llamativo. El uso de colores oscuros tanto del negro como morados y lilas permiten hacer un sombreado caracter\u00edstico. Esta composici\u00f3n plasma por un lado el rostro de un tigre y por otro lado la obra &#8220;Thriller&#8221; de Michael Jackson. Ambos trasmiten el car\u00e1cter de los 80s tanto el primero pues se vincula a la canci\u00f3n &#8220;Eye of the tiger&#8221; del grupo Survivor como el segundo, temas musicales muy escuchados durante esa d\u00e9cada.<\/p>\n<p>Localizaci\u00f3n: Avda. Jaime I. 03009 Alicante.<\/p>\n<p>Realizaci\u00f3n de la fotograf\u00eda. 10\/12\/2013<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Esta representaci\u00f3n es una ejemplo de arte urbano donde la iconograf\u00eda y los elementos textuales conjugan, dando un conjunto muy original y llamativo. El uso de colores oscuros tanto del negro como morados y lilas permiten hacer un sombreado caracter\u00edstico. Esta composici\u00f3n plasma por un lado el rostro de un tigre y por otro [&hellip;]<\/p>\n","protected":false},"author":3239,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278411],"tags":[1360,285700,502670,3227],"class_list":["post-388","post","type-post","status-publish","format-standard","hentry","category-grafities-iconograficos","tag-arte","tag-iconografico","tag-rostros-y-caras","tag-urbano"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/users\/3239"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/388\/revisions"}],"predecessor-version":[{"id":393,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/388\/revisions\/393"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/media?parent=388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/categories?post=388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/tags?post=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}