{"id":459,"date":"2014-01-11T13:44:52","date_gmt":"2014-01-11T13:44:52","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante6\/?p=459"},"modified":"2014-01-11T13:44:52","modified_gmt":"2014-01-11T13:44:52","slug":"publicidad-de-comercios-14","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante6\/2014\/01\/11\/publicidad-de-comercios-14\/","title":{"rendered":"Publicidad de comercios"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11865.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-460\" alt=\"\" src=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11865-227x300.jpg\" width=\"227\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11865-227x300.jpg 227w, https:\/\/blogs.ua.es\/alicante6\/files\/2014\/01\/SDC11865.jpg 360w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Publicidad de un comercio local, concr\u00e9tamente una joyer\u00eda local. La ilustraci\u00f3n en el graffiti de una mujer joven y tonalidades rosadas en su entorno es muestra del sector de la demanda al que se dirige, las mujeres.<\/p>\n<p>Localizaci\u00f3n:\u00a0Plaza de los Luceros 7.\u00a003003 Alicante\u00a0\u200e<\/p>\n<p>Realizaci\u00f3n de la fotograf\u00eda. 10\/12\/2013<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Publicidad de un comercio local, concr\u00e9tamente una joyer\u00eda local. La ilustraci\u00f3n en el graffiti de una mujer joven y tonalidades rosadas en su entorno es muestra del sector de la demanda al que se dirige, las mujeres. Localizaci\u00f3n:\u00a0Plaza de los Luceros 7.\u00a003003 Alicante\u00a0\u200e Realizaci\u00f3n de la fotograf\u00eda. 10\/12\/2013<\/p>\n","protected":false},"author":3239,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278411],"tags":[2843,288694,186],"class_list":["post-459","post","type-post","status-publish","format-standard","hentry","category-grafities-iconograficos","tag-comercio","tag-graffiti","tag-publicidad"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/users\/3239"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/comments?post=459"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/459\/revisions"}],"predecessor-version":[{"id":461,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/459\/revisions\/461"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/media?parent=459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/categories?post=459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/tags?post=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}