{"id":75,"date":"2013-12-19T08:52:29","date_gmt":"2013-12-19T08:52:29","guid":{"rendered":"https:\/\/blogs.ua.es\/alicante6\/?p=75"},"modified":"2014-01-14T14:03:17","modified_gmt":"2014-01-14T14:03:17","slug":"graffiti-en-garajes-2","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/alicante6\/2013\/12\/19\/graffiti-en-garajes-2\/","title":{"rendered":"Graffiti en garajes"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/coche.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-81\" alt=\"coche\" src=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/coche-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/coche-300x225.jpg 300w, https:\/\/blogs.ua.es\/alicante6\/files\/2013\/12\/coche.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Podemos observar un coche rojo, situado en una carretera con una perspectiva c\u00f3nica, en un paisaje des\u00e9rtico. Donde el coche est\u00e1 dise\u00f1ado a tama\u00f1o real, de tal manera que da la sensaci\u00f3n de que es una autom\u00f3vil de verdad.\u00a0La tem\u00e1tica de estos <em>graffitis<\/em> en las puertas de los garajes no tienen ning\u00fan valor simb\u00f3lico, tan solo es un elemento de decoraci\u00f3n encargado a gusto de la comunidad de propietarios, con el fin de decorar. Lo que se deduce con un simple golpe de vista al ver esta imagen, es que ese local es un garaje.<\/p>\n<p>Se localiza en la\u00a0C\/ Maestro Barbieri n\u00ba 16. 03004, fotografiado el\u00a028 de noviembre de 2013.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Podemos observar un coche rojo, situado en una carretera con una perspectiva c\u00f3nica, en un paisaje des\u00e9rtico. Donde el coche est\u00e1 dise\u00f1ado a tama\u00f1o real, de tal manera que da la sensaci\u00f3n de que es una autom\u00f3vil de verdad.\u00a0La tem\u00e1tica de estos graffitis en las puertas de los garajes no tienen ning\u00fan valor simb\u00f3lico, [&hellip;]<\/p>\n","protected":false},"author":3247,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278411],"tags":[180,1513,492257,288694],"class_list":["post-75","post","type-post","status-publish","format-standard","hentry","category-grafities-iconograficos","tag-alicante","tag-coche","tag-garaje","tag-graffiti"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/users\/3247"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/comments?post=75"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/75\/revisions"}],"predecessor-version":[{"id":639,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/posts\/75\/revisions\/639"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/media?parent=75"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/categories?post=75"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/alicante6\/wp-json\/wp\/v2\/tags?post=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}