{"id":679644,"count":1,"description":"","link":"https:\/\/blogs.ua.es\/alicante7\/tag\/cupcakes\/","name":"cupcakes","slug":"cupcakes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/alicante7\/wp-json\/wp\/v2\/tags\/679644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/alicante7\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ua.es\/alicante7\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ua.es\/alicante7\/wp-json\/wp\/v2\/posts?tags=679644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}