{"id":328,"date":"2012-01-12T11:21:13","date_gmt":"2012-01-12T11:21:13","guid":{"rendered":"https:\/\/blogs.ua.es\/archivosciudadalicante\/?p=328"},"modified":"2012-01-16T19:47:23","modified_gmt":"2012-01-16T19:47:23","slug":"archivo-postcapital","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/archivosciudadalicante\/2012\/01\/12\/archivo-postcapital\/","title":{"rendered":"Archivo Postcapital"},"content":{"rendered":"<p><em>Archivo postcapital<\/em> G. AND\u00daJAR, Daniel 1989. [consulta: 12 de enero de 2012]. Disponible en: <a href=\"http:\/\/www.interaccioneselectorales.org\/?page_id=306\" target=\"_blank\">http:\/\/www.interaccioneselectorales.org\/?page_id=306<\/a><\/p>\n<p>A trav\u00e9s de Camon, sitio web que posee la\u00a0CAM con un archivo en su obra social de Alicante, hemos encontrado este archivo sobre pol\u00edtica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Archivo postcapital G. AND\u00daJAR, Daniel 1989. [consulta: 12 de enero de 2012]. Disponible en: http:\/\/www.interaccioneselectorales.org\/?page_id=306 A trav\u00e9s de Camon, sitio web que posee la\u00a0CAM con un archivo en su obra social de Alicante, hemos encontrado este archivo sobre pol\u00edtica.<\/p>\n","protected":false},"author":2383,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6674],"tags":[85344],"class_list":["post-328","post","type-post","status-publish","format-standard","hentry","category-recursos-electronicos","tag-fuentes"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/posts\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/users\/2383"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/comments?post=328"}],"version-history":[{"count":7,"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/posts\/328\/revisions"}],"predecessor-version":[{"id":383,"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/posts\/328\/revisions\/383"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/media?parent=328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/categories?post=328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/archivosciudadalicante\/wp-json\/wp\/v2\/tags?post=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}