{"id":35,"date":"2014-04-04T12:00:10","date_gmt":"2014-04-04T10:00:10","guid":{"rendered":"https:\/\/blogs.ua.es\/arqueoblog\/?p=35"},"modified":"2014-09-02T21:28:48","modified_gmt":"2014-09-02T19:28:48","slug":"excavacion-arqueologica","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/arqueoblog\/2014\/04\/04\/excavacion-arqueologica\/","title":{"rendered":"La excavaci\u00f3n Arqueol\u00f3gica"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>La Arqueolog\u00eda.<\/strong> Una materia que ha atra\u00eddo la curiosidad de la sociedad a lo largo de la Historia. Una disciplina que <strong>llama la atenci\u00f3n enormemente de p\u00fablico<\/strong> con diferentes inquietudes, sean estas intelectuales o se trate de simplemente morbo.<\/p>\n<p style=\"text-align: justify\">La mayor\u00eda de personas <strong>hemos o\u00eddo hablar de la Arqueolog\u00eda<\/strong> en alg\u00fan momento de nuestras vidas. Sin embargo, generalmente no se recibe <a title=\"Aprender a ense\u00f1ar Arqueolog\u00eda\" href=\"http:\/\/www.patrimoniointeligente.com\/ensenar-arqueologia\/\" target=\"_blank\">una educaci\u00f3n adecuada sobre Arqueolog\u00eda<\/a> y por eso en ocasiones se tergiversa su significado.<strong>Una noticia en el telediario<\/strong> sobre una importante cueva con pinturas de animales extintos, un <strong>art\u00edculo en un peri\u00f3dico local<\/strong> sobre un tesoro muy antiguo descubierto en nuestra tierra, <strong>una pel\u00edcula<\/strong> sobre la maldici\u00f3n que persigue a un equipo de arque\u00f3log@s por perturbar el milenario descanso de una momia egipcia, etc.<\/p>\n<p style=\"text-align: justify\">Pero la Arqueolog\u00eda es algo m\u00e1s. Es mucho m\u00e1s. Esta materia <strong>tiene por objetivo estudiar al ser humano, su evoluci\u00f3n, su desarrollo social.<\/strong> Un trabajo que se realiza desde muchas perspectivas. Y <strong>cada vez m\u00e1s se relaciona con otras materias de la ciencia<\/strong>. Biolog\u00eda, antropolog\u00eda, geolog\u00eda, incluso las matem\u00e1ticas. <strong>\u00bfQui\u00e9n dijo que la Arqueolog\u00eda es una materia de letras?<\/strong><\/p>\n<p style=\"text-align: justify\">Ha diferentes m\u00e9todos de abordar el estudio arqueol\u00f3gico y <strong>diferentes fuentes.<\/strong> Sin embargo, la principal y tradicional fuente de informaci\u00f3n de las sociedades del pasado son<strong> los objetos materiales<\/strong>. Y\u00a0 \u00e9stos, los objetos, se encuentran generalmente (que no siempre) enterrados, por tanto la Arqueolog\u00eda a d\u00eda de hoy, se desarrolla a partir de <strong>la excavaci\u00f3n arqueol\u00f3gica<\/strong>. Pico y pala.<\/p>\n<p style=\"text-align: justify\"><!--more--><\/p>\n<h1><\/h1>\n<h1><span style=\"color: #0000ff\"><b>La excavaci\u00f3n arqueol\u00f3gica<\/b><\/span><\/h1>\n<p style=\"text-align: justify\"><strong>Una excavaci\u00f3n arqueol\u00f3gica<\/strong> tiene como objetivo <strong>examinar y recopilar la informaci\u00f3n<\/strong> de un determinado yacimiento <strong>a trav\u00e9s del m\u00e9todo arqueol\u00f3gico<\/strong> de excavaci\u00f3n con el objetivo de<strong> estudiar las sociedades del pasado a partir de sus <a title=\"Las fuentes materiales de la Arqueolog\u00eda\" href=\"http:\/\/arqueoblog.com\/las-fuentes-materiales\/\" target=\"_blank\">fuentes materiales<\/a><\/strong>.<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/blogs.ua.es\/arqueoblog\/files\/2014\/04\/campo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-40 aligncenter\" title=\"arqueolog\u00eda de campo\" alt=\"excavaci\u00f3n arqueol\u00f3gica\" src=\"https:\/\/blogs.ua.es\/arqueoblog\/files\/2014\/04\/campo.jpg\" width=\"259\" height=\"194\" srcset=\"https:\/\/blogs.ua.es\/arqueoblog\/files\/2014\/04\/campo.jpg 259w, https:\/\/blogs.ua.es\/arqueoblog\/files\/2014\/04\/campo-150x112.jpg 150w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Es decir, que <strong>el objeto de estudio es el pasado,<\/strong> concretamente el pasado de la sociedad humana desde los inicios de la hominizaci\u00f3n hasta nuestro d\u00edas pr\u00e1cticamente. Y este objeto de estudio es abordado con <strong>un m\u00e9todo espec\u00edfico de trabajo que es la excavaci\u00f3n arqueol\u00f3gica<\/strong>. \u00a0Esta excavaci\u00f3n suele estar programada y controlada ya que el trabajo de campo ya de por s\u00ed destruye la <strong>principal fuente de informaci\u00f3n de la Arqueolog\u00eda, el yacimiento<\/strong>.<\/p>\n<p style=\"text-align: justify\"><strong>El objetivo principal<\/strong> de una excavaci\u00f3n arqueol\u00f3gica es el de<strong> recopilar toda informaci\u00f3n posible<\/strong> (objetos materiales, tipo de tierra, restos org\u00e1nicos, el medio f\u00edsico, etc). Una vez acabado el trabajo de campo, toda esa informaci\u00f3n es <strong>estudiada en el laboratorio<\/strong> para posteriormente publicar y difundir las conclusiones de dicha investigaci\u00f3n. Como podr\u00e1s coprobar, queda lejos de la violencia y el saqueo de objetos antiguos del arque\u00f3logo m\u00e1s famoso del cine.<\/p>\n<h2><span style=\"color: #0000ff\"><b>Cu\u00e1ndo excavar un yacimiento arqueol\u00f3gico<\/b><\/span><\/h2>\n<p style=\"text-align: justify\">Como ya he comentado, <strong>la actividad arqueol\u00f3gica es destructiva<\/strong>. Y s\u00f3lo tendr\u00e1s una oportunidad\u00a0 de excavar ese yacimiento arqueol\u00f3gico. Por tanto, como norma general, <strong>la excavaci\u00f3n de campo es el \u00faltimo recurso<\/strong> para recuperar informaci\u00f3n y estudiar el yacimiento. \u00a0Esto se llevar\u00e1 a cabo en determinadas circunstancias, algunas de las cuales pueden ser las siguientes:<\/p>\n<ul>\n<li style=\"text-align: justify\">Como<strong> medida de emergencia por el desarrollo de obras<\/strong> de infraestructura <strong>que pongan en peligro un yacimiento<\/strong> arqueol\u00f3gico recogido en la carta arqueol\u00f3gica de la ciudad. La construcci\u00f3n de un edificio en un solar, la construcci\u00f3n de una carretera, de una l\u00ednea de tren, etc.<\/li>\n<li style=\"text-align: justify\">Como parte de un <strong>proyecto de investigaci\u00f3n<\/strong> en cuyo caso, el yacimiento no se encuentre en pleigro sino que forme parte de un proceso de estudio por parte generalmente de la Universidad un ejemplo de proyecto de investigaci\u00f3n arqueol\u00f3gica llevado por la Universidad de Alicante es la del <a title=\"Proyecto Ifach\" href=\"http:\/\/proyectoifach.blogspot.com.es\/\" target=\"_blank\">yacimiento de Ifach<\/a>.<\/li>\n<li style=\"text-align: justify\">Con el fin de<strong> preservar un yacimiento<\/strong> bien de inter\u00e9s cultural que se encuentre en mal estado.<\/li>\n<\/ul>\n<p>En ocasiones el hallazgo se produce de manera casual y se procede a meter el pico y la pala para &#8220;rescatar&#8221; el yacimiento.<\/p>\n<p>Una vez iniciada la excavaci\u00f3n se proceder\u00e1 a la recuperaci\u00f3n de la informaci\u00f3n a trav\u00e9s<strong> del m\u00e9todo arqueol\u00f3gico<\/strong>. Pero eso te lo explico otro d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Arqueolog\u00eda. Una materia que ha atra\u00eddo la curiosidad de la sociedad a lo largo de la Historia. Una disciplina que llama la atenci\u00f3n enormemente de p\u00fablico con diferentes inquietudes, sean estas intelectuales o se trate de simplemente morbo. La mayor\u00eda de personas hemos o\u00eddo hablar de la Arqueolog\u00eda en alg\u00fan momento de nuestras vidas. [&hellip;]<\/p>\n","protected":false},"author":3050,"featured_media":40,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[810],"tags":[230252,230251],"class_list":["post-35","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arqueologia","tag-arqueologia-2","tag-excavacion-arqueologica"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/posts\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/users\/3050"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":8,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"predecessor-version":[{"id":56,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/posts\/35\/revisions\/56"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/media\/40"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/arqueoblog\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}