{"id":82,"date":"2022-06-16T14:35:23","date_gmt":"2022-06-16T14:35:23","guid":{"rendered":"https:\/\/blogs.ua.es\/barnizdesierto\/?p=82"},"modified":"2023-04-10T10:14:53","modified_gmt":"2023-04-10T10:14:53","slug":"terremotos-valldigna","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/barnizdesierto\/2022\/06\/16\/terremotos-valldigna\/","title":{"rendered":"Terremotos Valldigna"},"content":{"rendered":"<p>El terremoto de \u201cTabernes de 1396\u201d, en el valle de la Valldigna, se ha considerado como uno de los mayores terremotos que se tiene registro en la Pen\u00ednsula Ib\u00e9rica. La informaci\u00f3n utilizada para tales afirmaciones siempre ha partido de fuentes secundarias de la zona porque las originales se cre\u00edan perdidas. En este trabajo, a partir de una copia recientemente editada, del libro de la historia del Real monasterio de Nuestra Se\u00f1ora de la Valldigna, la \u201cHistoria Cronol\u00f3gica\u201d de Padre Estevan Gil, se fija la fecha del 16 de diciembre en vez del 18 de diciembre para el terremoto principal y se reinterpretan los da\u00f1os del terremoto, a partir de la fuente original. El monasterio fue destruido 3 veces por terremotos y se han edificado 4 iglesias, en vez de 3 como se cre\u00eda hasta ahora. El importante terremoto del 7 de noviembre de 1330 destruy\u00f3 la primera iglesia, emplazada en un lugar diferente a las 3 posteriores. El libro original aporta informaci\u00f3n de la \u00faltima destrucci\u00f3n de iglesia, en el terremoto de 1644, sus da\u00f1os y la reconstrucci\u00f3n. Por \u00faltimo, se mencionan otros dos terremotos en los a\u00f1os 1724 y 1748 que tambi\u00e9n aparecen reflejados en el libro del Padre Gil.<\/p>\n<div id=\"attachment_85\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85\" class=\"wp-image-85 size-large\" src=\"https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/figura_web_terramotos_simat-1024x953.jpg\" alt=\"\" width=\"450\" height=\"419\" srcset=\"https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/figura_web_terramotos_simat-1024x953.jpg 1024w, https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/figura_web_terramotos_simat-300x279.jpg 300w, https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/figura_web_terramotos_simat-768x715.jpg 768w, https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/figura_web_terramotos_simat-1536x1430.jpg 1536w, https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/figura_web_terramotos_simat.jpg 2030w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-85\" class=\"wp-caption-text\">Monasterio de Nuestra Se\u00f1ora de la Valldigna en Simat de la Valldigna (Valencia). Campanario y cabeza de la iglesia barroca, a la derecha la torre noreste almenada. Entre las dos torres estar\u00eda la sacrist\u00eda y en el piso superior el camaril de la Virgen de la Valldigna. Explicaci\u00f3n de las etapas constructivas del campanario. A la base unos arcos del mismo estilo de las construcciones de tiempos del abad Sara\u00f1\u00f3 por lo que deben ser anteriores al terremoto de 1396. Encima una parte del campanario que debi\u00f3 mantenerse en pie durante el terremoto de 1644. Encima la parte que se termin\u00f3 durante el abad Francisco Crua\u00f1es circa 1652. El cuerpo de las campanas realizado con m\u00e1rmol de Buixcarr\u00f3 durante el segundo abadiazgo de Rafael Trobado circa 1655. El remate final del campanario durante el abadiazgo de Josep Castillo circa 1698. Detalle de la zona de base del campanario donde se pueden apreciar los arcos de piedra de la \u00e9poca del abad Sara\u00f1\u00f3.<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-84 size-full\" src=\"https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/tabla_terremotos_web.png\" alt=\"\" width=\"954\" height=\"504\" srcset=\"https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/tabla_terremotos_web.png 954w, https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/tabla_terremotos_web-300x158.png 300w, https:\/\/blogs.ua.es\/barnizdesierto\/files\/2022\/06\/tabla_terremotos_web-768x406.png 768w\" sizes=\"auto, (max-width: 954px) 100vw, 954px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Cita: <a href=\"https:\/\/recyt.fecyt.es\/index.php\/CUGEO\/article\/view\/91108\">Tent-Mancl\u00fas, J. E. (2022): Los terremotos del sur de la provincia de Valencia seg\u00fan las fuentes del Real Monasterio de Nuestra Se\u00f1ora de la Valldigna (E de Espa\u00f1a, Provincia de Valencia). Cuaternario y Geomorfolog\u00eda, 36 (1-2): 77-103. <\/a>https:\/\/doi.org\/10.17735\/cyg.v36i1-2.91108<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El terremoto de \u201cTabernes de 1396\u201d, en el valle de la Valldigna, se ha considerado como uno de los mayores terremotos que se tiene registro en la Pen\u00ednsula Ib\u00e9rica. La informaci\u00f3n utilizada para tales afirmaciones siempre ha partido de fuentes &hellip; <a href=\"https:\/\/blogs.ua.es\/barnizdesierto\/2022\/06\/16\/terremotos-valldigna\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4347,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[2366057,2366056,2366055,1550269],"class_list":["post-82","post","type-post","status-publish","format-standard","hentry","category-publicaciones","tag-monestir-valldigna","tag-simat","tag-terremotos-valencia","tag-valldigna"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/users\/4347"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":131,"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/posts\/82\/revisions\/131"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/barnizdesierto\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}