{"id":394,"date":"2013-12-21T17:52:53","date_gmt":"2013-12-21T17:52:53","guid":{"rendered":"https:\/\/blogs.ua.es\/benidorm1\/?p=394"},"modified":"2014-01-14T01:35:51","modified_gmt":"2014-01-14T01:35:51","slug":"carteles-donaciones-y-ofrendas","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/benidorm1\/2013\/12\/21\/carteles-donaciones-y-ofrendas\/","title":{"rendered":"Carteles de donaciones y ofrendas."},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/benidorm1\/files\/2013\/12\/BENIDORM-052_1466x1099.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-395\" alt=\"BENIDORM 052_1466x1099\" src=\"https:\/\/blogs.ua.es\/benidorm1\/files\/2013\/12\/BENIDORM-052_1466x1099-300x224.jpg\" width=\"300\" height=\"224\" srcset=\"https:\/\/blogs.ua.es\/benidorm1\/files\/2013\/12\/BENIDORM-052_1466x1099-300x224.jpg 300w, https:\/\/blogs.ua.es\/benidorm1\/files\/2013\/12\/BENIDORM-052_1466x1099-1024x767.jpg 1024w, https:\/\/blogs.ua.es\/benidorm1\/files\/2013\/12\/BENIDORM-052_1466x1099.jpg 1466w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Esta imagen es bastante curiosa, pues en una sola fotograf\u00eda recogemos tres carteles que giran en torno a las donaciones. Por un lado, tras las velas que se iluminan al introducir dinero, hay una oraci\u00f3n. Por otro, junto a la ranura, otro que indica el tipo de monedas que acepta (billetes y no) y al fondo a la derecha, un \u00faltimo cartel anunciando otro buz\u00f3n para recaudar para los pobres.<\/p>\n<p>Lugar: Iglesia de San Jaime.<\/p>\n<p>Direcci\u00f3n: Plaza de San Jaime, 1<br \/>\nE-03501,\u00a0Benidorm<br \/>\nAlicante,\u00a0<strong>Espa\u00f1a<\/strong><\/p>\n<p>Fecha: 05\/12\/2013.<\/p>\n<p>Hora: 14:20.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Esta imagen es bastante curiosa, pues en una sola fotograf\u00eda recogemos tres carteles que giran en torno a las donaciones. Por un lado, tras las velas que se iluminan al introducir dinero, hay una oraci\u00f3n. Por otro, junto a la ranura, otro que indica el tipo de monedas que acepta (billetes y no) y [&hellip;]<\/p>\n","protected":false},"author":3235,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[273499],"tags":[2339,208660,69,530449,487770],"class_list":["post-394","post","type-post","status-publish","format-standard","hentry","category-inscripciones-y-placas-en-recintos-religiosos","tag-cartel","tag-donacion","tag-iglesia","tag-ofrenda","tag-oracion"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/posts\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/users\/3235"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/posts\/394\/revisions"}],"predecessor-version":[{"id":560,"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/posts\/394\/revisions\/560"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/categories?post=394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/benidorm1\/wp-json\/wp\/v2\/tags?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}