{"id":121,"date":"2008-11-10T08:00:12","date_gmt":"2008-11-10T06:00:12","guid":{"rendered":"https:\/\/blogs.ua.es\/bibciencias\/?p=121"},"modified":"2008-09-18T20:12:03","modified_gmt":"2008-09-18T18:12:03","slug":"semillas-peligrosas","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibciencias\/2008\/11\/10\/semillas-peligrosas\/","title":{"rendered":"Semillas peligrosas"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2008\/09\/20081110_semillas_peligrosas.gif\"><\/a>&#8220;Semillas peligrosas : <strong>las mentiras de la industria y los gobiernos sobre lo que comemos<\/strong>&#8221; es el t\u00edtulo del libro escrito por <a href=\"http:\/\/www.seedsofdeception.com\/Public\/SeedsOfDeception\/AuthorBio\/index.cfm\" target=\"_blank\">Jeffrey M. Smith<\/a>.<\/p>\n<p>\u00c9ste libro, un trabajo de investigaci\u00f3n escrito despu\u00e9s de que su autor abandonara la actividad industrial, muestra la pasi\u00f3n de Smith por estas causas y sus amplios conocimientos acerca de los riesgos y encubrimientos que entra\u00f1an los <strong>alimentos gen\u00e9ticamente modificados<\/strong>. Smith es el fundador y director del <a href=\"http:\/\/www.responsibletechnology.org\">Institute for Responsible Technology<\/a> (Instituto por la tecnolog\u00eda responsable).<\/p>\n<p>Michael Meacher, exministro brit\u00e1nico del Medio Ambiente dijo:<\/p>\n<blockquote><p>&#8220;Este libro combina un an\u00e1lisis agudo de la verdadera naturaleza de la ingenier\u00eda gen\u00e9tica, una cr\u00edtica devastadora acerca de los riesgos para la salud y el medio ambiente de los cultivos GM (gen\u00e9ticamente modificados) y ejemplos grav\u00edsimos sobre la manipulaci\u00f3n de la ciencia y de los medios de informaci\u00f3n por parte de la industria biotecnol\u00f3gica.&#8221;<\/p><\/blockquote>\n<p>En oposici\u00f3n profundamente razonada contra la propaganda ejercida por la industria biotecnol\u00f3gica, apoyada en muchos casos abiertamente por los gobiernos, a favor de los <strong>organismos gen\u00e9ticamente modificados<\/strong> (OGM), Jeffrey M. Smith expone al desnudo, con estilo persuasivo y claro, situaciones en las que su nefasta utilizaci\u00f3n ha causado <strong>grav\u00edsimos da\u00f1os<\/strong> a seres humanos y animales, y advierte firmemente de los riesgos a gran escala que encierra una pol\u00edtica oficial que favorezca la implantaci\u00f3n de los <strong>alimentos transg\u00e9nicos<\/strong>.<\/p>\n<p>Para leer \u00e9ste interesante libro consulta su localizaci\u00f3n en el <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/SIRSI\/0\/5?searchdata1=^C349236\" target=\"_blank\">cat\u00e1logo<\/a>. Adem\u00e1s para profundizar en la materia encontrar\u00e1s en la biblioteca otros libros de biotecnolog\u00eda: <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Biotecnologia+Aspecto+del+medio+ambiente{650}\">aspecto del medio ambiente<\/a>, <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Biotecnologia+Aspecto+politico{650}\">aspecto pol\u00edtico<\/a>, <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Biotecnologia+Aspecto+social{650}\">aspecto social<\/a>, <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Alimentos+Biotecnologia{650}\">alimentos<\/a> y <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Alimentos+transgenicos{650}\">alimentos transg\u00e9nicos<\/a>.<\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2008\/09\/20081110_semillas_peligrosas.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-122\" src=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2008\/09\/20081110_semillas_peligrosas-212x300.gif\" alt=\"semillas_peligrosas\" width=\"212\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Semillas peligrosas : las mentiras de la industria y los gobiernos sobre lo que comemos&#8221; es el t\u00edtulo del libro escrito por Jeffrey M. Smith. \u00c9ste libro, un trabajo de investigaci\u00f3n escrito despu\u00e9s de que su autor abandonara la actividad industrial, muestra la pasi\u00f3n de Smith por estas causas y sus amplios conocimientos acerca de [&hellip;]<\/p>\n","protected":false},"author":732,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[969,967],"tags":[2158,2157],"class_list":["post-121","post","type-post","status-publish","format-standard","hentry","category-areas-tematicas","category-fondos-bibliograficos","tag-alimentos-transgenicos","tag-biotecnologia"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/users\/732"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}