{"id":144,"date":"2009-01-12T08:00:43","date_gmt":"2009-01-12T06:00:43","guid":{"rendered":"https:\/\/blogs.ua.es\/bibciencias\/?p=144"},"modified":"2008-10-29T21:33:50","modified_gmt":"2008-10-29T19:33:50","slug":"lo-que-einstein-le-conto-a-su-cocinero","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibciencias\/2009\/01\/12\/lo-que-einstein-le-conto-a-su-cocinero\/","title":{"rendered":"Lo que Einstein le cont\u00f3 a su cocinero"},"content":{"rendered":"<p>&#8220;<strong>Lo que Einstein le cont\u00f3 a su cocinero 2<\/strong>&#8221; es el t\u00edtulo del libro escrito por <a href=\"http:\/\/www.robertwolke.com\/\" target=\"_blank\">Robert L. Wolke<\/a>.<\/p>\n<p>\u00bfCree que el bicarbonato de sodio absorbe los olores de la nevera; que los huevos de doble yema albergaban polluelos gemelos; que <strong>los pl\u00e1tanos contienen m\u00e1s calor\u00edas cuanto m\u00e1s maduros y dulces est\u00e1n<\/strong>; o que las vieiras gigantes se pescan a mano?&#8230; \u00bfSe ha preguntado alguna vez por qu\u00e9 se cree que el queso para untar proviene de Filadelfia; si el helado que compra tiene m\u00e1s de un 50% de aire; <strong>c\u00f3mo se puede enfriar una bebida con hielo sin que se le diluya<\/strong>; por qu\u00e9 nos hacen llorar las cebollas; o por qu\u00e9 son mejores los hornos de ladrillo para hacer el pan y las pizzas?&#8230;<\/p>\n<p>Con el mismo lenguaje claro, did\u00e1ctico y desenfadado que convirti\u00f3 su primer <em><a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=8496222004{020}\" target=\"_blank\">Lo que Einstein cont\u00f3 a su cocinero<\/a><\/em>, Robert L. Wolke a\u00fana en este segundo volumen la autoridad del cient\u00edfico con la claridad y el ingenio de un profesor ejemplar. Una vez m\u00e1s, consigue h\u00e1bilmente <strong>salvar las distancias entre el qu\u00edmico y el cocinero<\/strong>, as\u00ed como acercar de manera magistral ambas disciplinas a toda aquella persona que simplemente siente curiosidad por el mundo que le rodea.<\/p>\n<p>Si nos lo podemos pasar bien con la alimentaci\u00f3n y la cocina, tambi\u00e9n podemos y deber\u00edamos hacerlo con la ciencia. Gracias a su fino humor y a su aguda iron\u00eda, Robert L. Wolke logra hacernos disfrutar tanto de una cosa como de otra desde la primera hasta la \u00faltima p\u00e1gina.<\/p>\n<p>Consulta el <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=9788496222489{020}\" target=\"_blank\">cat\u00e1logo<\/a> para leer \u00e9ste curioso libro de Robert L. Wolke, as\u00ed como <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Wolke,+Robert+L.{100}\" target=\"_blank\">otros libros<\/a> disponibles en la biblioteca. Si te interesa profundizar en la materia sobre la que trata \u00e9ste libro, tambi\u00e9n puedes ver otros libros sobre <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Ciencias+Obras+de+divulgacion{650}\" target=\"_blank\">divulgaci\u00f3n cient\u00edfica<\/a>, y <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Cocina{650}\" target=\"_blank\">cocina<\/a>.<\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2008\/10\/20090112_einstein_cocinero.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-145\" src=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2008\/10\/20090112_einstein_cocinero.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Lo que Einstein le cont\u00f3 a su cocinero 2&#8221; es el t\u00edtulo del libro escrito por Robert L. Wolke. \u00bfCree que el bicarbonato de sodio absorbe los olores de la nevera; que los huevos de doble yema albergaban polluelos gemelos; que los pl\u00e1tanos contienen m\u00e1s calor\u00edas cuanto m\u00e1s maduros y dulces est\u00e1n; o que las [&hellip;]<\/p>\n","protected":false},"author":732,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[969,967],"tags":[78,1964],"class_list":["post-144","post","type-post","status-publish","format-standard","hentry","category-areas-tematicas","category-fondos-bibliograficos","tag-cocina","tag-obras-de-divulgacion-de-la-ciencia"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/users\/732"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/144\/revisions"}],"predecessor-version":[{"id":148,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/144\/revisions\/148"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/media?parent=144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/categories?post=144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/tags?post=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}