{"id":506,"date":"2009-07-06T09:00:13","date_gmt":"2009-07-06T07:00:13","guid":{"rendered":"https:\/\/blogs.ua.es\/bibciencias\/?p=506"},"modified":"2009-05-28T19:03:45","modified_gmt":"2009-05-28T17:03:45","slug":"hipatia-de-alejandria","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibciencias\/2009\/07\/06\/hipatia-de-alejandria\/","title":{"rendered":"Hipatia de Alejandr\u00eda"},"content":{"rendered":"<p>&#8220;<strong>Hipatia de Alejandr\u00eda<\/strong>&#8221; es la obra escrita por Maria Dzielska.<\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/Hipatia_de_Alejandr%C3%ADa\">Hipatia<\/a> (<strong>matem\u00e1tica<\/strong> brillante, neoplat\u00f3nica elocuente y famosa por su belleza) fue brutalmente asesinada en el a\u00f1o 415 por una turba de cristianos de Alejandr\u00eda. Desde entonces ha sido una leyenda. <\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/cbskP9utQ0M\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>En su libro, Maria Dzielska va m\u00e1s all\u00e1 de la leyenda para ofrecernos la historia verdadera de la vida y la muerte de Hipatia, adem\u00e1s de <strong>nuevas ideas sobre su mundo<\/strong>. Historiadores, poetas, novelistas victorianos y feministas actuales han visto en Hipatia un s\u00edmbolo del ocaso de la cultura cl\u00e1sica y de la libertad sexual. Dzielska nos retrotrae a la Alejandr\u00eda de los d\u00edas de Hipatia, construye un cuadro convincente y lleno de color de los disc\u00edpulos y ense\u00f1anzas de la joven fil\u00f3sofa y aclara lo que el asesinato de Hipatia revela sobre las tensiones de esa \u00e9poca tumultuosa.<\/p>\n<p>Maria Dzielska es catedr\u00e1tica de historia romana antigua en la Universidad Jagel\u00f3nica de Cracovia.<\/p>\n<p>Por otro lado, la pel\u00edcula <a href=\"http:\/\/www.agoralapelicula.com\/\">\u00c1gora<\/a>, escrita y dirigida por Alejandro Amen\u00e1bar, trata sobre un esclavo de Hipatia que se enamora de \u00e9sta. Hipatia es interpretada por Rachel Weisz.<\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/-WSU-hh2j2g\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>Consulta el <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=8478447490{020}\">cat\u00e1logo<\/a> para leer \u00e9ste libro. Puedes <a href=\"http:\/\/books.google.es\/books?id=2MjpNlFRCU0C\">ojear<\/a> \u00e9ste libro. Tambi\u00e9n puedes estudiar otros libros sobre <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Mujeres+matem%E1ticas+Biograf%EDas{650}\">biograf\u00edas de mujeres matem\u00e1ticas<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2009\/05\/20090706_hipatiadealejandria.gif\" alt=\"20090706_hipatiadealejandria\" width=\"132\" height=\"187\" class=\"alignnone size-full wp-image-507\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Hipatia de Alejandr\u00eda&#8221; es la obra escrita por Maria Dzielska. Hipatia (matem\u00e1tica brillante, neoplat\u00f3nica elocuente y famosa por su belleza) fue brutalmente asesinada en el a\u00f1o 415 por una turba de cristianos de Alejandr\u00eda. Desde entonces ha sido una leyenda. [kml_flashembed movie=&#8221;http:\/\/www.youtube.com\/v\/cbskP9utQ0M&#8221; width=&#8221;425&#8243; height=&#8221;350&#8243; wmode=&#8221;transparent&#8221; \/] En su libro, Maria Dzielska va m\u00e1s all\u00e1 de [&hellip;]<\/p>\n","protected":false},"author":732,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[969,967],"tags":[2604,5468],"class_list":["post-506","post","type-post","status-publish","format-standard","hentry","category-areas-tematicas","category-fondos-bibliograficos","tag-biografias","tag-biografias-de-mujeres-matematicas"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/users\/732"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":5,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"predecessor-version":[{"id":511,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/506\/revisions\/511"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}