{"id":568,"date":"2009-10-19T09:00:04","date_gmt":"2009-10-19T07:00:04","guid":{"rendered":"https:\/\/blogs.ua.es\/bibciencias\/?p=568"},"modified":"2009-06-01T20:49:50","modified_gmt":"2009-06-01T18:49:50","slug":"las-damas-del-laboratorio","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibciencias\/2009\/10\/19\/las-damas-del-laboratorio\/","title":{"rendered":"Las damas del laboratorio"},"content":{"rendered":"<p>&#8220;<strong>Las damas del laboratorio : mujeres cient\u00edficas en la historia<\/strong>&#8221; es la obra escrita por <a href=\"http:\/\/www.comunidadsmart.es\/cientificos_detalle.php?id=83\">Mar\u00eda Jos\u00e9 Casado Ruiz de L\u00f3izaga<\/a>.<\/p>\n<p>El anonimato ha perseguido, hist\u00f3ricamente, a las mujeres dedicadas a la ciencia. Han sido sometidas al desprecio por sus colegas, y han sufrido la indiferencia de las instituciones acad\u00e9micas y, en muchos casos, la apropiaci\u00f3n de sus descubrimientos por parte de compa\u00f1eros ante el silencio c\u00f3mplice de la comunidad cient\u00edfica masculina. <strong>Esta obra pretende sacar a la luz sus trabajos y vidas, y destacar tanto las dificultades que tuvieron que superar como su impresionante contribuci\u00f3n al desarrollo de sus respectivas disciplinas<\/strong>.<\/p>\n<p>En este libro, narrado con amenidad y profusi\u00f3n de detalles que har\u00e1n sonrojar a m\u00e1s de un hombre, Mar\u00eda Jos\u00e9 Casado ha buceado en archivos y bibliotecas para desvelar la <strong>trayectoria de cient\u00edficas que superaron el rechazo social<\/strong>, aut\u00e9nticas pioneras en sus respectivos campos del saber, que impulsaron &#8211; con su talento, inteligencia y esfuerzo personal- el camino de la ciencia. <\/p>\n<p>De <a href=\"https:\/\/blogs.ua.es\/bibciencias\/2009\/07\/06\/hipatia-de-alejandria\/\">Hipatia de Alejandr\u00eda<\/a> a la paleont\u00f3loga Mary Leakey, pasando por Marie Curie, \u00c9milie de Ch\u00e2telet, Rosalind Franklin, Lise Meitner, Ada Lovelace o la espa\u00f1ola Mar\u00eda Andrea Casamayor, este ejercicio de memoria y reivindicaci\u00f3n del papel de la mujer en el saber universal permitir\u00e1 valorar, en su justa medida, su destacada <strong>contribuci\u00f3n al progreso cient\u00edfico<\/strong>.<\/p>\n<blockquote><p>Todas ellas nos sirven de ejemplo a las mujeres cient\u00edficas que en la actualidad luchamos para alcanzar en el mundo cient\u00edfico el puesto que nos corresponda de acuerdo con nuestra capacidad.<br \/>\nMARGARITA SALAS<\/p><\/blockquote>\n<p>Consulta el <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=9788483066881{020}\">cat\u00e1logo<\/a> para su localizaci\u00f3n. Puedes <a href=\"http:\/\/www.casadellibro.com\/capitulos\/8483066882.pdf\">ojear<\/a> el primer cap\u00edtulo. Tambi\u00e9n puedes echar un vistazo a otras obras sobre <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Mujeres+Historia{650}\">historia sobre las mujeres<\/a> y <a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=Mujeres+cientificas+Biografia{650}\">biograf\u00eda de mujeres cient\u00edficas<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.ua.es\/bibciencias\/files\/2009\/06\/20091019_lasdamasdellaboratorio.jpg\" alt=\"20091019_lasdamasdellaboratorio\" width=\"140\" height=\"218\" class=\"alignnone size-full wp-image-569\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Las damas del laboratorio : mujeres cient\u00edficas en la historia&#8221; es la obra escrita por Mar\u00eda Jos\u00e9 Casado Ruiz de L\u00f3izaga. El anonimato ha perseguido, hist\u00f3ricamente, a las mujeres dedicadas a la ciencia. Han sido sometidas al desprecio por sus colegas, y han sufrido la indiferencia de las instituciones acad\u00e9micas y, en muchos casos, la [&hellip;]<\/p>\n","protected":false},"author":732,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[969,967],"tags":[5496,5495],"class_list":["post-568","post","type-post","status-publish","format-standard","hentry","category-areas-tematicas","category-fondos-bibliograficos","tag-biografia-de-mujeres-cientificas","tag-historia-sobre-las-mujeres"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/users\/732"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/comments?post=568"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/568\/revisions"}],"predecessor-version":[{"id":572,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/posts\/568\/revisions\/572"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/media?parent=568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/categories?post=568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibciencias\/wp-json\/wp\/v2\/tags?post=568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}