{"id":20077,"date":"2017-12-05T09:06:19","date_gmt":"2017-12-05T08:06:19","guid":{"rendered":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/?p=20077"},"modified":"2021-02-05T13:02:09","modified_gmt":"2021-02-05T12:02:09","slug":"semana-internacional-gottingen","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/2017\/12\/05\/semana-internacional-gottingen\/","title":{"rendered":"Semana Internacional G\u00f6ttingen"},"content":{"rendered":"<p style=\"text-align: justify\">Hoy compartimos con vosotr@s la estancia de nuestra compa\u00f1era de la Biblioteca de Ciencias, M\u00aa \u00c1ngeles Gomis Sempere, en la Georg-August-Universit\u00e4t de G\u00f6ttingen (Alemania) durante el pasado mes de mayo. \u00a1Disfrutadla y buen puente!<\/p>\n<p style=\"text-align: justify\">&#8220;El pasado mes de mayo acud\u00ed a una semana internacional del programa Erasmus+ en la Georg-August-Universit\u00e4t, en G\u00f6ttingen (Alemania). Formaba parte del grupo de bibliotecas europeas. \u00c9ramos 6 personas que ven\u00edamos de Polonia (Universidad de Bydgoszcz), Hungr\u00eda (Universidad de Debrecen), Croacia (Universidad de Zagreb) y Espa\u00f1a (Universidad de Barcelona y Alicante). Las exposiciones se centraron la mayor\u00eda entorno a publicaciones online y en papel, repositorios y organizaci\u00f3n de las bibliotecas. Y por supuesto, nos explicaron el funcionamiento de la biblioteca de la universidad en diferentes visitas guiadas.<\/p>\n<p style=\"text-align: justify\">G\u00f6ttingen est\u00e1 situada en el centro de Alemania. Es la t\u00edpica ciudad universitaria. El campus se encuentra disperso por toda la ciudad y sus alrededores. \u00a0Paseando se percibe la relevancia cient\u00edfica y cultural que tuvo esta ciudad. Hay \u00a0placas informativas y conmemorativas sobre los profesores y cient\u00edficos que residieron y trabajaron en ella: Benjamin Franklin, los hermanos Grimm, Carl Gauss, Lichtenberg \u2026<\/p>\n<figure id=\"attachment_20080\" aria-describedby=\"caption-attachment-20080\" style=\"width: 350px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20080 size-full\" title=\"Lichtenberg\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Lichtenberg.jpg\" alt=\"\" width=\"350\" height=\"467\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Lichtenberg.jpg 350w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Lichtenberg-217x290.jpg 217w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Lichtenberg-225x300.jpg 225w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><figcaption id=\"caption-attachment-20080\" class=\"wp-caption-text\">Lichtenberg<\/figcaption><\/figure>\n<p><!--more--><\/p>\n<p style=\"text-align: justify\">La universidad fundada en 1734 es una de las m\u00e1s antiguas de Europa. Su biblioteca, la \u201cBiblioteca del Estado y de la Universidad de G\u00f6ttingen Baja Sajonia\u201d, \u00a0fundada el mismo a\u00f1o, fue la primera biblioteca acad\u00e9mica moderna, con un concepto integral de la investigaci\u00f3n y es una de las m\u00e1s importantes de Alemania. Al igual que la UA tiene una biblioteca central y otras repartidas por facultades y departamentos. A destacar dos edificios, la Biblioteca Hist\u00f3rica y la Biblioteca Central Universitaria. Respecto a la primera se\u00f1alar que cuando se fund\u00f3, se ordenaron los libros con un sistema nuevo de catalogaci\u00f3n. En ella se encuentra un ejemplar original de la Biblia de Gutenberg.<\/p>\n<p style=\"text-align: justify\">En las visitas guiadas a las bibliotecas comprobamos que hab\u00eda muy poco personal en las salas atendiendo al p\u00fablico y en las oficinas. Tienen un sistema de teletrabajo para quien lo desee. Y el alumnado parece bastante aut\u00f3nomo y sabe desenvolverse s\u00f3lo.<\/p>\n<figure id=\"attachment_20079\" aria-describedby=\"caption-attachment-20079\" style=\"width: 650px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20079 size-full\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Learning-Resources-Center.jpg\" alt=\"\" width=\"650\" height=\"488\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Learning-Resources-Center.jpg 650w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Learning-Resources-Center-290x218.jpg 290w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/Learning-Resources-Center-300x225.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-20079\" class=\"wp-caption-text\">Learning Resources Center<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Respecto a las instalaciones destaca el aprovechamiento de todos los espacios disponibles. Desde la nueva y moderna biblioteca central hasta los s\u00f3tanos de las bibliotecas peque\u00f1as ubicadas en edificios m\u00e1s antiguos (como la de Educaci\u00f3n). Todo controlado con un sistema automatizado a trav\u00e9s de tarjeta electr\u00f3nica (parecida a \u00a0nuestra TIU): autopr\u00e9stamo de libros, reserva de salas de trabajo, petici\u00f3n de libros, etc. Lo que m\u00e1s nos llam\u00f3 la atenci\u00f3n fue la cantidad de recursos que se ofrecen al alumnado.\u00a0 Empezando por el equipamiento nuevo y funcional de la biblioteca central, con salas de estudio individuales, y acabando con el edificio (LSG) cercano dedicado exclusivamente a estudio y salas de trabajo, abierto\u00a0 desde las 7 de la ma\u00f1ana hasta la 1 de la noche todos los d\u00edas de la semana. Para acceder a todo ello se dispone de puntos que se renuevan cada 40 d\u00edas. Salas individuales, de equipo, con ordenadores, para estudiantes con ni\u00f1os\u2026\u00a0 Todo muy organizado. Y muy cuidado.&#8221;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20078\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/foto-de-grupo-Semana-Internacional.jpg\" alt=\"\" width=\"650\" height=\"488\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/foto-de-grupo-Semana-Internacional.jpg 650w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/foto-de-grupo-Semana-Internacional-290x218.jpg 290w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2017\/12\/foto-de-grupo-Semana-Internacional-300x225.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Si quer\u00e9is saber m\u00e1s de G\u00f6ttingen y su universidad:<\/p>\n<p><a href=\"https:\/\/es.wikipedia.org\/wiki\/Gotinga\">https:\/\/es.wikipedia.org\/wiki\/Gotinga<\/a><\/p>\n<p><a href=\"http:\/\/www.uni-goettingen.de\/\">http:\/\/www.uni-goettingen.de\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy compartimos con vosotr@s la estancia de nuestra compa\u00f1era de la Biblioteca de Ciencias, M\u00aa \u00c1ngeles Gomis Sempere, en la Georg-August-Universit\u00e4t de G\u00f6ttingen (Alemania) durante el pasado mes de mayo. \u00a1Disfrutadla y buen puente! &#8220;El pasado mes de mayo acud\u00ed a una semana internacional del programa Erasmus+ en la Georg-August-Universit\u00e4t, en G\u00f6ttingen (Alemania). Formaba parte [&hellip;]<\/p>\n","protected":false},"author":3819,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5675],"tags":[6432],"class_list":["post-20077","post","type-post","status-publish","format-standard","hentry","category-la-biblioteca-por-dentro","tag-jornadas-y-congresos"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/20077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/users\/3819"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/comments?post=20077"}],"version-history":[{"count":11,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/20077\/revisions"}],"predecessor-version":[{"id":20094,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/20077\/revisions\/20094"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/media?parent=20077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/categories?post=20077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/tags?post=20077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}