{"id":24589,"date":"2020-10-15T13:44:53","date_gmt":"2020-10-15T11:44:53","guid":{"rendered":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/?p=24589"},"modified":"2021-02-01T10:29:48","modified_gmt":"2021-02-01T09:29:48","slug":"cine-de-otono","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/2020\/10\/15\/cine-de-otono\/","title":{"rendered":"Cine de oto\u00f1o"},"content":{"rendered":"<p><strong>MEDIATECA,<\/strong> <strong><em>Apuntes de cine<\/em><\/strong><\/p>\n<p><strong><em>Cine de oto\u00f1o<\/em><\/strong><\/p>\n<p><em>Sesi\u00f3n doble de cine\u00a0\u00a0\u00a0\u00a0\u00a0<\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24592 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-1.jpg\" alt=\"\" width=\"650\" height=\"434\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-1.jpg 660w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-1-212x141.jpg 212w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/em><\/p>\n<p style=\"text-align: justify\"><strong><em>Os damos la bienvenida a tod@s en Mediateca, apuntes de cine<\/em><\/strong>, con el primer post del curso acad\u00e9mico 2020\/2021. Antes de todo, deseo que est\u00e9is tod@s bien y en especial en el aspecto de salud, dada la situaci\u00f3n actual, y adem\u00e1s desearos que teng\u00e1is un buen \u00e1nimo de cara a este nuevo curso que acaba de comenzar. Por nuestra parte, vamos a intentar estar todas las semanas con todos vosotr@s en esta ventana virtual. Adem\u00e1s, tenemos programadas para este curso novedades, entre otras, varias exposiciones, que os iremos informando en el Blog de la BUA.\u00a0 Con el t\u00edtulo de <strong><em>\u201cCine de oto\u00f1o\u201d <\/em><\/strong>iniciamos la andadura, y lo hacemos con un <strong><em>programa doble<\/em><\/strong>. De la mano de <strong><em>Woody Allen con \u201dD\u00eda de lluvia en Nueva York\u201d<\/em><\/strong>, y un film nominado al Oscar al mejor documental \u201c<strong><em>N\u00f3madas del viento\u201d. <\/em><\/strong>La primera es una comedia rom\u00e1ntica ambientada en la ciudad fetiche de Allen, Nueva York, es su pen\u00faltima pel\u00edcula, la \u00faltima est\u00e1 proyect\u00e1ndose actualmente en cines; la segunda es un magn\u00edfico reclamo para \u201cel urbanita de a pie\u201d, para que dirija su mirada al cielo y descubra el \u00e9pico viaje de las aves migratorias, que est\u00e1n surcando nuestros cielos en un viaje a territorios m\u00e1s c\u00e1lidos, al mismo tiempo, nuestros parques y bosques empiezan a te\u00f1irse de tonos oto\u00f1ales: amarillos, naranjas y rojos, y que para los \u00e1rboles caducifolios son los proleg\u00f3menos para recibir al fr\u00edo invierno.<\/p>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24612 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/pel\u00edculas-ok.jpg\" alt=\"\" width=\"517\" height=\"366\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/pel\u00edculas-ok.jpg 600w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/pel\u00edculas-ok-199x141.jpg 199w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>D\u00eda de lluvia en Nueva York\u00a0 <\/em><\/strong><\/p>\n<p><em>Vuelven Woody Allen y la lluvia<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24595 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-4.jpg\" alt=\"\" width=\"366\" height=\"541\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-4.jpg 649w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-4-95x141.jpg 95w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" \/><\/p>\n<p style=\"text-align: center\"><em>\u00bfPor qu\u00e9 siempre suele llover en las pel\u00edculas de Woody Allen?<\/em><\/p>\n<p style=\"text-align: justify\">Habr\u00eda que pregunt\u00e1rselo a \u00e9l, pero, de todas formas, as\u00ed es, recordad entre otras a Midnight in Paris; en <strong><em>A Rainy Day in New York, la lluvia<\/em> <\/strong>va insertada hasta en el t\u00edtulo original, as\u00ed que esta es una buena excusa para incluirla en este post de \u201cCine de oto\u00f1o\u201d, adem\u00e1s no hay nada m\u00e1s que ver el Central Park con la vegetaci\u00f3n en tonos c\u00e1lidos caldera, y la lluvia cayendo sobre los protagonistas y las calles de Nueva York.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24596 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-5.jpg\" alt=\"\" width=\"566\" height=\"315\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-5.jpg 1000w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-5-250x139.jpg 250w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-5-768x428.jpg 768w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<p style=\"text-align: justify\"><strong><em>D\u00eda de lluvia en Nueva York (2019) <\/em><\/strong>es la pen\u00faltima <strong><em>Woody Allen<\/em><\/strong>, que con 85 a\u00f1os sigue estando en un estado de forma incre\u00edble, y contin\u00faa haciendo una peli por a\u00f1o. Allen casi siempre ambienta sus historias en una ciudad determinada, esta vez vuelve a Nueva York, su ciudad preferida, y all\u00ed nos presenta una ingeniosa historia de amores cruzados. <strong><em>D\u00eda de lluvia en Nueva York <\/em><\/strong>es una comedia rom\u00e1ntica contada en un tono divertido, casi adolescente. El film a\u00fan no se ha estrenado en Estados Unidos, entre otras causas, debido al desencuentro entre Allen y Amazon Estudios, y s\u00ed lo ha hecho en Europa y Espa\u00f1a.<\/p>\n<p><strong><em>Fotogramas, unas pinceladas<\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24597 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-6.jpg\" alt=\"\" width=\"566\" height=\"377\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-6.jpg 1366w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-6-211x141.jpg 211w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-6-768x512.jpg 768w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<p style=\"text-align: justify\"><strong><em>Gatsby Welles (Timoth\u00e9e Chalamet) y Ashleigh (Elle Fanning)<\/em><\/strong> son una pareja de j\u00f3venes universitarios enamorados que se van a pasar un fin de semana a la ciudad de Nueva York.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24599 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-7.jpg\" alt=\"\" width=\"566\" height=\"269\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-7.jpg 800w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-7-250x119.jpg 250w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-7-768x365.jpg 768w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<p style=\"text-align: justify\">Ashleigh va a entrevistar a un reconocido <strong><em>cineasta, Roland Pollard (Liev Schreiber)<\/em><\/strong> para hacer un reportaje para una revista universitaria; el director est\u00e1 pasando por unos malos momentos de crisis creativa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24600 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-8.jpg\" alt=\"\" width=\"566\" height=\"377\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-8.jpg 900w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-8-212x141.jpg 212w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-8-768x512.jpg 768w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<p style=\"text-align: justify\">Gatsby a su vez tambi\u00e9n conocer\u00e1 a <strong><em>una joven,<\/em><\/strong> <strong><em>Chan (Selena G\u00f3mez), <\/em><\/strong>mientras que Ashleigh lo har\u00e1, adem\u00e1s de con el cineasta Roland Pollard, con el atractivo actor Francisco Vega<strong><em>.<\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24601 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-9.jpg\" alt=\"\" width=\"436\" height=\"636\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-9.jpg 494w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-9-97x141.jpg 97w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/><\/p>\n<p style=\"text-align: justify\">Os hemos dado unas pinceladas, ten\u00e9is noventa minutos para disfrutar de un magn\u00edfico recorrido por bellos rincones de Nueva York, con unos personajes forzados casi al l\u00edmite, y que se mueven entre el amor y el desamor, con encuentros y desencuentros, originando unas relaciones cruzadas llenas de unos ingeniosos di\u00e1logos.<\/p>\n<p style=\"text-align: center\">\u00a1 Buen provecho !<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Di\u0301a de lluvia en Nueva York - Trailer espan\u0303ol (HD)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/6wuTmcCQjL8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>N\u00f3madas del viento<\/em><\/strong><\/p>\n<p><em>El gran viaje de las aves<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24602 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-10.jpg\" alt=\"\" width=\"365\" height=\"497\" \/><\/p>\n<p style=\"text-align: justify\">Despu\u00e9s de \u201cD\u00eda de lluvia en Nueva York\u201d, quiero poner el contrapunto con <strong><em>N\u00f3madas del viento<\/em><\/strong>. La primera est\u00e1 ambientada en una gran ciudad, con personajes y situaciones muy urbanitas; mientras que la segunda nos acerca al ecosistema animal, al mundo de las aves migratorias.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24603 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-11.jpg\" alt=\"\" width=\"566\" height=\"365\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-11.jpg 642w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-11-219x141.jpg 219w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<p style=\"text-align: justify\"><em>\u201cLa historia de las aves migratorias es la historia de una promesa, la promesa del retorno. Hacen traves\u00edas a menudo de miles de kil\u00f3metros sembrados de peligros, alcanzando las cumbres m\u00e1s altas, los oc\u00e9anos y los inh\u00f3spitos desiertos. Si se enfrentan a la intemperie es para responder a una misma necesidad, SOBREVIVIR\u2026\u201d<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24604 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-12.jpg\" alt=\"\" width=\"566\" height=\"379\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-12.jpg 1200w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-12-210x141.jpg 210w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-12-768x515.jpg 768w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<p style=\"text-align: justify\"><strong><em>N\u00f3madas del viento <\/em><\/strong>es un magn\u00edfico documental realizado por los <strong><em>directores franceses Jacques Perrin y Jacques Clyzaud<\/em><\/strong>, que se han especializado en cintas sobre el medio ambiente, esta fue su primera pel\u00edcula, despu\u00e9s le siguieron \u00a0<strong><em>Oc\u00e9anos, \u00a0Las estaciones, y \u00a0Los habitantes del bosque<\/em><\/strong>. Sus documentales son muy personales, acercando sus c\u00e1maras a la naturaleza desde una perspectiva nueva y empleando unos medios t\u00e9cnicos novedosos para adentrarse en el ecosistema animal. Muy recomendable ver tambi\u00e9n el \u201cmaking off\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24605 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-13.jpg\" alt=\"\" width=\"366\" height=\"539\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-13.jpg 1000w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-13-96x141.jpg 96w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-13-768x1132.jpg 768w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" \/><\/p>\n<p style=\"text-align: justify\"><strong><em>N\u00f3madas del viento<\/em><\/strong> viene en el momento adecuado, ahora que est\u00e1n volando sobre nuestras ciudades y campos bandadas de aves, realizando la migraci\u00f3n anual de oto\u00f1o, para acercarse a espacios y h\u00e1bitats m\u00e1s propicios. Deber\u00e1n recorrer miles de kil\u00f3metros en los que tendr\u00e1n que vencer multitud de adversidades, en una traves\u00eda de supervivencia de car\u00e1cter casi \u00e9pico.<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/youtu.be\/XFtqKRRn4XQ<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>La puedes encontrar en el<\/em><\/strong> <strong><em>cat\u00e1logo de la Biblioteca de la Universidad de Alicante (BUA):<\/em><\/strong><\/p>\n<p><a href=\"https:\/\/cat.biblioteca.ua.es\/discovery\/search?query=any,contains,N%C3%B3madas%20del%20viento&amp;tab=Coleccion_impresa_audiovisual&amp;search_scope=Coleccion_impresa_audiovisual&amp;vid=34CVA_UA:VU1&amp;lang=es&amp;offset=0\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24606 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-14.jpg\" alt=\"\" width=\"217\" height=\"295\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/cat.biblioteca.ua.es\/permalink\/34CVA_UA\/mcr823\/alma991004363649706257\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24607 aligncenter\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-15.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-15.jpg 300w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2020\/10\/foto-15-250x141.jpg 250w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MEDIATECA, Apuntes de cine Cine de oto\u00f1o Sesi\u00f3n doble de cine\u00a0\u00a0\u00a0\u00a0\u00a0 Os damos la bienvenida a tod@s en Mediateca, apuntes de cine, con el primer post del curso acad\u00e9mico 2020\/2021. Antes de todo, deseo que est\u00e9is tod@s bien y en especial en el aspecto de salud, dada la situaci\u00f3n actual, y adem\u00e1s desearos que teng\u00e1is [&hellip;]<\/p>\n","protected":false},"author":3819,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212],"tags":[161533,5776],"class_list":["post-24589","post","type-post","status-publish","format-standard","hentry","category-cine","tag-apuntes-de-cine","tag-mediateca"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/24589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/users\/3819"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/comments?post=24589"}],"version-history":[{"count":16,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/24589\/revisions"}],"predecessor-version":[{"id":25174,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/24589\/revisions\/25174"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/media?parent=24589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/categories?post=24589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/tags?post=24589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}