{"id":2856,"date":"2011-07-05T11:26:07","date_gmt":"2011-07-05T09:26:07","guid":{"rendered":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/?p=2856"},"modified":"2021-05-06T14:06:13","modified_gmt":"2021-05-06T12:06:13","slug":"las-ventas-de-libros-caen-un-7","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/2011\/07\/05\/las-ventas-de-libros-caen-un-7\/","title":{"rendered":"Las ventas de libros caen un 7%"},"content":{"rendered":"<p>El sector editorial espa\u00f1ol cae por segundo a\u00f1o consecutivo. Si en 2009 la facturaci\u00f3n cay\u00f3 solo un 2,4%, en 2010 la ca\u00edda fue de un 7%, lo que devuelve la industria del libro a las cifras de 2004.<\/p>\n<p>Estos datos forman parte del <a href=\"http:\/\/www.federacioneditores.org\/0_Resources\/Documentos\/Comercio_Interior2010.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>estudio del Comercio Interior del Libro <\/strong><\/a>correspondiente a 2010, presentado ayer por Antoni Comas y Antonio Mar\u00eda \u00c1vila, presidente y director ejecutivo, respectivamente, de la<a href=\"http:\/\/www.federacioneditores.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Federaci\u00f3n de Gremios de Editores de Espa\u00f1a (FGEE)<\/a>, que realiza este <strong>informe <\/strong>con el patrocinio del Ministerio de Cultura y del Centro Espa\u00f1ol de Derechos Reprogr\u00e1ficos (CEDRO).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/www.federacioneditores.org\/0_Resources\/Documentos\/Comercio_Interior2010.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2857\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2011\/07\/Dibujochulo-300x161.jpg\" alt=\"\" width=\"300\" height=\"161\" \/><\/a><\/p>\n<p>La palabra clave de ese informe es descenso, y toma cuerpo sobre todo en dos aspectos clave: las ventas de libros de texto y las compras de las bibliotecas p\u00fablicas. Las primeras caen un 7% y las\u00a0 segundas, un 43,7%.<\/p>\n<p>Las esperanzas est\u00e1n puestas en la campa\u00f1a del libro escolar de septiembre y en la de navidad, y los resultados finales de 2011 tambi\u00e9n &#8220;depender\u00e1n de los recursos que liberen la Administraci\u00f3n central y las auton\u00f3micas&#8221; para la compra destinada a las bibliotecas.<\/p>\n<p>Positivas s\u00ed son las ventas del libro electr\u00f3nico, que casi se han duplicado y crecen un 37,5% respecto al 2009 con una facturaci\u00f3n de 70,5 millones de euros. Eso s\u00ed, el 68,9% de esa subida hay que adjudicarla a materias como el derecho y la econom\u00eda. Sin ellas, las cifras hubieran permanecido congeladas.<\/p>\n<p>Y positivo resulta tambi\u00e9n el\u00a0 mercado exterior: las exportaciones del sector crecieron un 3,5% el a\u00f1o pasado, y M\u00e9xico sigue siendo el principal mercado extranjero para los libros espa\u00f1oles.<\/p>\n<p style=\"text-align: center\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector editorial espa\u00f1ol cae por segundo a\u00f1o consecutivo. Si en 2009 la facturaci\u00f3n cay\u00f3 solo un 2,4%, en 2010 la ca\u00edda fue de un 7%, lo que devuelve la industria del libro a las cifras de 2004. Estos datos forman parte del estudio del Comercio Interior del Libro correspondiente a 2010, presentado ayer por [&hellip;]<\/p>\n","protected":false},"author":1261,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[324],"tags":[7184],"class_list":["post-2856","post","type-post","status-publish","format-standard","hentry","category-libros","tag-recursos-de-informacion"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/2856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/users\/1261"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/comments?post=2856"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/2856\/revisions"}],"predecessor-version":[{"id":25366,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/2856\/revisions\/25366"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/media?parent=2856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/categories?post=2856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/tags?post=2856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}