{"id":9502,"date":"2013-10-16T10:29:00","date_gmt":"2013-10-16T08:29:00","guid":{"rendered":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/?p=9502"},"modified":"2021-02-03T12:30:16","modified_gmt":"2021-02-03T11:30:16","slug":"aprende-a-usar-tu-biblioteca","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/2013\/10\/16\/aprende-a-usar-tu-biblioteca\/","title":{"rendered":"Aprende a usar tu biblioteca"},"content":{"rendered":"<p style=\"text-align: justify\">Conoce los Tutoriales para que te familiarices y aprendas a usar los servicios y recursos del cat\u00e1logo bibliogr\u00e1fico de la Biblioteca de la Universidad de Alicante.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Conoce qu\u00e9 puedes encontrar y qu\u00e9 servicios te ofrece, aprende a realizar b\u00fasquedas sencillas y complejas combinando varios campos, a hacer reservas y a guardar un documento, a modificar un pin,\u00a0 renovar un pr\u00e9stamo o,\u00a0 por qu\u00e9 no, a utilizar truncamientos y operadores para mejorar tus resultados al realizar una b\u00fasqueda.<strong><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure style=\"width: 450px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.pinterest.com\/librodistraido\/aprende-a-usar-tu-biblioteca\/\"><img loading=\"lazy\" decoding=\"async\" class=\" \" alt=\"\" src=\"http:\/\/media-cache-ak0.pinimg.com\/736x\/74\/44\/75\/7444756ca7762b11add1a4b451dbee48.jpg\" width=\"450\" height=\"296\" \/><\/a><figcaption class=\"wp-caption-text\">Haz clic sobre la imagen para conocer los siete tutoriales que hemos preparado<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Conoce los Tutoriales para que te familiarices y aprendas a usar los servicios y recursos del cat\u00e1logo bibliogr\u00e1fico de la Biblioteca de la Universidad de Alicante. &nbsp; Conoce qu\u00e9 puedes encontrar y qu\u00e9 servicios te ofrece, aprende a realizar b\u00fasquedas sencillas y complejas combinando varios campos, a hacer reservas y a guardar un documento, a [&hellip;]<\/p>\n","protected":false},"author":2606,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5675],"tags":[15],"class_list":["post-9502","post","type-post","status-publish","format-standard","hentry","category-la-biblioteca-por-dentro","tag-formacion"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/9502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/users\/2606"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/comments?post=9502"}],"version-history":[{"count":11,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/9502\/revisions"}],"predecessor-version":[{"id":9513,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/9502\/revisions\/9513"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/media?parent=9502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/categories?post=9502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/tags?post=9502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}