{"id":9601,"date":"2013-10-23T12:42:18","date_gmt":"2013-10-23T10:42:18","guid":{"rendered":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/?p=9601"},"modified":"2021-02-03T12:18:17","modified_gmt":"2021-02-03T11:18:17","slug":"mediateca-apuntes-de-cine-33","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/2013\/10\/23\/mediateca-apuntes-de-cine-33\/","title":{"rendered":"Mediateca. Apuntes de cine"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><b><i><strong>Jack el caza gigantes (2013)<\/strong><\/i><\/b><\/p>\n<p style=\"text-align: justify\"><i>\u00bfMe cuentas un cuento?<\/i><\/p>\n<p>&nbsp;<\/p>\n<p><i>\u00a0<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9604\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes1.jpg\" alt=\"Jack el caza gigantes\" width=\"397\" height=\"571\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes1.jpg 397w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes1-208x300.jpg 208w\" sizes=\"auto, (max-width: 397px) 100vw, 397px\" \/><\/p>\n<p style=\"text-align: justify\">Adaptaci\u00f3n para adultos del cuento \u00a0\u201c<i>Jack y las habichuelas m\u00e1gicas<\/i>\u201d, del escritor dan\u00e9s \u00a0<b><i><strong>Hans Christian Andersen.<\/strong>\u00a0 <\/i><\/b><\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><iframe loading=\"lazy\" title=\"Jack el caza gigantes - Trailer final en espa\u00f1ol HD\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/mnPa4UsXD-U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><i>Cine fant\u00e1stico y de aventuras.\u00a0 <\/i>Un cuento convertido en epopeya.\u00a0 Realizado con los \u00faltimos adelantos tecnol\u00f3gicos, con magn\u00edficos efectos especiales, en la l\u00ednea de \u00a0\u201cel se\u00f1or de los anillos\u201d. \u00a0A pesar de ello, la historia mantiene el encanto de los <b><i><strong>cuentos cl\u00e1sicos.<\/strong><\/i><\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><b><i><strong>El origen de todo<\/strong><\/i><\/b><b><i><\/i><\/b><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9606\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes2.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"299\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes2.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes2-300x199.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\">Jack se reencuentra con el pasado.\u00a0\u00a0 En la caba\u00f1a,\u00a0 <i>el viejo libro de cuentos de la familia<\/i>.\u00a0 Recuerdos lejanos de la infancia.\u00a0 Cuentos al calor del hogar, con la voz grave del padre, mientras le\u00eda sus gastadas hojas, \u00a0la imaginaci\u00f3n de Jack recorr\u00eda mundos habitados por extra\u00f1os seres\u2026 \u00a0\u00a0Cuentos a la luz de una vela en el crudo invierno\u00a0 del bosque, \u00a0mientras que la lluvia y el viento golpeaban incesantemente la caba\u00f1a, \u00a0con un sonido seco e inquietante\u2026<\/p>\n<p style=\"text-align: justify\"><b><i>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9607\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes3.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"187\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes3.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes3-300x124.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/i><\/b><\/p>\n<p style=\"text-align: justify\"><b><i>\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify\"><b><i><strong>Sinopsis<\/strong>.\u00a0\u00a0 <\/i><\/b>La paz entre los seres humanos y los gigantes llega a su fin, cuando \u00e9stos secuestran a una princesa.\u00a0 En respuesta, un grupo de hombres valientes encabezado por un joven granjero intentar\u00e1n rescatarla\u2026<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9608\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes4.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"311\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes4.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes4-300x207.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><b><i><strong>A destacar<\/strong><\/i><\/b>.\u00a0 \u00a0<i>Jack el caza gigantes<\/i>, es una pel\u00edcula que se ve bien. \u00a0El secreto est\u00e1 en \u00a0un buen gui\u00f3n, \u00a0unos personajes perfectamente definidos, \u00a0que tienen vida propia.\u00a0 La historia est\u00e1 bien narrada y fluye a un buen ritmo, y lo que menos produce en el espectador es aburrimiento, manteniendo la tensi\u00f3n narrativa hasta el final.\u00a0 Adem\u00e1s, los efectos especiales no \u201canulan\u201d\u00a0 la estructura del cuento, manteniendo un equilibrio entre narraci\u00f3n y tecnolog\u00eda, \u00a0con lo que le da un halo de cuento cl\u00e1sico.<\/p>\n<p style=\"text-align: justify\">Dirigida por <b><i><strong>Bryan Singer<\/strong><\/i><\/b>, que vuelve otra vez al cine fant\u00e1stico, en el que se mueve con gran acierto. \u00a0Bryan tiene en su haber 13 pel\u00edculas, que van del cine fant\u00e1stico al thriller:\u00a0 \u00a0<b><i><strong>X-Men<\/strong><\/i><\/b>,\u00a0 <b><i><strong>Superman Returns<\/strong><\/i><\/b>,\u00a0 y\u00a0 <b><i><strong>Valkiria<\/strong><\/i><\/b> (un film de acci\u00f3n y b\u00e9lico).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><b><i><strong>Fotogramas<\/strong><\/i><\/b>.\u00a0\u00a0 Unas pinceladas.<\/p>\n<p>Entre el <i>mito y la leyenda<\/i>.\u00a0 Una historia de gigantes, y de la enemistad ancestral con los humanos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9609\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigante5.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"187\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigante5.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigante5-300x124.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\">Hay un territorio entre la tierra y el cielo, la tierra intermedia, en donde habitan unos temibles seres, cuyo nombre da pavor,\u00a0 \u201c<b><strong>los gigantes<\/strong><\/b>\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9610\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes6.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"299\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes6.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes6-300x199.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\">Hac\u00eda mucho, mucho tiempo que los humanos no hab\u00edan pisado ese peligroso territorio, un hecho que encoleriz\u00f3 a sus moradores<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9611\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes7.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"260\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes7.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes7-300x173.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\">La venganza, se sirve en la mesa, y en caliente\u2026<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9612\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes8.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"187\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes8.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes8-300x124.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9613\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes9.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"186\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes9.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes9-300x124.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9614\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes10.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"237\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes10.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes10-300x158.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9615\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes11.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"225\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes11.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes11-300x150.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">En este estado de cosas, la guerra es inevitable\u2026<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9616\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes12.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"188\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes12.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes12-300x125.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9617\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes13.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"187\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes13.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes13-300x124.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9618\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes14.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"180\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes14.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes14-300x120.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9619\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes15.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"187\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes15.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes15-300x124.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9620\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes16.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"290\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes16.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes16-300x193.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Y color\u00edn, colorado, este cuento\u2026<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9621\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes17.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"247\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes17.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes17-300x164.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><b><i><strong>Ahora, te toca a ti<\/strong><\/i><\/b><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9622\" src=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes18.jpg\" alt=\"Jack el caza gigantes\" width=\"450\" height=\"232\" srcset=\"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes18.jpg 450w, https:\/\/blogs.ua.es\/bibliotecauniversitaria\/files\/2013\/10\/cazagigantes18-300x154.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify\">\u201c\u00bfMiedo a las alturas?<\/p>\n<p style=\"text-align: justify\">\u00a1No!, \u00a0miedo a caerme\u201d<\/p>\n<p style=\"text-align: justify\">\u00a1S\u00e9 valiente!, \u00a0y vive tu propia aventura.\u00a0 Que no te de v\u00e9rtigo\u2026<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">La puedes encontrar en el <b><i><strong>cat\u00e1logo de la Biblioteca Universitaria<\/strong><\/i><\/b>:<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/gaudi.ua.es\/uhtbin\/cgisirsi\/0\/x\/0\/05?searchdata1=jack_caza_singer%7b245%7d\"><b><i><strong>Jack el caza gigantes\u00a0\u00a0 de Bryan Singer<\/strong><\/i><\/b><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Jack el caza gigantes (2013) \u00bfMe cuentas un cuento? &nbsp; \u00a0 Adaptaci\u00f3n para adultos del cuento \u00a0\u201cJack y las habichuelas m\u00e1gicas\u201d, del escritor dan\u00e9s \u00a0Hans Christian Andersen.\u00a0 &nbsp;<\/p>\n","protected":false},"author":2606,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212],"tags":[161533,5776],"class_list":["post-9601","post","type-post","status-publish","format-standard","hentry","category-cine","tag-apuntes-de-cine","tag-mediateca"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/9601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/users\/2606"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/comments?post=9601"}],"version-history":[{"count":12,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/9601\/revisions"}],"predecessor-version":[{"id":14365,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/posts\/9601\/revisions\/14365"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/media?parent=9601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/categories?post=9601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/bibliotecauniversitaria\/wp-json\/wp\/v2\/tags?post=9601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}