{"id":186,"date":"2016-06-25T12:56:19","date_gmt":"2016-06-25T12:56:19","guid":{"rendered":"https:\/\/blogs.ua.es\/brainsedenua\/?p=186"},"modified":"2024-04-19T10:55:14","modified_gmt":"2024-04-19T10:55:14","slug":"dia-1-the-quest-for-parity","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/brainsedenua\/2016\/06\/25\/dia-1-the-quest-for-parity\/","title":{"rendered":"D\u00eda 1 &#8211; The Quest for Parity"},"content":{"rendered":"<figure id=\"attachment_189\" aria-describedby=\"caption-attachment-189\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113134_HDR.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-189 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113134_HDR-150x150.jpg\" alt=\"LTS Games trajo el sol a Cambridge\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113134_HDR-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113134_HDR-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113134_HDR-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-189\" class=\"wp-caption-text\">LTS Games trajo el sol a Cambridge<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Se nota que hemos venido de Espa\u00f1a: nada m\u00e1s llegar hacemos que salga  el sol hasta en Cambridge. A las 10h est\u00e1bamos listos para ser recibidos por la chica simp\u00e1tica del registro. Despu\u00e9s de firmar unos papeles en los que pon\u00eda algo de vender nuestras almas al diablo en caso de muerte, nos dieron una <em>tablet<\/em> <em>chinorri<\/em> para poder jugar con ella. Despu\u00e9s de ver que tiene una c\u00e1mara y pantalla decentes, llegamos a la conclusi\u00f3n de que tambi\u00e9n podr\u00edamos usarla para probar nuestro juego.<\/p>\n<p style=\"text-align: justify\">Despu\u00e9s de registrarnos ten\u00edamos un rato de espera hasta que nos dieran nuestro primer <em>Lunch<\/em>. Aprovechamos para discutir m\u00e1s ideas acerca de las mec\u00e1nicas que podr\u00edamos utilizar en el juego, mientras hac\u00edamos la fotos\u00edntesis: as\u00ed nos sal\u00edan ideas m\u00e1s brillantes. A las 12:30h, y con puntualidad brit\u00e1nica, entramos en el restaurante impacientes por ver en qu\u00e9 consist\u00eda el grandioso <em>Lunch<\/em>. Exceptuando algunos detalles, el <em>Lunch<\/em> nos sorprendi\u00f3 para bien.<\/p>\n<figure id=\"attachment_190\" aria-describedby=\"caption-attachment-190\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113239_HDR.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-190 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113239_HDR-150x150.jpg\" alt=\"Hablemos de mec\u00e1nicas\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113239_HDR-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113239_HDR-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_113239_HDR-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-190\" class=\"wp-caption-text\">Hablemos de mec\u00e1nicas<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Hab\u00eda lasa\u00f1a de ternera y vegetal, arroz con verduras y alg\u00fan que otro plato m\u00e1s que no probamos. Tartas de chocolate y queso con ar\u00e1ndanos y autoservicio de ensaladas. Lo \u00fanico m\u00e1s llamativo eran los colores naranja semitransparente y rojo p\u00e1lido de las bebidas de sabores: todos menos uno optamos por beber agua. El menos uno tambi\u00e9n termin\u00f3 bebiendo agua, tras comprobar que el rojo p\u00e1lido no era un buen presagio.<\/p>\n<p style=\"text-align: justify\">Con el est\u00f3mago lleno, y a\u00fan mucha menos hambre de la que ten\u00edamos al entrar al <em>Lunch<\/em>, regresamos a la sala de registro para que nos llevaran en grupos a los distintos <em>Workshops<\/em>. La voz de la chica amable de registro nos convenci\u00f3 a todos para que fu\u00e9ramos al <em>Workshop<\/em> de programaci\u00f3n, e iniciamos el peregrinaje hacia el otro edificio, en busca de nuevos conocimientos.<\/p>\n<figure id=\"attachment_192\" aria-describedby=\"caption-attachment-192\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_124522.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-192 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_124522-150x150.jpg\" alt=\"Tomando energ\u00edas en el Lunch\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_124522-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_124522-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_124522-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-192\" class=\"wp-caption-text\">Tomando energ\u00edas en el Lunch<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Hab\u00eda tanta gente en el Workshop que lo hab\u00edan dividido en 2 laboratorios y en uno de ellos se ve\u00eda la presentaci\u00f3n por <em>streaming<\/em>. Como no pod\u00eda ser de otra manera, nos toc\u00f3 el laboratorio malo, y el <em>streaming<\/em> no era muy all\u00e1. Al rato optaron por juntarnos a todos en el otro laboratorio, cuando se dieron cuenta de que los gemidos que musitaban los altavoces no eran inteligibles. En la charla un simp\u00e1tico chico de ARM nos cont\u00f3 con emoci\u00f3n como consegu\u00eda <em>renderizar<\/em> una escena con chorrocientos reflejos y m\u00e1s capas que una cebolla sin que el procesador agonizase. Mucha optimizaci\u00f3n y muchas t\u00e9cnicas interesantes, aunque tambi\u00e9n algunos bostezos por el calor y las digestiones en proceso.<\/p>\n<p style=\"text-align: justify\">Tras esta primera charla, volvieron a dividirnos en 2 laboratorios y comenz\u00f3 una segunda parte en la que nos ense\u00f1aron t\u00e9cnicas de iluminaci\u00f3n din\u00e1mica.<\/p>\n<figure id=\"attachment_202\" aria-describedby=\"caption-attachment-202\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/PANO_20160624_135726.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-202\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/PANO_20160624_135726-300x51.jpg\" alt=\"Streaming con altavoces emitiendo gemidos de otro mundo\" width=\"300\" height=\"51\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/PANO_20160624_135726-300x51.jpg 300w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/PANO_20160624_135726-768x131.jpg 768w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/PANO_20160624_135726-1024x175.jpg 1024w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/PANO_20160624_135726.jpg 1851w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-202\" class=\"wp-caption-text\">Streaming con altavoces emitiendo gemidos de otro mundo<\/figcaption><\/figure>\n<p style=\"text-align: justify\">En esta segunda parte nos dieron un proyecto en Unity con el que pod\u00edamos juguetear con el modelo de iluminaci\u00f3n que nos estaban contando. Aunque la idea era interesante, hubiera sido mejor si nos hubieran dejado tiempo para juguetear con el proyecto. En lugar de eso, el autor nos dio otra charla de una hora, que justo termin\u00f3 cuando nos ten\u00edamos que ir. Moraleja: intentar condensar en 2 horas cosas que requieren 8 da mucho menos de 1\/4 de los mismos resultados.<\/p>\n<figure id=\"attachment_193\" aria-describedby=\"caption-attachment-193\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_161210_HDR.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-193 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_161210_HDR-150x150.jpg\" alt=\"Parity, el tema que nos dej\u00f3 a todos sin palabras\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_161210_HDR-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_161210_HDR-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_161210_HDR-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-193\" class=\"wp-caption-text\">Parity, el tema que nos dej\u00f3 a todos sin palabras<\/figcaption><\/figure>\n<p style=\"text-align: justify\">A la vuelta de los <em>Workshops<\/em> nos juntamos de nuevo en la sala con la chica amable de la recepci\u00f3n y sus compa\u00f1eros. Nos amontonamos todos para el anuncio del advenimiento: el tema estaba a punto de aparecer en escena. Tras indicarnos las normas de convivencia y seguridad, y un repicar de suspense, lleg\u00f3 el tema: <em>Parity<\/em>. Las caras de todos se quedaron congeladas por un momento y empezamos a mirarnos como diciendo &#8220;Paridad? Y c\u00f3mo hacemos un juego sobre Paridad?&#8221;. Tardamos un buen rato en recuperarnos del impacto de la tem\u00e1tica: buscamos distintas alternativas de significado del t\u00e9rmino <em>Parity<\/em> en ingl\u00e9s de camino a la zona de desarrollo. Despu\u00e9s de muchas vueltas, una soluci\u00f3n apareci\u00f3: <em>Parity<\/em> es una propiedad cu\u00e1ntica de algunas part\u00edculas subat\u00f3micas.<\/p>\n<figure id=\"attachment_194\" aria-describedby=\"caption-attachment-194\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_172013-e1466851221562.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-194 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_172013-e1466851221562-150x150.jpg\" alt=\"Gravitones a montones!\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_172013-e1466851221562-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_172013-e1466851221562-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_172013-e1466851221562-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-194\" class=\"wp-caption-text\">Gravitones a montones!<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Tras unos redise\u00f1os por aqu\u00ed y unos encajes por all\u00e1, y algo m\u00e1s de media hora de pensar y repensar, el concepto estaba listo. El juego consiste en transmitir mensajes en el espacio y el tiempo utilizando <em>gravitones<\/em>. En cada nivel, controlaremos la gravedad para mover un <em>gravit\u00f3n<\/em> y llevarlo hasta su part\u00edcula par. Cada vez que se consigue el contacto entre un gravit\u00f3n y su part\u00edcula par se consiguen transmitir algunos bits de un mensaje. El mensaje completo es el argumento del juego y se ir\u00e1 mostrando conforme el jugador avanza niveles, descubriendo la historia. Para controlar la gravedad, el jugador tendr\u00e1 2 pulsadores: girar a izquierda y a derecha. Con cada pulsaci\u00f3n, el mapa entero rotar\u00e1 una cantidad variando la gravedad y permitiendo controlar los movimientos de forma indirecta.<\/p>\n<figure id=\"attachment_196\" aria-describedby=\"caption-attachment-196\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_204515-e1466852512950.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-196 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_204515-e1466852512950-150x150.jpg\" alt=\"Mucha intensidad al comienzo del desarrollo\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_204515-e1466852512950-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_204515-e1466852512950-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_204515-e1466852512950-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-196\" class=\"wp-caption-text\">Mucha intensidad al comienzo del desarrollo<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Concepto en mano, nos planteamos tener una primera versi\u00f3n del juego funcionando antes de irnos a dormir. El n\u00facleo del juego ser\u00e1n niveles r\u00e1pidos con jugabilidad sencilla y una historia emotiva embebida en el mensaje. Casi a las 17:00h empezamos a trabajar: dise\u00f1o de niveles, implementaci\u00f3n de mec\u00e1nicas y elaboraci\u00f3n de la historia. Mucho trabajo por delante, pero un concepto claro y muchas ganas de hacer un buen juego. Durante la tarde, el concepto recibi\u00f3 el respaldo de 2 mentores que se interesaron por lo que est\u00e1bamos desarrollando. Ambos coincidieron en su valoraci\u00f3n positiva, destacando la simplicidad del concepto y la buena aproximaci\u00f3n de planificaci\u00f3n para poder tener un proyecto terminado. Muchos \u00e1nimos por parte de ambos que nos hicieron empezar con muy buen pie.<\/p>\n<figure id=\"attachment_195\" aria-describedby=\"caption-attachment-195\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_182025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-195 size-thumbnail\" src=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_182025-150x150.jpg\" alt=\"Cena potenciadora del Level Design!\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_182025-150x150.jpg 150w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_182025-36x36.jpg 36w, https:\/\/blogs.ua.es\/brainsedenua\/files\/2016\/06\/20160624_182025-115x115.jpg 115w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-195\" class=\"wp-caption-text\">Cena potenciadora del Level Design!<\/figcaption><\/figure>\n<p style=\"text-align: justify\">A mitad de tarde nos trajeron el <em>Dinner<\/em>, por llamarlo cari\u00f1osamente m\u00e1s que nada. El formato del <em>Dinner<\/em> <a href=\"https:\/\/mentos4d.iutarc.net\/\n\">mentos 4d<\/a> es el de s\u00e1lvese quien pueda: trajeron cajas y cada uno cog\u00eda lo que pod\u00eda o le dejaban. Entre todo ello conseguimos pescar algunos <em>sandwitches<\/em>, fruta y patatas fritas, una combinaci\u00f3n altamente energ\u00e9tica y potenciadora del buen dise\u00f1o de niveles, como todo el mundo sabe. Con este \u00faltimo impulso continuamos desarrollando niveles y el concepto del juego hasta la hora de irse, algo antes de las 24:00h. Al cerrar el d\u00eda ten\u00edamos un primer prototipo semifuncional, algunos niveles dise\u00f1ados y mec\u00e1nicas y una buena lista de detalles y mejoras para completar al d\u00eda siguiente, pero eso ser\u00eda otra historia&#8230;<\/p>\n<ol>\n","protected":false},"excerpt":{"rendered":"<p>Se nota que hemos venido de Espa\u00f1a: nada m\u00e1s llegar hacemos que salga el sol hasta en Cambridge. A las 10h est\u00e1bamos listos para ser recibidos por la chica simp\u00e1tica del registro. Despu\u00e9s de firmar unos papeles en los que pon\u00eda algo de vender nuestras almas al diablo en caso de muerte, nos dieron una [&hellip;]<\/p>\n","protected":false},"author":4110,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[676],"tags":[1540081,1540078,1540079,1540080],"class_list":["post-186","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-brains-eden","tag-cambridge","tag-gamedev","tag-indiedev"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/users\/4110"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":19,"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"predecessor-version":[{"id":236,"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/posts\/186\/revisions\/236"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/brainsedenua\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}