{"id":150,"date":"2013-01-27T21:03:13","date_gmt":"2013-01-27T21:03:13","guid":{"rendered":"https:\/\/blogs.ua.es\/cajaahorrossureste\/?page_id=150"},"modified":"2013-01-27T21:08:38","modified_gmt":"2013-01-27T21:08:38","slug":"galeria-fotografica","status":"publish","type":"page","link":"https:\/\/blogs.ua.es\/cajaahorrossureste\/galeria-fotografica\/","title":{"rendered":"Galeria fotogr\u00e1fica"},"content":{"rendered":"<p>Las primeras Cajas de Ahorros que se fusionaron para formar la CAM<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/marcaporhombro.com\/wp-content\/uploads\/2012\/07\/Sin-t\u00edtulo-2.jpg\" alt=\"\" width=\"391\" height=\"234\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Evoluci\u00f3n del Logotipo de la CAM<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/marcaporhombro.com\/wp-content\/uploads\/2012\/07\/cam-1.jpg\" alt=\"\" width=\"500\" height=\"175\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/marcaporhombro.com\/wp-content\/uploads\/2012\/07\/medi.jpg\" alt=\"\" width=\"500\" height=\"122\" \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/marcaporhombro.com\/wp-content\/uploads\/2012\/07\/cam2.jpg\" alt=\"\" width=\"560\" height=\"122\" \/><\/p>\n<p>Fusi\u00f3n Banco Sabadell &#8211; CAM<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/marcaporhombro.com\/wp-content\/uploads\/2012\/07\/logomed.jpg\" alt=\"\" width=\"500\" height=\"217\" \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/marcaporhombro.com\/wp-content\/uploads\/2012\/07\/Captura-de-pantalla-2012-07-09-a-las-19.18.14-500x199.png\" alt=\"\" width=\"500\" height=\"199\" \/><\/p>\n<p>Im\u00e1genes disponibles en : <a href=\"http:\/\/marcaporhombro.com\/cam\/\">http:\/\/marcaporhombro.com\/cam\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Art\u00edculos varios de la Caja de Ahorros del Sureste:<\/p>\n<p>Cartilla de ahorros entre 1.944 y 1.955<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/pictures2.todocoleccion.net\/tc\/2012\/06\/21\/32246963.jpg\" alt=\"TRASTERIACOM - 2 LIBRETA CAJA DE AHORROS SURESTE DE ESPA\u00d1A 1.944 y 1.955 CARTILLA (Papel - Documentos - Otros documentos)\" width=\"399\" height=\"271\" border=\"0\" \/><\/p>\n<p><a href=\"http:\/\/www.todocoleccion.net\/trasteriacom-2-libreta-caja-ahorros-sureste-espana-1-944-1-955-cartilla~x32246963\">http:\/\/www.todocoleccion.net\/trasteriacom-2-libreta-caja-ahorros-sureste-espana-1-944-1-955-cartilla~x32246963<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Cajas antiguas de la Caja de Ahorros del Sureste:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/pictures2.todocoleccion.net\/tc\/2012\/10\/14\/33689879.jpg\" alt=\"Caja antigua de CAJA DE AHORROS DEL SURESTE DE ESPA\u00d1A N 33611 y otra nueva  (Botellas, Cajas y Envases - Cajas y Cajitas Met\u00e1licas)\" width=\"398\" height=\"244\" border=\"0\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.todocoleccion.net\/caja-antigua-caja-ahorros-sureste-espana-n-33611-otra-nueva~x33689879\">http:\/\/www.todocoleccion.net\/caja-antigua-caja-ahorros-sureste-espana-n-33611-otra-nueva~x33689879<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Calendario de la Caja de Ahorros del Sureste en 1.964:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/pictures2.todocoleccion.net\/tc\/2012\/05\/13\/31742570.jpg\" alt=\"Calendario Fournier a\u00f1o 1964 Caja de ahorros del sureste de Espa\u00f1a (Papel - Calendarios)\" width=\"400\" height=\"239\" border=\"0\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.todocoleccion.net\/calendario-fournier-ano-1964-caja-ahorros-sureste-espana~x31742570\">http:\/\/www.todocoleccion.net\/calendario-fournier-ano-1964-caja-ahorros-sureste-espana~x31742570<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Caja de ahorros del Sureste en Benal\u00faa, y \u00a0Villena:<\/p>\n<p><a href=\"http:\/\/3.bp.blogspot.com\/_IQNDFvXJF-k\/ScUKxT2qcII\/AAAAAAAAMOk\/12JnrS4XzNo\/s1600-h\/caja1.jpg\"><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/_IQNDFvXJF-k\/ScUKxT2qcII\/AAAAAAAAMOk\/12JnrS4XzNo\/s320\/caja1.jpg\" alt=\"\" border=\"0\" \/><\/a>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<a href=\"http:\/\/1.bp.blogspot.com\/-mtSp-kbgStI\/ULkCvTWj4YI\/AAAAAAABkAc\/GOchPQAaQHc\/s1600\/1965+tesoro+villena+deposito+en+la+caja+de+ahorros+del+sureste+franciscopalazondirectorsucursal+y+educardolopez+tesorero+municipal.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-mtSp-kbgStI\/ULkCvTWj4YI\/AAAAAAABkAc\/GOchPQAaQHc\/s400\/1965+tesoro+villena+deposito+en+la+caja+de+ahorros+del+sureste+franciscopalazondirectorsucursal+y+educardolopez+tesorero+municipal.jpg\" alt=\"\" width=\"265\" height=\"325\" border=\"0\" \/><\/a><\/p>\n<p>La Caja de Ahorros del Sureste en Benal\u00faa\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0El dep\u00f3sito\u00a0del tesoro\u00a0de la Caja de Ahorros del Sureste en<\/p>\n<p>Villena<\/p>\n<p><a href=\"http:\/\/www.barriodebenalua.es\/2009\/04\/la-caja-de-ahorros-del-sureste-en.html\">http:\/\/www.barriodebenalua.es\/2009\/04\/la-caja-de-ahorros-del-sureste en.html\u00a0\u00a0\u00a0<\/a><\/p>\n<p><a href=\"http:\/\/www.villenacuentame.com\/2012\/12\/1965-deposito-del-tesoro-de-villena-en.html\">http:\/\/www.villenacuentame.com\/2012\/12\/1965-deposito-del-tesoro-de-villena-en.html<\/a><\/p>\n<p>La\u00a0Caja de Ahorros del Sureste\u00a0en\u00a0Alicante:<\/p>\n<p><a href=\"http:\/\/1.bp.blogspot.com\/-RYocyQJm0-0\/Tt_sQrRRJQI\/AAAAAAAAAqI\/WuSFwnAAfBo\/s1600\/CAM.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-RYocyQJm0-0\/Tt_sQrRRJQI\/AAAAAAAAAqI\/WuSFwnAAfBo\/s400\/CAM.jpg\" alt=\"\" width=\"400\" height=\"339\" border=\"0\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.alicantevivo.org\/2011\/12\/los-origenes-alicantinos-de-la-cam-la.html\">http:\/\/www.alicantevivo.org\/2011\/12\/los-origenes-alicantinos-de-la-cam-la.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Caja del Mediterr\u00e1neo en Alicante y Murcia:<\/p>\n<p><a href=\"http:\/\/3.bp.blogspot.com\/-dpqq7pmRBuA\/TZ4hx4U_qfI\/AAAAAAAAszk\/SlH55pzIdZQ\/s1600\/CAM+sede+nueva.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-dpqq7pmRBuA\/TZ4hx4U_qfI\/AAAAAAAAszk\/SlH55pzIdZQ\/s400\/CAM+sede+nueva.jpg\" alt=\"\" width=\"336\" height=\"268\" border=\"0\" \/><\/a><a id=\"irc_mil\" href=\"&amp;ved=0CAUQjRw&amp;url=http%3A%2F%2Fwww.europapress.es%2Feconomia%2Fnoticia-banco-sabadell-hace-efectiva-inyeccion-2449-millones-cam-20120601200530.html&amp;ei=f5MFUcndJMXMhAfK_IGgBg&amp;psig=AFQjCNGVYKuv0yP4QsKHMDszdYYJSmnNCQ&amp;ust=1359406336084404\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/img.europapress.net\/fotoweb\/fotonoticia_20120601200530_500.jpg\" alt=\"\" width=\"325\" height=\"266\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.europapress.es\/economia\/noticia-banco-sabadell-hace-efectiva-inyeccion-2449-millones-cam-20120601200530.html\">http:\/\/www.europapress.es\/economia\/noticia-banco-sabadell-hace-efectiva-inyeccion-2449-millones-cam-20120601200530.html<\/a><\/p>\n<p><a href=\"http:\/\/murciaconfidencial.blogspot.com.es\/2011_04_07_archive.html\">http:\/\/murciaconfidencial.blogspot.com.es\/2011_04_07_archive.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Banco Sabadell- la CAM:<\/p>\n<p>&nbsp;<\/p>\n<p><a id=\"irc_mil\" href=\"&amp;ved=0CAUQjRw&amp;url=http%3A%2F%2Fwww.elmundo.es%2Felmundo%2F2012%2F10%2F10%2Feconomia%2F1349830991.html&amp;ei=f5UFUf_OIdSzhAeQioDoCA&amp;bvm=bv.41524429,d.ZG4&amp;psig=AFQjCNEofDRypz6uMkQXkNg8i5adoLYJpw&amp;ust=1359406848018741\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/estaticos.elmundo.es\/elmundo\/imagenes\/2012\/10\/10\/economia\/1349830991_0.jpg\" alt=\"\" width=\"470\" height=\"313\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.elmundo.es\/elmundo\/2012\/10\/10\/economia\/1349830991.html\">http:\/\/www.elmundo.es\/elmundo\/2012\/10\/10\/economia\/1349830991.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las primeras Cajas de Ahorros que se fusionaron para formar la CAM &nbsp; &nbsp; Evoluci\u00f3n del Logotipo de la CAM \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Fusi\u00f3n Banco Sabadell &#8211; CAM \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Im\u00e1genes disponibles en : http:\/\/marcaporhombro.com\/cam\/ &nbsp; Art\u00edculos varios de la Caja de Ahorros del Sureste: Cartilla de ahorros entre 1.944 y 1.955 http:\/\/www.todocoleccion.net\/trasteriacom-2-libreta-caja-ahorros-sureste-espana-1-944-1-955-cartilla~x32246963 &nbsp; Cajas antiguas de la [&hellip;]<\/p>\n","protected":false},"author":3000,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-150","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/pages\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/users\/3000"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/pages\/150\/revisions"}],"predecessor-version":[{"id":156,"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/pages\/150\/revisions\/156"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/cajaahorrossureste\/wp-json\/wp\/v2\/media?parent=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}