{"id":42,"date":"2009-03-05T14:45:05","date_gmt":"2009-03-05T13:45:05","guid":{"rendered":"https:\/\/blogs.ua.es\/calvino\/?p=42"},"modified":"2009-03-05T14:45:05","modified_gmt":"2009-03-05T13:45:05","slug":"el-desarrollo-de-la-institucion","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/calvino\/2009\/03\/05\/el-desarrollo-de-la-institucion\/","title":{"rendered":"EL Desarrollo de La Institucion"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify\"><span lang=\"ES\">La primera edici\u00f3n de la Instituci\u00f3n fue publicada en Basilea para el mes de marzo de 1536. El libro, en aquel entonces, ten\u00eda tan s\u00f3lo 516 p\u00e1ginas y era peque\u00f1o, de tal manera que cab\u00eda en los amplio bolsillos de la \u00e9poca, y por tanto pod\u00eda circular encubiertamente en Francia. Ten\u00eda s\u00f3lo seis cap\u00edtulos. Los primeros cuatro hablaban sobre la ley, el Credo, el Padrenuestro y los sacramentos. Los \u00faltimos dos eran un resumen de la posici\u00f3n protestante frente a los &#8220;falsos sacramentos romanos,&#8221; y a la libertad cristiana.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span lang=\"ES\"><span lang=\"ES\">En ediciones sucesivas, Calvino lo ampli\u00f3 desde seis cap\u00edtulos a ochenta, completando as\u00ed cuatro libros. En la \u00faltima edici\u00f3n, la de 1559, la Instituci\u00f3n sigui\u00f3 el orden del Credo Apost\u00f3lico, al tratar de las verdades de la religi\u00f3n cristiana. Al d\u00eda de hoy, la Instituci\u00f3n est\u00e1 disponible en por lo menos diez idiomas.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span lang=\"ES\"><span lang=\"ES\">sus 4 libros son: 1- El conocimiento de Dios. 2- El conocimiento de Dios como redentor de Cristo. 3- Participacion de la gracia de Jsucristo. 4- Las ayudas de Dios<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera edici\u00f3n de la Instituci\u00f3n fue publicada en Basilea para el mes de marzo de 1536. El libro, en aquel entonces, ten\u00eda tan s\u00f3lo 516 p\u00e1ginas y era peque\u00f1o, de tal manera que cab\u00eda en los amplio bolsillos de la \u00e9poca, y por tanto pod\u00eda circular encubiertamente en Francia. Ten\u00eda s\u00f3lo seis cap\u00edtulos. Los [&hellip;]<\/p>\n","protected":false},"author":1148,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-42","post","type-post","status-publish","format-standard","hentry","category-sin-categora"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/posts\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/users\/1148"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"predecessor-version":[{"id":43,"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/posts\/42\/revisions\/43"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/calvino\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}