{"id":52,"date":"2023-02-21T21:02:48","date_gmt":"2023-02-21T21:02:48","guid":{"rendered":"https:\/\/blogs.ua.es\/conchaalos\/?p=52"},"modified":"2023-03-01T22:15:49","modified_gmt":"2023-03-01T22:15:49","slug":"homenajes-y-vuelta-a-casa-parte-i","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/conchaalos\/2023\/02\/21\/homenajes-y-vuelta-a-casa-parte-i\/","title":{"rendered":"Homenajes y vuelta a casa (parte I)"},"content":{"rendered":"<p>Justo ayer se inaugur\u00f3 en <a href=\"https:\/\/www.apuntmedia.es\/noticies\/cultura\/concha-alos-l-escriptora-castellonenca-oblidada-critica-literaria-franquisme_1_1593179.html\" target=\"_blank\" rel=\"noopener\">La Casa de los Caracoles<\/a> de Castell\u00f3n de la Plana la exposici\u00f3n en honor a Concha Al\u00f3s. Pincha <a href=\"https:\/\/www.vivecastellon.com\/noticiario\/fotos-40831\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed <\/a>si quieres ver la galer\u00eda de fotos. El colof\u00f3n a este homenaje ser\u00e1 el pr\u00f3ximo viernes 24 con la participaci\u00f3n de las cuatro Alosianas, as\u00ed en may\u00fascula, donde cada una hablar\u00e1 de un aspecto diferente de la literatura de Concha Al\u00f3s. Pero eso ya os lo contar\u00e9 en la segunda parte de esta entrada. Ahora me detengo en el <em>making off<\/em> del homenaje hasta llegar al gran d\u00eda de ayer.<\/p>\n<p>Podr\u00eda retrotraerme al pasado julio. Ola de calor en Berl\u00edn (para ellos 35\u00ba C es muerte s\u00fabita). He estado m\u00e1s de ocho horas viajando en trenes regionales desde Frankfurt haciendo malabares con los horarios y los trasbordos (esto se explica porque ten\u00eda el abono de verano alem\u00e1n y viajar as\u00ed era muy econ\u00f3mico). El atrac\u00f3n de tren mereci\u00f3 la pena. Hab\u00eda quedado con la que ser\u00eda mi futura antorcha alosiana en una braser\u00eda de comida espa\u00f1ola frente a un hotel berlin\u00e9s m\u00e1s o menos c\u00e9ntrico. La Alosiana original. Amparo Ayora del Olmo. Ella lleva trabajando en Concha Al\u00f3s desde hace varios a\u00f1os. Yo hab\u00eda le\u00eddo su ensayo <em>Las guerras de Concha Al\u00f3s: Castell\u00f3n, historia y relato<\/em> de 2015. Para m\u00ed era muy importante conocerla, hablarle de mi investigaci\u00f3n.<\/p>\n<p>A riesgo de repetirme, creo que no he contado c\u00f3mo insist\u00ed a Ver\u00f3nica Bernardini, nuestra Alosiana de N\u00e1poles, para que me pasara el contacto de Amparo Ayora. Ella tambi\u00e9n hab\u00eda estado a\u00f1os antes con Amparo y, gracias a ella, Ver\u00f3nica conoci\u00f3 y entrevist\u00f3 a la hermana de Concha Al\u00f3s. Francamente, he de confesaros que, como buena friki Alosiana que soy, a m\u00ed me daba vueltas la cabeza y mataba por poder hacer lo mismo que Ver\u00f3nica. As\u00ed que me convert\u00ed en una chica pesada y acribill\u00e9 a correos la bandeja de entrada de Bernardini. Y ah\u00ed me vi, semanas m\u00e1s tarde, sentada en la braser\u00eda de comida espa\u00f1ola en Berl\u00edn, con tremendo sudor en la espalda porque los 35\u00baC apretaban, conociendo a la mujer que iluminar\u00eda mi camino alosiano con su energ\u00eda y empe\u00f1o.<\/p>\n<p>All\u00ed le cont\u00e9 a Amparo Ayora mi lucha, sin demasiado \u00e9xito, por conseguir que la figura de Concha Al\u00f3s fuera revalorada porque, hasta hace bien poquito, su nicho era un n\u00famero perdido entre las sinuosas colinas de Montju\u00efc. El nombre de Concha Al\u00f3s estaba siendo rescatado por el mundo editorial, pero necesitaba un toque, un empuje, <em>algo grande<\/em>\u2026 Amparo lo ten\u00eda claro. Me dijo: \u00abMira, bonica, hace tiempo que tengo una idea. De hecho, estuve hablando con Mar\u00eda del Mar Bonet, pero no pudo ser. Ahora ser\u00e1 diferente. Vamos a traer a Concha Al\u00f3s a Castell\u00f3n, junto a su familia. Donde debe estar\u00bb. No me acuerdo si fueron sus palabras exactas, estoy ficcionalizando el momento, pero creo que la idea queda bastante clara.<\/p>\n<p>Nos pusimos manos a la obra. La misi\u00f3n consist\u00eda en conseguir hablar con Mar\u00eda del Mar Bonet, la persona que ten\u00eda los derechos de la tumba de Concha Al\u00f3s, ya que fue ella quien se hizo cargo de los gastos del sepelio cuando Concha Al\u00f3s falleci\u00f3 en julio de 2011. Tir\u00e9 de contactos, habl\u00e9 con Biel Mesquida pidi\u00e9ndole ayuda, \u00e9l me dijo que s\u00ed, que hablar\u00eda con Bonet. El escritor mallorqu\u00edn es amigo de Mar\u00eda del Mar Bonet y tambi\u00e9n estuvo en el entierro de Concha Al\u00f3s. Pero debi\u00f3 pasar que o ten\u00edan la agenda muy apretada o yo era una mindundi para tomarme en serio. Yo deseaba por todos los medios ayudar a Amparo Ayora para retomar unas conversaciones entre Bonet y Ayora que se quedaron congeladas en 2017, cuando ambas se conocieron en el Auditorio de Castell\u00f3n y Amparo le regal\u00f3 un ejemplar de su libro. En aquel encuentro ya proyectaron la idea de gestionar el traslado de los restos mortales de Concha Al\u00f3s a Castell\u00f3n, pero por cuestiones de agenda y otros eventos personales, la idea fue quedando relegada&#8230; hasta ahora.<\/p>\n<p>De manera que, cinco a\u00f1os despu\u00e9s, se inici\u00f3 la burocracia. Amparo Ayora consigui\u00f3 contactar de nuevo con Mar\u00eda del Mar Bonet que facilit\u00f3 la documentaci\u00f3n que necesitaba Ayora. Amparo fue al Ayuntamiento y se reuni\u00f3 con la alcaldesa Amparo Marco que desde el primer momento se entusiasm\u00f3 con el proyecto de Ayora. Se dio luz verde y Amparo Ayora comenz\u00f3 a trabajar duro.<\/p>\n<p>Mi aportaci\u00f3n qued\u00f3 al margen, apoyo moral, poco pod\u00eda hacer desde Granada (una vez que volv\u00ed de Frankfurt) con una mudanza a Alicante a la vuelta de la esquina. Es una justificaci\u00f3n barata, lo reconozco. Pero ella estaba en Castell\u00f3n, ten\u00eda los contactos, la documentaci\u00f3n, ten\u00eda todo el poder en su mano para conseguir ese <em>algo grande<\/em>, como de hecho ha conseguido. Lo primero fue organizar la vuelta p\u00f3stuma a casa de Concha Al\u00f3s. Burocracia. Espera. Contactos con el cementerio de Castell\u00f3n, con el de Barcelona\u2026 Y finalmente, el pasado <a href=\"https:\/\/castellonplaza.com\/la-ultima-vuelta-a-casa-de-concha-alos\" target=\"_blank\" rel=\"noopener\">24 de noviembre<\/a>, se hizo realidad: Concha Al\u00f3s volvi\u00f3 a Castell\u00f3n despu\u00e9s de muchas d\u00e9cadas desde que saliera con su marido para instalarse en la isla de Mallorca.<\/p>\n<p>No fue un traslado com\u00fan. El Ayuntamiento, guiado por los consejos de Amparo Ayora, deseaba otorgarle un espacio conmemorativo a la tumba de Concha Al\u00f3s en un enclave visible y acompa\u00f1ado de una escultura de Juan Cabeza. El nicho ya est\u00e1 culminado y el pr\u00f3ximo viernes 24 ser\u00e1 la celebraci\u00f3n oficial del entierro de Concha Al\u00f3s en su nuevo merecido lugar de reconocimiento. El empe\u00f1o de Amparo Ayora del Olmo y la gentileza del Ayuntamiento de Castell\u00f3n han permitido que sea posible este viernes para que las Alosianas podamos estar en el acto. Prometo fotos en la pr\u00f3xima entrada.<\/p>\n<p>El periodista Ximo G\u00f3rriz se alza como cronista de estos eventos en el diario digital Castell\u00f3n Plaza porque, en consonancia con el evento oficial del funeral p\u00f3stumo con toda la pompa que en su d\u00eda no tuvo, tiene car\u00e1cter y motivo la <a href=\"https:\/\/castellonplaza.com\/el-primer-homenaje-de-castello-a-su-escritora-concha-alos\" target=\"_blank\" rel=\"noopener\">exposici\u00f3n de honor<\/a> a Concha Al\u00f3s en la que, de nuevo, nuestra Alosiana original, ha puesto toda la carne en el asador. Ha pintado y limpiado vitrinas, ha escrito paneles informativos, ha ayudado en las tareas de montaje muse\u00edstico\u2026 Tambi\u00e9n ha cedido su material bibliogr\u00e1fico a la causa. En este punto, es necesario agradecer la confianza y el material fotogr\u00e1fico y personal cedido por la familia Al\u00f3s, su hermana Mercedes y sus hijos Elena y Jos\u00e9 Francisco, important\u00edsimo para que esto fuera posible, as\u00ed como el aporte desinteresado de Montserrat Badal (ya os contar\u00e9 sobre esta gran mujer) y a m\u00e1s personas que han colaborado activamente en la preparaci\u00f3n de unos actos que est\u00e1n dise\u00f1ados desde el amor y el respeto a la figura de Concha Al\u00f3s.<\/p>\n<figure id=\"attachment_53\" aria-describedby=\"caption-attachment-53\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53 size-medium\" src=\"https:\/\/blogs.ua.es\/conchaalos\/files\/2023\/02\/PAU-569-0002-300x296.jpg\" alt=\"\" width=\"300\" height=\"296\" srcset=\"https:\/\/blogs.ua.es\/conchaalos\/files\/2023\/02\/PAU-569-0002-300x296.jpg 300w, https:\/\/blogs.ua.es\/conchaalos\/files\/2023\/02\/PAU-569-0002-100x100.jpg 100w, https:\/\/blogs.ua.es\/conchaalos\/files\/2023\/02\/PAU-569-0002.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-53\" class=\"wp-caption-text\">Archivo Fotogr\u00e1fico de Pau Barcel\u00f3. Fecha desconocida pero se estima que la foto fue tomada entre la d\u00e9cada de los 60 y 70. Material cedido por Montserrat Badal.<\/figcaption><\/figure>\n<p>Estas personas merecen ser nombradas y reconocidas: Delfina Miravete, Mar\u00eda Rubert ayudando en el montaje de la exposici\u00f3n, Jos\u00e9 Luis Lorenz y Paco Mezquita por permitir el acceso al Archivo del Instituto Ribalta, donde estudi\u00f3 Concha Al\u00f3s, Joan Font del Archivo de la Universidad de las Islas Baleares, Virginia Lloret, Ra\u00fal Fuertes, Virginia Fuertes, Jos\u00e9 Manuel Rom\u00e1n y Concha Pascual que durante la inauguraci\u00f3n leyeron fragmentos de la novela <em>El caballo rojo<\/em>; Ximo Roses, Ram\u00f3n Mar\u00edn, las hijas de Rosa Tena, amiga de la infancia de Concha Al\u00f3s\u2026 Todos estos nombres salen del muro de Facebook de Amparo Ayora, porque en su trabajo infinito ha dado espacio para agradecer toda la ayuda brindada y yo, en mi posici\u00f3n pasiva hasta el viernes 24, no me queda m\u00e1s que copiar como un loro.<\/p>\n<p>Y lo que surgi\u00f3 de una conversaci\u00f3n en un lugar anodino de Berl\u00edn \u2e3aen verdad no surgi\u00f3, Amparo ya lo ten\u00eda en mente desde 2017, pero me gusta pensar que mi ingenuidad investigadora empuj\u00f3 a que se retomaran unas ideas que estaban relegadas en un caj\u00f3n cualquiera\u2e3a ha cobrado vida y se ha hecho realidad gracias al trabajo desinteresado de muchas personas contagiadas por ese esp\u00edritu alosiano insuflado por Amparo Ayora del Olmo. Yo volv\u00ed a Frankfurt feliz en un tren Flix con olor a ganado y poca ventilaci\u00f3n, pero por lo menos tard\u00e9 cuatro horas en vez de ocho. Supe que ese viaje hab\u00eda sido el inicio de algo hermoso y de enjundia para el mundo alosiano. Y eso es lo que me llev\u00e9 de aquella aventura.<\/p>\n<p>La cosa es seria, pues, el Ayuntamiento de Castell\u00f3n de la Plana cuenta con la colaboraci\u00f3n de la Diputaci\u00f3n Provincial de Castell\u00f3n y de la Generalitat Valenciana (los cr\u00e9ditos p\u00fablicos no pueden dejarse de lado). Las Alosianas se pondr\u00e1n cara este viernes 24, nos conocemos v\u00eda e-mail, v\u00eda WhatsApp, pero todav\u00eda no hemos llegado a la corporalidad de las tres dimensiones. Llegamos en lo bonito, para poner la guinda a todo un esfuerzo tit\u00e1nico de este homenaje tan emotivo y necesario. Y mientras llega el d\u00eda m\u00e1gico, no queda m\u00e1s que decir gracias. Gracias, Amparo, por reunirnos, por conseguirlo, por contagiarnos tu tes\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Justo ayer se inaugur\u00f3 en La Casa de los Caracoles de Castell\u00f3n de la Plana la exposici\u00f3n en honor a Concha Al\u00f3s. Pincha aqu\u00ed si quieres ver la galer\u00eda de fotos. El colof\u00f3n a este homenaje ser\u00e1 el pr\u00f3ximo viernes 24 con la participaci\u00f3n de las cuatro Alosianas, as\u00ed en may\u00fascula, donde cada una hablar\u00e1 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blogs.ua.es\/conchaalos\/2023\/02\/21\/homenajes-y-vuelta-a-casa-parte-i\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Homenajes y vuelta a casa (parte I)&#8221;<\/span><\/a><\/p>\n","protected":false},"author":4549,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2434572],"tags":[693,691,692],"class_list":["post-52","post","type-post","status-publish","format-standard","hentry","category-hablemos-de","tag-alosianas","tag-exposicion","tag-homenaje"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/posts\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/users\/4549"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/posts\/52\/revisions"}],"predecessor-version":[{"id":80,"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/posts\/52\/revisions\/80"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/categories?post=52"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/conchaalos\/wp-json\/wp\/v2\/tags?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}