{"id":207,"date":"2009-12-23T11:45:19","date_gmt":"2009-12-23T09:45:19","guid":{"rendered":"https:\/\/blogs.ua.es\/concurso09\/?p=207"},"modified":"2009-12-23T11:45:19","modified_gmt":"2009-12-23T09:45:19","slug":"%c2%a1%c2%a1-nuevo-concursante-26","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/concurso09\/2009\/12\/23\/%c2%a1%c2%a1-nuevo-concursante-26\/","title":{"rendered":"\u00a1\u00a1 Nuevo Concursante !!"},"content":{"rendered":"<p><\/p>\n<p align=\"center\"><a href=\"https:\/\/blogs.ua.es\/friedrichludwiggottlobfrege\/\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.ua.es\/concurso09\/files\/2009\/12\/FranciscoGarcia.PNG\" alt=\"\" width=\"300\" height=\"190\" class=\"aligncenter size-medium wp-image-270\" \/><br \/>\n<\/a><\/p>\n<p align=\"center\"><a href=\"https:\/\/blogs.ua.es\/friedrichludwiggottlobfrege\/\"><font color=\"#e69b29\" size=\"4px\"><strong>\u00a1Que divertida es la L\u00f3gica!<br \/>\n<\/strong><\/font><\/a><\/p>\n<p><font color=\"#e69b29\"><strong>Creador:<\/strong><\/font>Francisco Garc\u00eda Lillo<br \/>\n<font color=\"#e69b29\"><strong>Categor\u00eda:<\/strong><\/font> Asignatura<br \/>\n<br \/>\n<font color=\"#e69b29\"><strong>Descripci\u00f3n:<\/strong><\/font><br \/>\nEl blog presentado a concurso tiene por objeto relatar la experiencia vivida como alumno de primer curso de la Licenciatura en Matem\u00e1ticas de un estudiante de la UA, tambi\u00e9n Profesor Titular de \u00e9sta, nuestra Universidad, en el discurrir de la impartici\u00f3n de la asignatura &#8220;L\u00f3gica de Primer Orden&#8221; por parte de la profesora D\u00f1a. M\u00aa Jes\u00fas Castel de Haro adscrita al Dpto. de Ciencia de la Computaci\u00f3n e Inteligencia Artificial.<br \/>\nEn \u00e9l, adem\u00e1s de tratar sobre ciertas cuestiones relativas a la L\u00f3gica de Primer Orden y otros Sistemas L\u00f3gicos, ir\u00e1n apareciendo enlaces de inter\u00e9s sobre dicha materia, recursos did\u00e1cticos,curiosiodades, etc.<br \/>\n\u00bfSab\u00edas, por ejemplo, que \u2026? Arist\u00f3teles fue el primero en establecer una clasificaci\u00f3n de las ciencias, que dividi\u00f3 en teor\u00e9ticas (matem\u00e1ticas, fisica y metaf\u00edsica), pr\u00e1cticas (\u00e9tica, politica y econom\u00eda) y po\u00e9ticas (po\u00e9tica, ret\u00f3rica etc.).<br \/>\nEn esta clasificaci\u00f3n no se incluye la l\u00f3gica, pues \u00e9sta viene a ser el instrumento para el recto discurrir de todas las dem\u00e1s.<br \/>\nLa l\u00f3gica y la metaf\u00edsica fueron en verdad descubiertas por \u00e9l, corrigiendo en aspectos fundamentales las teorias de Plat\u00f3n.<br \/>\n<br \/>\n<font color=\"#e69b29\"><strong>Tags:<\/strong><\/font>L\u00f3gica, LPO, Sistemas L\u00f3gicos, Lenguaje ProLog.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Que divertida es la L\u00f3gica! Creador:Francisco Garc\u00eda Lillo Categor\u00eda: Asignatura Descripci\u00f3n: El blog presentado a concurso tiene por objeto relatar la experiencia vivida como alumno de primer curso de la Licenciatura en Matem\u00e1ticas de un estudiante de la UA, tambi\u00e9n Profesor Titular de \u00e9sta, nuestra Universidad, en el discurrir de la impartici\u00f3n de la asignatura [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5863,1],"tags":[2153,6483,2409,6484],"class_list":["post-207","post","type-post","status-publish","format-standard","hentry","category-categoria-asignaturas","category-general","tag-logica","tag-lpo","tag-prolog","tag-sistemas-logicos"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":210,"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/posts\/207\/revisions\/210"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso09\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}