{"id":109,"date":"2011-03-30T18:32:04","date_gmt":"2011-03-30T16:32:04","guid":{"rendered":"https:\/\/blogs.ua.es\/concurso10\/?p=109"},"modified":"2011-03-30T18:32:29","modified_gmt":"2011-03-30T16:32:29","slug":"%c2%a1%c2%a1-nuevo-concursante-11","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/concurso10\/2011\/03\/30\/%c2%a1%c2%a1-nuevo-concursante-11\/","title":{"rendered":"\u00a1\u00a1 Nuevo Concursante !!"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/oranesado\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-270\" src=\"https:\/\/blogs.ua.es\/concurso10\/files\/2011\/03\/eloranesado.png\" alt=\"\" width=\"300\" height=\"190\" \/><br \/>\n<\/a><\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/oranesado\"><span style=\"color: #e69b29;font-size: medium\"><strong>El Oranesado<br \/>\n<\/strong><\/span><\/a><\/p>\n<p><span style=\"color: #e69b29\"><strong>Creador:<\/strong><\/span>Jose Benito Deleito<br \/>\n<span style=\"color: #e69b29\"><strong>Categor\u00eda:<\/strong><\/span> Tem\u00e1tico<\/p>\n<p><span style=\"color: #e69b29\"><strong>Descripci\u00f3n:<\/strong><\/span><br \/>\nEste blog hace un repaso a la historia de la conquista por parte de<br \/>\nEspa\u00f1a de la plaza de Or\u00e1n, en el norte de \u00c1frica, y de la posterior ocupaci\u00f3n<br \/>\nespa\u00f1ola que se produjo durante aproximadamente dos siglos, en la misma.<\/p>\n<p><span style=\"color: #e69b29\"><strong>Tags:<\/strong><\/span>1509, Or\u00e1n, Tremec\u00e9n,<br \/>\nConquista, Cisneros, Mazalquivir, Montemar y Villaro\u00ebl.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Oranesado Creador:Jose Benito Deleito Categor\u00eda: Tem\u00e1tico Descripci\u00f3n: Este blog hace un repaso a la historia de la conquista por parte de Espa\u00f1a de la plaza de Or\u00e1n, en el norte de \u00c1frica, y de la posterior ocupaci\u00f3n espa\u00f1ola que se produjo durante aproximadamente dos siglos, en la misma. Tags:1509, Or\u00e1n, Tremec\u00e9n, Conquista, Cisneros, Mazalquivir, [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5862],"tags":[53555,53561,5392,53557,3941,53553,53554,53558],"class_list":["post-109","post","type-post","status-publish","format-standard","hentry","category-categoria-tematica","tag-53555","tag-cisneros","tag-conquista","tag-mazalquivir","tag-montemar","tag-oran","tag-tremecen","tag-villaroel"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"predecessor-version":[{"id":132,"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/posts\/109\/revisions\/132"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/concurso10\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}