{"id":280,"date":"2010-12-27T21:41:18","date_gmt":"2010-12-27T19:41:18","guid":{"rendered":"https:\/\/blogs.ua.es\/contrarreforma\/?p=280"},"modified":"2010-12-27T21:41:18","modified_gmt":"2010-12-27T19:41:18","slug":"la-propaganda-de-la-contrarreforma","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/contrarreforma\/2010\/12\/27\/la-propaganda-de-la-contrarreforma\/","title":{"rendered":"La propaganda de la Contrarreforma"},"content":{"rendered":"<p style=\"text-align: justify\">El <strong><em>Barroco<\/em><\/strong> podemos entenderlo como una nueva cultura que impregn\u00f3 los distintos \u00e1mbitos de la vida desde finales del siglo XVI y, sobre todo, durante el XVII, en lo que se refiere al caso espa\u00f1ol. Este movimiento se ha considerado la <strong>manifestaci\u00f3n del <em>esp\u00edritu<\/em> contrarreformista<\/strong>, especialmente relevante en el arte y la reflexi\u00f3n pol\u00edtica -aspectos que ampliaremos en pr\u00f3ximas entradas-.<\/p>\n<p style=\"text-align: justify\">Pero el t\u00e9rmino que nos ocupa se identifica com\u00fanmente con un \u00e1mbito concreto: el arte. Y fue en el caso de Espa\u00f1a, dado su arraigamiento ideol\u00f3gico contrarreformista frente al resto de Europa, donde se extendi\u00f3 ampliamente la sensibilidad art\u00edstica barroca. <strong>La exageraci\u00f3n ornamental<\/strong>, caracter\u00edstica de esa sensibilidad, <strong>sirvi\u00f3 de medio propagand\u00edstico tanto a nivel pol\u00edtico como religioso<\/strong>. As\u00ed, la pol\u00edtica utiliz\u00f3 ese arte exuberante como manifestaci\u00f3n de su poder\u00edo, mientras que la religi\u00f3n lo hizo por dos motivos fundamentales:<\/p>\n<ul>\n<li>Para responder a la actitud (y cr\u00edtica) iconoclasta protestante -idea recogida rotundamente en una frase de Santiago Sebasti\u00e1n en su obra <em>Contrarreforma y barroco<\/em> (p\u00e1g. 145): &#8220;A la Reforma contest\u00f3 la Iglesia multiplicando las im\u00e1genes&#8221;-.<\/li>\n<li>Para cumplir el objetivo -establecido en el <a href=\"http:\/\/es.wikipedia.org\/wiki\/Concilio_de_Trento\" target=\"_blank\">Concilio de Trento<\/a>&#8211; de una eficaz instrucci\u00f3n del pueblo en la renovada moral cat\u00f3lica, con lo que el arte se deb\u00eda caracterizar formalmente por su sencillez y su adecuaci\u00f3n de los personajes a las caracter\u00edsticas de los fieles, fundamentalmente. En definitiva, una f\u00e1cil identificaci\u00f3n y comprensi\u00f3n del pueblo con lo representado.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Con el segundo objetivo se consegu\u00eda, adem\u00e1s de la veneraci\u00f3n -planteada en el Concilio- de ciertos dogmas, como la Inmaculada, la posibilidad de ejecutar buenas obras por imitar ejemplos de actitudes representadas, especialmente de santos -clara respuesta a la &#8220;doctrina de la justificaci\u00f3n por la fe&#8221; de la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Reforma_Protestante\" target=\"_blank\">Reforma protestante<\/a>-. Y es que el recurso al dramatismo de la est\u00e9tica barroca apelaba a los sentimientos del espectador y lo mov\u00eda a actuar.<\/p>\n<p style=\"text-align: justify\">El arte barroco como instrumento pol\u00edtico, antes se\u00f1alado, hay que entenderlo enmarcado en las <a href=\"http:\/\/es.wikipedia.org\/wiki\/Absolutismo\" target=\"_blank\">monarqu\u00edas absolutas<\/a> del momento. A su vez, esta situaci\u00f3n de sumisi\u00f3n del pueblo, as\u00ed como las diversas crisis que experimentaba (demogr\u00e1fica, econ\u00f3mica&#8230;), llevaba a \u00e9ste a buscar consuelo en la religi\u00f3n, cuya expresi\u00f3n m\u00e1s inmediata y humana era el arte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Barroco podemos entenderlo como una nueva cultura que impregn\u00f3 los distintos \u00e1mbitos de la vida desde finales del siglo XVI y, sobre todo, durante el XVII, en lo que se refiere al caso espa\u00f1ol. Este movimiento se ha considerado la manifestaci\u00f3n del esp\u00edritu contrarreformista, especialmente relevante en el arte y la reflexi\u00f3n pol\u00edtica -aspectos [&hellip;]<\/p>\n","protected":false},"author":1780,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1360],"tags":[4551,10602,10595],"class_list":["post-280","post","type-post","status-publish","format-standard","hentry","category-arte","tag-barroco","tag-ideas-conciliares","tag-protestantismo"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/posts\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/users\/1780"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":14,"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/posts\/280\/revisions"}],"predecessor-version":[{"id":294,"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/posts\/280\/revisions\/294"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/media?parent=280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/categories?post=280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/contrarreforma\/wp-json\/wp\/v2\/tags?post=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}