{"id":1469,"date":"2017-10-05T16:21:17","date_gmt":"2017-10-05T14:21:17","guid":{"rendered":"https:\/\/blogs.ua.es\/danielrodriguez\/?p=1469"},"modified":"2017-10-23T13:21:45","modified_gmt":"2017-10-23T11:21:45","slug":"el-aikido-no-es-un-arte-marcial","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/danielrodriguez\/el-aikido-no-es-un-arte-marcial\/","title":{"rendered":"El Aikido no es un arte marcial (al menos como se entiende normalmente)"},"content":{"rendered":"<p>Acabo de ver este v\u00eddeo, cuyo resultado se corresponde muy bien con lo que me pas\u00f3 las pocas veces que he tenido la ocasi\u00f3n de probar con gente de otras artes marciales:<br \/>\n<iframe loading=\"lazy\" title=\"Aikido vs MMA  - REAL SPARRING\" width=\"580\" height=\"326\" src=\"https:\/\/www.youtube.com\/embed\/0KUXTC8g_pk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nY es que el Aikido no est\u00e1 pensado para entrar a un ring a competir y a vencer a otro. Hay otros artes marciales para aprender a hacer eso. El Aikido es una transformaci\u00f3n de una serie de t\u00e9cnicas mortales\/destructivas de Ju-Jitsu en un m\u00e9todo de entrenamiento de la propia reacci\u00f3n ante una agresi\u00f3n. Si lo sacas de su contexto, no funciona.<\/p>\n<p>Es en la vida real, ante un ataque verbal, una agresi\u00f3n (no f\u00edsica) en el trabajo, <em>mobbing<\/em> escolar, etc. donde realmente he podido comprobar la transformaci\u00f3n que mi cerebro ha experimentado en 15 a\u00f1os. Ante alguien entrenado tenemos pocas posibilidades, salvo que tomemos la iniciativa (justo lo contrario del pobre chaval del v\u00eddeo) y podamos conducir el conflicto a un punto de equilibrio y de reconciliaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acabo de ver este v\u00eddeo, cuyo resultado se corresponde muy bien con lo que me pas\u00f3 las pocas veces que he tenido la ocasi\u00f3n de probar con gente de otras artes marciales: Y es que el Aikido no est\u00e1 pensado para entrar a un ring a competir y a vencer a otro. Hay otros artes [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,321],"tags":[],"class_list":["post-1469","post","type-post","status-publish","format-standard","hentry","category-filosofia","category-videos"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/posts\/1469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/comments?post=1469"}],"version-history":[{"count":4,"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/posts\/1469\/revisions"}],"predecessor-version":[{"id":1474,"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/posts\/1469\/revisions\/1474"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/media?parent=1469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/categories?post=1469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/danielrodriguez\/wp-json\/wp\/v2\/tags?post=1469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}