{"id":1544,"date":"2020-02-29T12:47:35","date_gmt":"2020-02-29T12:47:35","guid":{"rendered":"https:\/\/blogs.ua.es\/dimates\/?p=1544"},"modified":"2020-02-29T12:47:35","modified_gmt":"2020-02-29T12:47:35","slug":"solucion-a-un-sistema-muy-grande","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/dimates\/2020\/02\/29\/solucion-a-un-sistema-muy-grande\/","title":{"rendered":"Soluci\u00f3n a un sistema muy grande"},"content":{"rendered":"<pre>Problema 3 de la Fase Local de la LVI OME 2020\r\nSe dirige a una edad de: 16-17 a\u00f1os<\/pre>\n<p>Encuentra todos los posibles valores x, y z, para los que se cumple:<br \/>\nx + y + z = 1<br \/>\nx\u00b2y + y\u00b2z + z\u00b2x = xy\u00b2 + yz\u00b2 + zx\u00b2<br \/>\nx\u00b3 + y\u00b2 + z = y\u00b3 + z\u00b2 + x <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1538\" src=\"https:\/\/blogs.ua.es\/dimates\/files\/2020\/02\/134.Sistemalargo.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/dimates\/files\/2020\/02\/134.Sistemalargo.png 300w, https:\/\/blogs.ua.es\/dimates\/files\/2020\/02\/134.Sistemalargo-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nSoluci\u00f3n:<br \/>\n<!--more--><br \/>\nAparentemente, s\u00f3lo es un sistema de ecuaciones, pero al tener dos de las ecuaciones tercer grado, tanto el m\u00e9todo de sustituci\u00f3n como el de reducci\u00f3n no garantizan buenos resultados.<\/p>\n<p>De hecho, aplicar el m\u00e9todo de sustituci\u00f3n s\u00f3lo ser\u00eda viable si despejamos z, en la primera ecuaci\u00f3n (z = 1 \u2013 x \u2013 y), pero a\u00fan as\u00ed, deber\u00edamos sustituir z\u00b2, de forma que el aspecto de las dos ecuaciones resultantes asusta un poco. Si lo hac\u00e9is, es una v\u00eda que tiene futuro, pero es muy dif\u00edcil. Se debe factorizar los resultados lo m\u00e1s pronto posible, y empezar a solucionar de esa forma.<\/p>\n<p>Otra manera de trabajar ser\u00eda tratar de factorizar desde el inicio las ecuaciones que tenemos. Para empezar, deber\u00edamos recordar que toda expresi\u00f3n de la forma x<sup>n<\/sup> \u2013 y<sup>n<\/sup> tiene un factor x \u2013 y, ya que esta idea aparecer\u00e1 varias veces en la resoluci\u00f3n.<\/p>\n<p>En efecto, sabemos que x\u00b2 \u2013 y\u00b2 = (x \u2013 y)(x + y), pero tambi\u00e9n es sencillo ver que x\u00b3 \u2013 y\u00b3 = (x \u2013 y)(x\u00b2 + xy + y\u00b2), y que x\u2074 \u2013 y\u2074 = (x \u2013 y)(x\u00b3 + x\u00b2y + xy\u00b2 + y\u00b3), aunque s\u00f3lo es necesario llegar a la segunda igualdad en este caso. La identidad es posible generalizarla usando una especie de suma telesc\u00f3pica.<\/p>\n<p>El caso es que tratamos de factorizar la segunda ecuaci\u00f3n por ser la m\u00e1s sim\u00e9trica. La primera ya es de primer grado y la tercera no es sencilla de factorizar.<\/p>\n<p>Para empezar, interesa igualar a cero (x\u00b2y + y\u00b2z + z\u00b2x \u2013 xy\u00b2 \u2013 yz\u00b2 \u2013 zx\u00b2 = 0). Para tener una pista de si es posible factorizar o no, podemos probar con valores concretos. Pero la estrategia es similar.<\/p>\n<p>Si lo ordenamos como si fuera un polinomio, por ejemplo, en z, escribir\u00edamos  z\u00b2x \u2013 yz\u00b2+ y\u00b2z \u2013 zx\u00b2 + x\u00b2y \u2013 xy\u00b2 = 0, donde observamos que tenemos tres coeficientes, (x \u2013 y)z\u00b2+ (y\u00b2 \u2013 x\u00b2)z + x\u00b2y \u2013 xy\u00b2 = 0. Podemos observar que el factor (x \u2013 y) aparece en todos los coeficientes, es decir, (x \u2013 y)z\u00b2+ (y \u2013 x)(x + y)z + xy(x \u2013 y) = 0. Es decir, que se puede sacar factor com\u00fan del polinomio (x \u2013 y)(z\u00b2 \u2013 (x + y)z + xy). Observa que puesto que y \u2013 x = -(x \u2013 y), al sacar este \u00faltimo factor aparece un signo en el segundo sumando.<\/p>\n<p>Para encontrar cu\u00e1les son las ra\u00edces con las que factorizar, podr\u00edamos aplicar la f\u00f3rmula de la ecuaci\u00f3n de segundo grado, donde el coeficiente de la z\u00b2 es ahora 1, el de la z es -(x + y) y el t\u00e9rmino independiente xy, de forma que los valores de z ser\u00edan (x + y &plusmn; ra\u00edz(x\u00b2 + 2xy + y\u00b2 \u2013 4xy))\/2, pero casualmente el contenido de la ra\u00edz se puede simplificar y es un cuadrado perfecto, el de x \u2013 y, as\u00ed que las ra\u00edces quedar\u00edan (x + y &plusmn; ra\u00edz(x\u00b2 \u2013 2xy + y\u00b2))\/2 = (x + y &plusmn; (x \u2013 y))\/2. Si optamos por la que suma, tenemos que la z vale x y la z que corresponde a la resta es, curiosamente, y.<\/p>\n<p>As\u00ed que la factorizaci\u00f3n es (x \u2013 y)(z \u2013 x)(z \u2013 y) = 0, que nos permite tomar ya una simplificaci\u00f3n importante. El producto de tres n\u00fameros reales es cero si y s\u00f3lo si alguno de los tres lo es, de forma, que en las soluciones, o bien x = y, o bien y = z, o bien x = z. En esos tres supuestos, la ecuaci\u00f3n central se cumple (y \u00fanicamente en uno de esos casos). Veamos qu\u00e9 significa para las otras dos.<\/p>\n<p>En el caso de que x = y, la primera ecuaci\u00f3n ser\u00e1 2x + z = 1, es decir, z = 1 \u2013 2x. En ese caso, la tercera ecuaci\u00f3n queda x\u00b3 + x\u00b2 + z = x\u00b3 + z\u00b2 + x, es decir,  x\u00b2 + z = z\u00b2 + x, y sustituyendo, x\u00b2 + 1 \u2013 2x = 1 \u2013 4x + 4x\u00b2 + x, que se transforma en 0 = 3x\u00b2 \u2013 x. Eso proporciona la soluci\u00f3n x = 0, y = 0, z = 1, y la soluci\u00f3n x = 1\/3, y = 1\/3, z = 1\/3.<\/p>\n<p>En el caso de que x = z, la primera ecuaci\u00f3n ser\u00e1 2x + y = 1, es decir, y = 1 \u2013 2x. En ese caso, la tercera ecuaci\u00f3n queda x\u00b3 + y\u00b2 + x = y\u00b3 + x\u00b2 + x , es decir,  x\u00b3 + y\u00b2 = y\u00b3 + x\u00b2. En este caso, tenemos que x\u00b3 \u2013 y\u00b3 = x\u00b2 \u2013 y\u00b2, es decir, (x \u2013 y)(x\u00b2 + xy + y\u00b2) = (x \u2013 y)(x + y). Puesto que el caso en que x = y ya ha sido visto, podemos suponer que x no es igual a y, y dividir por ese factor, con lo que la igualdad queda x\u00b2 + xy + y\u00b2 = x + y. Sustituyendo, x\u00b2 + x \u2013 2x\u00b2 + 1 \u2013 4x + 4x\u00b2 = x + 1 \u2013 2x, que se transforma en 3x\u00b2 \u2013 2x = 0. Eso proporciona la soluci\u00f3n x = 0, y = 1, z = 0, y la soluci\u00f3n x = 2\/3, y = -1\/3, z = 2\/3.<\/p>\n<p>En el caso de que z = y, la primera ecuaci\u00f3n ser\u00e1 x + 2y = 1, es decir, x = 1 \u2013 2y. En ese caso, la tercera ecuaci\u00f3n queda x\u00b3 + y\u00b2 + y = y\u00b3 + y\u00b2 + x , es decir,  x\u00b3 + y = y\u00b3 + x. En este caso, tenemos que x\u00b3 \u2013 y\u00b3 = x \u2013 y, es decir, (x \u2013 y)(x\u00b2 + xy + y\u00b2) = x \u2013 y. Puesto que el caso en que x = y ya ha sido visto, podemos suponer que x no es igual a y, y dividir por ese factor, con lo que la igualdad queda x\u00b2 + xy + y\u00b2 = 1. Sustituyendo, 1 \u2013 4y + 4y\u00b2 + y \u2013 2y\u00b2 +y\u00b2 = 1, que se transforma en 3y\u00b2 \u2013 3y = 0. Eso proporciona la soluci\u00f3n y = 0, x = 1, z = 0, y la soluci\u00f3n y = 1, x = -1, z = 1.<\/p>\n<p>As\u00ed, las seis \u00fanicas soluciones ser\u00edan (0, 0, 1), (1\/3, 1\/3, 1\/3), (0, 1, 0), (2\/3, -1\/3, 2\/3), (1, 0, 0), y (-1, 1, 1).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Problema 3 de la Fase Local de la LVI OME 2020 Se dirige a una edad de: 16-17 a\u00f1os Encuentra todos los posibles valores x, y z, para los que se cumple: x + y + z = 1 x\u00b2y + y\u00b2z + z\u00b2x = xy\u00b2 + yz\u00b2 + zx\u00b2 x\u00b3 + y\u00b2 + z [&hellip;]<\/p>\n","protected":false},"author":4267,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242021,1738,2849,3303],"tags":[],"class_list":["post-1544","post","type-post","status-publish","format-standard","hentry","category-olimpiada-matematica-espanola","category-olimpiadas","category-problemas","category-soluciones"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/1544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/users\/4267"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/comments?post=1544"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/1544\/revisions"}],"predecessor-version":[{"id":1547,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/1544\/revisions\/1547"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/media?parent=1544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/categories?post=1544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/tags?post=1544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}