{"id":2448,"date":"2022-05-08T06:26:15","date_gmt":"2022-05-08T06:26:15","guid":{"rendered":"https:\/\/blogs.ua.es\/dimates\/?p=2448"},"modified":"2022-05-08T06:26:20","modified_gmt":"2022-05-08T06:26:20","slug":"solucion-a-un-sistema-con-potencias","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/dimates\/2022\/05\/08\/solucion-a-un-sistema-con-potencias\/","title":{"rendered":"Soluci\u00f3n a un sistema con potencias"},"content":{"rendered":"<p>Problema 3 de la Fase Local de la Olimpiada Espa\u00f1ola de Matem\u00e1ticas 2022 (viernes tarde)<br \/>\nSe dirige a una edad de: 16-17 a\u00f1os<br \/>\nHallar todas las ternas de n\u00fameros reales (a, b, c) que cumplan el sistema:<br \/>\na + b + c = 3<br \/>\n2<sup>a<\/sup> + 2<sup>b<\/sup> + 2<sup>c<\/sup> = 7<br \/>\n2<sup>-a<\/sup> + 2<sup>-b<\/sup> = \u00be<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2446\" src=\"https:\/\/blogs.ua.es\/dimates\/files\/2022\/05\/245.sistema.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/dimates\/files\/2022\/05\/245.sistema.png 300w, https:\/\/blogs.ua.es\/dimates\/files\/2022\/05\/245.sistema-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nSoluci\u00f3n:<br \/>\n<!--more--><br \/>\nLo primero que debemos observar es que hay una funci\u00f3n no polin\u00f3mica implicada, la potencia de base 2. Sin embargo, hay ecuaciones que no lo tienen. Un primer avance supone escribir la ecuaci\u00f3n a + b + c = 3 de forma que contenga potencias de 2 de exponentes a, b y c.<\/p>\n<p>Aprovechamos que 2<sup>a + b + c<\/sup> = 2<sup>a<\/sup>\u00b72<sup>b<\/sup>\u00b72<sup>c<\/sup> = 2\u00b3 = 8 para escribir la primera ecuaci\u00f3n con potencias de base 2. Y, evidentemente, la \u00faltima es muy f\u00e1cil expresarla en forma de potencias de base 2 y exponentes de a y b.<\/p>\n<p>2<sup>a<\/sup>\u00b72<sup>b<\/sup>\u00b72<sup>c<\/sup> = 8<br \/>\n2<sup>a<\/sup> + 2<sup>b<\/sup> + 2<sup>c<\/sup> = 7<br \/>\n1\/2<sup>a<\/sup> + 1\/2<sup>b<\/sup> = \u00be<\/p>\n<p>En un segundo paso, cambiamos la funci\u00f3n 2<sup>a<\/sup> por una nueva variable x, 2<sup>b<\/sup> por y y 2<sup>c<\/sup> por z.<\/p>\n<p>xyz = 8<br \/>\nx + y + z = 7<br \/>\n1\/x + 1\/y = \u00be<\/p>\n<p>Ahora es un sistema m\u00e1s similar a los que habitualmente nos enfrentamos, con polinomios de grado 3, 1 y 2 (si elimin\u00e1semos denominadores).<\/p>\n<p>xyz = 8<br \/>\nx + y + z = 7<br \/>\n(x + y)\/(xy) = \u00be<\/p>\n<p>Sin embargo, podemos aprovechar la simetr\u00eda de las dos primeras ecuaciones, ya que xy = 8\/z y x + y = 7 \u2013 z, por lo que podemos escribir la \u00faltima ecuaci\u00f3n con ayuda de la \u00fanica variable z:<\/p>\n<p>(7 \u2013 z)\/(8\/z) = \u00be<\/p>\n<p>Simplificar las fracciones que componen la fracci\u00f3n, multiplicando numerador y denominador por z, deja la expresi\u00f3n:<\/p>\n<p>z(7 \u2013 z)\/8 = \u00be<\/p>\n<p>Y multiplicando ambos extremos de la igualdad por 8, nos deja una ecuaci\u00f3n de segundo grado:<\/p>\n<p>z(7 \u2013 z) = 6<\/p>\n<p>Que es equivalente a<\/p>\n<p>0 = z\u00b2 \u2013 7z + 6<\/p>\n<p>Evidentemente, aplicando la conocida f\u00f3rmula para ecuaciones de segundo grado, nos deja dos soluciones, 6 y 1, que podemos estudiar por separado:<\/p>\n<p>Si z = 6, tenemos que las variables x e y deben cumplir<\/p>\n<p>xy = 4\/3<br \/>\nx + y = 1<\/p>\n<p>Despejando y = 1 \u2013 x, y sustituyendo, nos lleva a la ecuaci\u00f3n 3x\u00b2 \u2013 3x + 4 = 0, que no tiene soluciones reales (ya que su discriminante, la expresi\u00f3n que habitualmente encontramos dentro de la ra\u00edz cuadrada, es negativo), por lo que no da lugar a ninguna soluci\u00f3n para el sistema.<\/p>\n<p>Sin embargo, si z = 1 tenemos:<\/p>\n<p>xy = 8<br \/>\nx + y = 6<\/p>\n<p>De nuevo, despejando y = 6 \u2013 x y sustituyendo en la primera ecuaci\u00f3n, nos lleva a x\u00b2 \u2013 6x + 8 = 0, que da lugar a dos soluciones, x = 2 (y por tanto, y = 4), y x = 4, con lo que y = 2.<\/p>\n<p>Por lo tanto, s\u00f3lo tendr\u00edamos dos soluciones (dos ternas, por tanto):<\/p>\n<p>x = 2, y = 4, z = 1, con lo que tenemos la terna (1, 2, 0), y x = 4, y = 2, z = 1, que da lugar a la terna (2, 1, 0).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Problema 3 de la Fase Local de la Olimpiada Espa\u00f1ola de Matem\u00e1ticas 2022 (viernes tarde) Se dirige a una edad de: 16-17 a\u00f1os Hallar todas las ternas de n\u00fameros reales (a, b, c) que cumplan el sistema: a + b + c = 3 2a + 2b + 2c = 7 2-a + 2-b = [&hellip;]<\/p>\n","protected":false},"author":4267,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242021,1738,2849,3303],"tags":[],"class_list":["post-2448","post","type-post","status-publish","format-standard","hentry","category-olimpiada-matematica-espanola","category-olimpiadas","category-problemas","category-soluciones"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/2448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/users\/4267"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/comments?post=2448"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/2448\/revisions"}],"predecessor-version":[{"id":2450,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/2448\/revisions\/2450"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/media?parent=2448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/categories?post=2448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/tags?post=2448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}