{"id":2868,"date":"2023-05-27T06:22:48","date_gmt":"2023-05-27T06:22:48","guid":{"rendered":"https:\/\/blogs.ua.es\/dimates\/?p=2868"},"modified":"2023-07-01T17:06:53","modified_gmt":"2023-07-01T17:06:53","slug":"solucion-a-cartas-y-maravillas","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/dimates\/2023\/05\/27\/solucion-a-cartas-y-maravillas\/","title":{"rendered":"Soluci\u00f3n a cartas y maravillas"},"content":{"rendered":"<pre>Problema 3 del nivel B de la Fase Comarcal de la Olimpiada de la Comunidad Valenciana\r\nSe dirige a una edad de: 14-15 a\u00f1os<\/pre>\n<p>Alicia, el Conejo Blanco y el Sombrerero Loco disputan un juego con tres cartas.<\/p>\n<p>Cada una de estas cartas lleva dibujado un n\u00famero entero positivo distinto.<\/p>\n<p>En cada partida, las tres cartas se reparten al azar y cada jugador se anota tantos puntos como indica la carta que le ha tocado.<br \/>\nDespu\u00e9s de jugar al menos dos partidas, Alicia tiene 20 puntos, el Conejo Blanco 10 puntos y el Sombrerero Loco 9.<\/p>\n<p>Adem\u00e1s, sabemos que en la \u00faltima partida, el Conejo Blanco ha obtenido la carta con mayor puntuaci\u00f3n posible de las tres.<\/p>\n<p>\u00bfQu\u00e9 jugador obtuvo la carta de valor intermedio en la primera partida?<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2866\" src=\"https:\/\/blogs.ua.es\/dimates\/files\/2023\/05\/299.Cartas.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.ua.es\/dimates\/files\/2023\/05\/299.Cartas.png 300w, https:\/\/blogs.ua.es\/dimates\/files\/2023\/05\/299.Cartas-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nSoluci\u00f3n:<br \/>\n<!--more--><br \/>\nPuesto que juegan 3 rondas y en total reciben 20 + 10 + 9 = 39 puntos, las cartas suman 13 puntos en total.<\/p>\n<p>Est\u00e1 claro que Alicia no recibe 3 veces la m\u00e1s valiosa, puesto que su total no es un m\u00faltiplo de 3.<\/p>\n<p>Como m\u00e1ximo, la carta m\u00e1s valiosa debe tener un 9, pero en ese caso, una de las otras 2 debe ser un 2, para que Alicia tenga 20. Eso no es posible, porque habr\u00eda 2 cartas iguales.<\/p>\n<p>Si la carta m\u00e1s valiosa tiene un 8, las otras dos suman 5, podr\u00edan ser 4 y 1, para que Alicia sumara 20. y en ese caso, el Conejo Blanco podr\u00eda sumar 10 con 8 + 1 + 1, y el resto se las apuntar\u00eda el Sombrero Loco.<\/p>\n<p>Si la carta m\u00e1s valiosa es un 7, las otras dos sumar\u00edan 6, y en ese caso es inalcanzable el total de 20 puntos para Alicia.<\/p>\n<p>Por lo tanto la \u00fanica opci\u00f3n es que las cartas sean 8, 4 y 1.<\/p>\n<p>Puesto que en la \u00faltima partida el Conejo Blanco obtuvo un 8, Alicia debi\u00f3 de obtener en esa partida un 4, pues fue la \u00fanica vez que no consigui\u00f3 un 8, y por eso el resto de 4 (el valor intermedio) los obtuvo el Sombrero Loco.<\/p>\n<p>As\u00ed que la respuesta correcta es el Sombrero Loco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Problema 3 del nivel B de la Fase Comarcal de la Olimpiada de la Comunidad Valenciana Se dirige a una edad de: 14-15 a\u00f1os Alicia, el Conejo Blanco y el Sombrerero Loco disputan un juego con tres cartas. Cada una de estas cartas lleva dibujado un n\u00famero entero positivo distinto. En cada partida, las tres [&hellip;]<\/p>\n","protected":false},"author":4267,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2242020,1738,2849,3303],"tags":[],"class_list":["post-2868","post","type-post","status-publish","format-standard","hentry","category-olimpiada-de-la-comunidad-valenciana","category-olimpiadas","category-problemas","category-soluciones"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/2868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/users\/4267"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/comments?post=2868"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/2868\/revisions"}],"predecessor-version":[{"id":2922,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/posts\/2868\/revisions\/2922"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/media?parent=2868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/categories?post=2868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/dimates\/wp-json\/wp\/v2\/tags?post=2868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}