{"id":1163,"date":"2008-07-10T14:46:43","date_gmt":"2008-07-10T12:46:43","guid":{"rendered":"https:\/\/blogs.ua.es\/diversitatfuncional\/?p=1163"},"modified":"2008-07-10T14:46:43","modified_gmt":"2008-07-10T12:46:43","slug":"navegando-navegando-me-encontre-con-este-fango","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/diversitatfuncional\/2008\/07\/10\/navegando-navegando-me-encontre-con-este-fango\/","title":{"rendered":"Navegando, navegando me encontr\u00e9 con este fango&#8230;"},"content":{"rendered":"<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><a href=\"http:\/\/reovirtual.blogspot.com\/2008_04_01_archive.html\" target=\" blank\"><span style=\"font-weight: bold;font-size:180%\">Maligno Moure<\/span><\/a><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<div style=\"text-align: justify\"><span style=\"font-weight: bold;font-size:100%\">\u201c\u00bfYooooooo? Es que&#8230; mmmmm&#8230; ese me dijo&#8230; \u201c <\/span><span style=\"font-weight: bold;font-size:100%\">Con estos argumentos se defendi\u00f3 el presidente de la Fundaci\u00f3n San Rosendo, el sacerdote Benigno Moure, el pasado 2 de abril en la Audiencia Provincial de Ourense. El padre Benigno tuvo que declarar ante el juez por delito continuado de apropiaci\u00f3n indebida, estafa y falsedad en documento p\u00fablico y privado, y le sigui\u00f3 el segundo imputado, el notario de Ourense Alejo Calatayud tras la denuncia del sobrino de una anciana ingresada en un geri\u00e1trico de la Fundaci\u00f3n San Rosendo, que los acus\u00f3 de traspasar a esta instituci\u00f3n casi 600.000 \u20ac de las cuentas bancarias de su t\u00eda y unas 60 propiedades.<\/span><\/div>\n<div style=\"text-align: justify\"><span style=\"color: #000000\">.<\/span>\n<\/div>\n<div style=\"text-align: justify\">\n<div style=\"text-align: center\"><a href=\"http:\/\/bp1.blogger.com\/_Ti_EM1H5nCo\/SHYBPMM5pbI\/AAAAAAAADus\/q_bBMmIkIck\/s1600-h\/curaynotario.jpg\"><img decoding=\"async\" src=\"http:\/\/bp1.blogger.com\/_Ti_EM1H5nCo\/SHYBPMM5pbI\/AAAAAAAADus\/q_bBMmIkIck\/s400\/curaynotario.jpg\" border=\"0\" alt=\"\" \/><\/a><span style=\"font-weight: bold;font-size:78%\"><br \/>\nEl cura y el notario en el banquillo de los acusados.<\/span><span style=\"font-weight: bold;font-size:78%\"><br \/>\nSe trata sin duda de una conspiraci\u00f3n comunista!<\/span><\/div>\n<div style=\"text-align: center\"><span style=\"color: #000000\">.<\/span>\n<\/div>\n<p><span style=\"font-weight: bold;font-size:130%\">El Imperio<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Benigno Moure es \u201cel Amo\u201dde la Fundaci\u00f3n San Rosendo. Esta entidad \u201csin \u00e1nimo de lucro\u201d cuenta con centros geri\u00e1tricos para v\u00e1lidos, residencias asistidas, centros para discapacitados, especializados, mixtos, etc. En total 54 centros asistenciales distribuidos por toda Galicia. Adem\u00e1s cuenta con 4 hoteles y 3 balnearios del Grupo Caldaria, administrados \u00fanicamente por el cl\u00e9rigo de desafortunado nombre. La Fundaci\u00f3n recibe cuantiosas subvenciones p\u00fablicas, donaciones privadas a tutipl\u00e9n, conciertos de plazas de la Xunta y este a\u00f1o cuenta con un presupuesto de 43 millones&#8230; \u00a1\u00a1de euros!!. El hecho de ser una instituci\u00f3n ben\u00e9fico-asistencial dedicada a la lucha contra la pobreza y la marginaci\u00f3n (seg\u00fan su p\u00e1gina web) no le ha impedido demostrar tambi\u00e9n gran habilidad en el campo de la especulaci\u00f3n urban\u00edstica. Desde luego, gracias a la Fundaci\u00f3n, Moure y sus adl\u00e1teres no pasan hambre.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">\u201cYo no rob\u00e9 nada, fue una cesi\u00f3n\u201d<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">En 1998 Mar\u00eda V\u00e1zquez ingres\u00f3 en la residencia Os Gozos, perteneciente a la Fundaci\u00f3n San Rosendo, en Pereiro de Aguiar. Entonces ya fue diagnosticada por los m\u00e9dicos de la instituci\u00f3n con una \u201calteraci\u00f3n de memoria y razonamiento, junto a demencia senil incipiente\u201d. Despu\u00e9s de otro examen en 2001 el forense escribi\u00f3: \u201cLa informada no puede realizar los actos propios de su autogobierno y del gobierno de sus bienes\u201d. Y en julio de ese mismo a\u00f1o el juez declar\u00f3 incapacitada a la anciana. Fue entonces cuando el padre Benigno, sin poder soportar la tentaci\u00f3n, hizo caso omiso del 7\u00ba mandamiento y organiz\u00f3 el teatrillo para hacerse con el patrimonio de Mar\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Moure tiene la conciencia tranquila y sigue afirmando que Mar\u00eda \u201cestaba en perfecto estado y lo don\u00f3 todo voluntariamente\u201d. Seg\u00fan la declaraci\u00f3n del notario Alejo Calatayud, \u201cla anciana mov\u00eda la cabeza para asentir en respuesta a mis preguntas, por lo que a mi parecer ella entend\u00eda lo que le estaba diciendo\u201d. Finalmente, a pesar de la silla de ruedas, la demencia senil, el parkinson, la artrosis, y con la ayuda de dos cuidadoras de la residencia, consiguieron estampar la huella digital de la anciana en el documento que hac\u00eda a Benigno Moure \u201cdue\u00f1o y titular de las cuentas\u201d.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">El despistado<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Al por entonces director de la sucursal de Banesto en O Carballi\u00f1o, Jos\u00e9 Luis de la Iglesia Santos, \u201cno le llam\u00f3 la atenci\u00f3n\u201d que Benigno Moure traspasase en dos d\u00edas 451.000 euros de las cuentas de la mujer a otra de la Fundaci\u00f3n. Este hombre, que estuvo presente en la firma de los documentos de las autorizaciones, declar\u00f3 que la se\u00f1ora\u201d afirmaba con la cabeza, aunque en ning\u00fan momento habl\u00f3 de donar nada\u201d. A su vez, s\u00ed explic\u00f3 que las correcciones visibles en los papeles bancarios hab\u00edan sido hechas por \u00e9l, \u201cya que me equivoqu\u00e9 en algunos n\u00fameros. Por norma general, en estos casos rompo el papel y hago otro, pero como los cubr\u00ed en el banco y estaban firmados ya por Mar\u00eda V\u00e1zquez, los correg\u00ed para no tener que volver al geri\u00e1trico a firmar otros\u201d.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Si ustedes siguen creyendo en la justicia institucional sepan que este individuo declar\u00f3 como testigo y no como imputado.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">Los Hermanos Marx en el juzgado<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">El se\u00f1or banquero no fue el \u00fanico desfachatado del proceso. Aqu\u00ed van algunas de las declaraciones que se oyeron el 2 y 3 de abril en la Audiencia Provincial de Ourense.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">&#8211; El notario imputado: \u201cDoy fe de lo que me cuentan, no de la veracidad de lo que me cuentan\u201d.(El Pa\u00eds, ed. Galicia, 03\/04\/2008, p.3)<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">&#8211; El posterior comprador de las propiedades: \u201cNo me extra\u00f1\u00f3 que la Fundaci\u00f3n hiciese el trato, a pesar de que en la escritura que firm\u00e9 para la compra estuviese Mar\u00eda V\u00e1zquez como propietaria\u201d. (faro de vigo. 03\/04\/2008)<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">&#8211; Benigno Moure: \u201cLos pisos, las fincas y el dinero de las cuentas de Mar\u00eda fueron traspasados a la Fundaci\u00f3n, pero yo no me qued\u00e9 con nada\u201d. (El Pa\u00eds, ed. Galicia, 03\/04\/2008, p.3)<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">&#8211; Benigno Moure: \u201cSiempre hice las cosas a trav\u00e9s del banco y a trav\u00e9s de los directores del banco, de los que tengo que fiarme\u201d. (Canarias 7. 02\/04\/2008)<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">&#8211; Benigno Moure: \u201cEstoy muy tranquilo. Siempre se hizo la voluntad de la se\u00f1ora. Me puso como titular de sus cuentas por si hac\u00eda falta algo, pero ella segu\u00eda en la cuenta igual\u201d. (faro de vigo. 03\/04\/2008)<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">La sentencia<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">S\u00f3lo queda que el juez dicte sentencia sobre el cura, el notario y, lo que m\u00e1s preocupa a acusados y acusadores, la herencia de la se\u00f1ora Mar\u00eda. No se hagan muchas ilusiones. El padre benigno es un tirano \u2018de prestigio\u2019. El t\u00edpico illuminati regional agente del Octogonus, un dinosaurio neofeudal con amigos en el oscuro submundo de los pistoleros. \u00bfQui\u00e9n les dice a ustedes que el juez encargado de este caso es menos despistado que el notario o el banquero? La casa es grande, y donde comen dos comen tres. F\u00edjense en el poder que tiene este hombre que, en 1990, un centenar de trabajadores y el secretario de la CIG en Ourense, Etelvino Blanco, lo demandaron por malos tratos a los residentes de sus geri\u00e1tricos y el juzgado orensano no s\u00f3lo no admiti\u00f3 a tr\u00e1mite la denuncia sino que acab\u00f3 condenado el sindicalista a prisi\u00f3n y al pago de un mill\u00f3n de pesetas.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><span style=\"font-weight: bold;font-size:100%\"><\/span><br \/>\n<span style=\"font-weight: bold;font-size:100%\">De todas maneras estaremos pendientes de la Audiencia provincial.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">Por nuestra parte declaramos:<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Culpable a Mar\u00eda V\u00e1zquez por acumular tanto patrimonio.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Culpable al sobrino acusador de Mar\u00eda V\u00e1zquez por miserable aprovechado que s\u00f3lo se preocup\u00f3 por la herencia y nunca de su t\u00eda.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Culpable al notario, al banquero y otros par\u00e1sitos, c\u00f3mplices del r\u00e9gimen de terror de Moure.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:100%\">Culpable al maligno Moure por practicar el fascismo en unas tierras tan bellas, por ladr\u00f3n, por tirano con alzacuellos, por explotador, por peligroso y por exigir a sus siervos ir arreglados decorosamente e ir a misa cada vez que visita una de sus residencias, mientras el bellaco se lucra hasta el infinito con \u2018la lucha contra la pobreza\u2019 y con el negocio de la dependencia.<\/span><\/p>\n<p><span style=\"color: #000000\">.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>. Maligno Moure . \u201c\u00bfYooooooo? Es que&#8230; mmmmm&#8230; ese me dijo&#8230; \u201c Con estos argumentos se defendi\u00f3 el presidente de la Fundaci\u00f3n San Rosendo, el sacerdote Benigno Moure, el pasado 2 de abril en la Audiencia Provincial de Ourense. El padre Benigno tuvo que declarar ante el juez por delito continuado de apropiaci\u00f3n indebida, estafa [&hellip;]<\/p>\n","protected":false},"author":791,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1163","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/users\/791"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/1163\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/media?parent=1163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/categories?post=1163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/tags?post=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}