{"id":2206,"date":"2009-10-26T19:11:24","date_gmt":"2009-10-26T17:11:24","guid":{"rendered":"https:\/\/blogs.ua.es\/diversitatfuncional\/2009\/10\/26\/reportaje-da-del-dao-cerebral-adquirido\/"},"modified":"2009-10-26T19:11:24","modified_gmt":"2009-10-26T17:11:24","slug":"reportaje-da-del-dao-cerebral-adquirido","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/diversitatfuncional\/2009\/10\/26\/reportaje-da-del-dao-cerebral-adquirido\/","title":{"rendered":"REPORTAJE. D&Iacute;A DEL DA&Ntilde;O CEREBRAL ADQUIRIDO"},"content":{"rendered":"<p>&#160; <\/p>\n<p>&#160;<\/p>\n<p><a href=\"http:\/\/www.diarioinformacion.com\/\" target=\" blank\">Informaci\u00f3n.es<\/a> \u00bb <a href=\"http:\/\/www.diarioinformacion.com\/alicante\/\" target=\" blank\"><b>Alicante<\/b><\/a><\/p>\n<p>&#160;<\/p>\n<h2>Para evitar secuelas<\/h2>\n<p>&#160;<\/p>\n<h1><a href=\"https:\/\/blogs.ua.es\/diversitatfuncional\/files\/2009\/10\/ATT00069.jpg\" target=\" blank\"><img loading=\"lazy\" decoding=\"async\" style=\"border-top-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-right-width: 0px\" height=\"192\" alt=\"foto abstracta\" src=\"https:\/\/blogs.ua.es\/diversitatfuncional\/files\/2009\/10\/ATT00069_thumb.jpg\" width=\"244\" border=\"0\" \/><\/a> <\/h1>\n<h1>Sanidad estudia concertar con el Centro de Da\u00f1o Cerebral Sobrevenido de Alicante 40 plazas para pacientes sub-agudos.<\/h1>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p><a href=\"http:\/\/www.diarioinformacion.com\/\" target=\" blank\"><img decoding=\"async\" style=\"margin: 0px 0px 10px 10px\" alt=\"Profesionales del centro Casaverde trabajan las habilidades de los pacientes\" src=\"http:\/\/fotos.diarioinformacion.com\/fotos\/noticias\/318x200\/2009-11-02_IMG_2009-10-26_01.21.15__L1301.jpg.jpg\" align=\"right\" border=\"0\" \/><\/a> <\/p>\n<\/p>\n<p align=\"right\">Profesionales del centro Casaverde trabajan las habilidades de los pacientes <\/p>\n<p align=\"right\">RAFA ARJONES<\/p>\n<p><b>\u00c1FRICA PRADO <\/b><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">La Conselleria de Sanidad prev\u00e9 concertar 40 plazas con el Centro de Da\u00f1o Cerebral Sobrevenido de Alicante para el tratamiento y la rehabilitaci\u00f3n de pacientes en fase sub-aguda, una vez estos obtienen el alta hospitalaria tras ser atendidos de un episodio de da\u00f1o cerebral.<\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">Este centro, perteneciente al grupo Casaverde y ubicado en Mutxamel, funciona desde 2001 como una unidad que ahora ha sido transformada en centro monogr\u00e1fico dedicado al da\u00f1o cerebral adquirido (DCA), cuyo d\u00eda mundial se celebra hoy. El DCA es una lesi\u00f3n s\u00fabita en el cerebro que produce diversas secuelas de car\u00e1cter f\u00edsico, ps\u00edquico o sensorial. Entre las causas m\u00e1s comunes figuran los traumatismos craneoencef\u00e1licos y los ictus o accidentes cerebrovasculares, adem\u00e1s de tumores cerebrales o causas de origen infeccioso.      <br \/>Seg\u00fan datos de la Federaci\u00f3n Espa\u00f1ola de Da\u00f1o Cerebral, unas 300.000 personas padecen este tipo de lesiones, de los que buena parte de ellos se producen por accidentes de tr\u00e1fico.<\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">El centro de Casaverde, con 100 camas y 40 plazas de centro de d\u00eda, lleva siete a\u00f1os atendiendo a pacientes con estas lesiones procedentes de toda Espa\u00f1a, ya que apenas existen instalaciones de este tipo y el Ministerio de Sanidad tiene concertadas 40 plazas para la rehabilitaci\u00f3n y reinserci\u00f3n de pacientes de larga estancia, cuya estancia media oscila entre 7 y 15 meses y donde el principal objetivo es trabajar en las habilidades preservadas.<\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">El presidente de Casaverde, Alberto Gim\u00e9nez, se\u00f1ala que el centro prev\u00e9 formalizar en breve plazo un concierto con la Conselleria de Sanidad para asistir en la fase previa a pacientes de la Comunidad Valenciana, una vez atendida la urgencia vital, con el fin de reducir en lo posible las secuelas producidas por un da\u00f1o cerebral. <\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">&quot;En este caso, la estancia es de 3 \u00f3 4 meses de media, con un tiempo m\u00e1ximo de 6 u 8 meses&quot;, indica Gim\u00e9nez, que a\u00f1ade que &quot;trabajamos muy intensamente para reducir o minimizar sus d\u00e9ficits funcionales, motores, de memoria, del habla, e incluso trastornos de conducta que en ocasiones se producen&quot;.<\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">El centro cuenta con un equipo multidisciplinar de 90 profesionales sanitarios, que incluye neur\u00f3logo, neuropsic\u00f3logos, logopedas, fisioterapeutas y terapeutas ocupacionales. La unidad de rehabilitaci\u00f3n, donde la mitad de los pacientes proviene de la provincia y la otra, de otros puntos del pa\u00eds, tiene en lista de espera a una veintena de personas.<\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">El 50 por ciento de los pacientes atendidos han sufrido un ictus, el equivalente cerebral a un ataque al coraz\u00f3n, y el porcentaje restante ha sufrido un accidente, por lo que en ocasiones las edades corresponden a gente joven.<\/font><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"3\">El responsable del centro destaca a su vez la importancia de logar en la medida de lo posible la vida aut\u00f3noma del paciente afectado por da\u00f1o cerebral y para ello, subraya, &quot;es necesario en muchas ocasiones realizar terapia con los familiares porque estas situaciones son un drama y a veces el familiar puede frenar el tratamiento rehabilitador&quot;.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#160; &#160; Informaci\u00f3n.es \u00bb Alicante &#160; Para evitar secuelas &#160; Sanidad estudia concertar con el Centro de Da\u00f1o Cerebral Sobrevenido de Alicante 40 plazas para pacientes sub-agudos. &#160; &#160; Profesionales del centro Casaverde trabajan las habilidades de los pacientes RAFA ARJONES \u00c1FRICA PRADO La Conselleria de Sanidad prev\u00e9 concertar 40 plazas con el Centro de [&hellip;]<\/p>\n","protected":false},"author":791,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5725,306,1444],"tags":[],"class_list":["post-2206","post","type-post","status-publish","format-standard","hentry","category-diversidad-funcional","category-noticias","category-vida-independiente"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/users\/791"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/2206\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/media?parent=2206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/categories?post=2206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/tags?post=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}