{"id":2219,"date":"2009-10-27T20:43:02","date_gmt":"2009-10-27T18:43:02","guid":{"rendered":"https:\/\/blogs.ua.es\/diversitatfuncional\/2009\/10\/27\/anglica-such-donde-dijo-digo-dijo-diego\/"},"modified":"2009-10-27T20:43:02","modified_gmt":"2009-10-27T18:43:02","slug":"anglica-such-donde-dijo-digo-dijo-diego","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/diversitatfuncional\/2009\/10\/27\/anglica-such-donde-dijo-digo-dijo-diego\/","title":{"rendered":"Ang&eacute;lica Such: &laquo;Donde dijo digo, dijo Diego&raquo;"},"content":{"rendered":"<p>&#160;<\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/diversitatfuncional\/files\/2009\/10\/clip_image0021.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"border-top-width: 0px;border-left-width: 0px;border-bottom-width: 0px;margin: 0px;border-right-width: 0px\" height=\"215\" alt=\"clip_image002\" hspace=\"12\" src=\"https:\/\/blogs.ua.es\/diversitatfuncional\/files\/2009\/10\/clip_image002_thumb1.jpg\" width=\"181\" align=\"left\" border=\"0\" \/><\/a><\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<h1>COMUNICADO DE PRENSA<\/h1>\n<h1>VALENCIA 27\/10\/09<\/h1>\n<p>&#160;<\/p>\n<p>&#160;<\/p>\n<h3 align=\"justify\">Las <b><u>\u201cPlataformas de la Comunidad Valenciana en Defensa de la Ley 39\/2006 de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a las Personas en Situaci\u00f3n de Dependencia\u201d<\/u><\/b>, se han reunido a las 13:00 horas del d\u00eda de la fecha, en la Conselleria de Bienestar Social con su titular, la consellera Sra. D\u00f1a. Ang\u00e9lica Such.&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">Las plataformas han expuesto las deficiencias, seg\u00fan ellas, en la aplicaci\u00f3n de esta ley en nuestra comunidad.<\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">1\u00ba.- Ante la demanda de que las solicitudes presentadas en 2007 queden resueltas antes de dos meses (final de 2009), la consellera no se compromete a su resoluci\u00f3n pero s\u00ed a estudiar el porqu\u00e9 del retraso y hasta d\u00f3nde van a poder llegar, y en el plazo de 15 dias comunicarlo a las Plataformas.&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">2\u00ba.- Se le solicita que una vez recibida la resoluci\u00f3n del PIA, con la prestaci\u00f3n correspondiente, se haga efectiva en el plazo m\u00e1ximo de un mes. Sobre este punto dice que lo estudiar\u00e1 y dar\u00e1 una respuesta.&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">3\u00ba.- Se le ha pedido una regulaci\u00f3n y desarrollo de la figura del asistente personal, urgente para grandes dependientes. No se compromete a su resoluci\u00f3n pero tambi\u00e9n dar\u00e1 una respuesta en 15 dias.&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">4\u00ba.- Respecto a la petici\u00f3n de la retirada del decreto del r\u00e9gimen de incompatibilidades, la consellera no tiene voluntad de retirarlo, aludiendo que lo que hay que hacer es llegar donde no hay ning\u00fan recurso y no pensar en un segundo antes de resolver los anteriores situaciones. Seg\u00fan ella hay que priorizar objetivos y recursos. S\u00ed se compromete a que existen clausulas de flexibilizaci\u00f3n que atiendan a situaciones concretas.&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">5\u00ba.- Le pedimos la retroactividad con arreglo a Ley incluyendo a las personas fallecidas. Ella considera respecto a este tema que debe haber un criterio homog\u00e9neo a nivel nacional y que hay que esperar a la decisi\u00f3n del Consejo Interterritorial. <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">6\u00ba.- Se solicita la descentralizaci\u00f3n y las resoluciones de los expedientes en las delegaciones territoriales provinciales de Bienestar Social. La consellera comenta que no hay suficientes recursos para llevarlo a cabo.&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">7\u00ba.- Respecto a la Salud Mental, aunque la plataforma considera deb\u00eda de estar dentro del sistema general de salud con todos sus efectos sanitarios, considera que mientras que est\u00e9 adscrito a Bienestar Social se dispondr\u00e1 de recursos para atender a este colectivo. La consellera plantea que est\u00e1 planificada su ampliaci\u00f3n y se compromete a facilitar todas las cifras y datos de los recursos en pr\u00f3ximas reuniones. A pesar de ello le manifestamos la absoluta carencia de plazas en especial p\u00fablicas.&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">Por \u00faltimo se juzga cr\u00edticamente el borrador del proyecto del Bono para Enfermedades Mentales (BONEM). La consellera nos remite a reuniones posteriores para su modificaci\u00f3n, si cabe.&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/h3>\n<h3 align=\"justify\">Se termina la reuni\u00f3n expresando por parte de las Plataformas la opini\u00f3n de que es una verg\u00fcenza que para que se aplique la Ley de Dependencia tengamos que recurrir a los tribunales de justicia.<\/h3>\n<p align=\"justify\">.<\/p>\n<p align=\"justify\">.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#160; &#160; &#160; &#160; &#160; &#160; &#160; &#160; &#160; COMUNICADO DE PRENSA VALENCIA 27\/10\/09 &#160; &#160; Las \u201cPlataformas de la Comunidad Valenciana en Defensa de la Ley 39\/2006 de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a las Personas en Situaci\u00f3n de Dependencia\u201d, se han reunido a las 13:00 horas del d\u00eda de la fecha, [&hellip;]<\/p>\n","protected":false},"author":791,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5239,5721],"tags":[],"class_list":["post-2219","post","type-post","status-publish","format-standard","hentry","category-comunicado-de-la-plataforma-en-defensa-de-la-ley-de-dependencia","category-nota-de-prensa"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/2219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/users\/791"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/comments?post=2219"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/2219\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/media?parent=2219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/categories?post=2219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/tags?post=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}