{"id":474,"date":"2007-11-25T17:38:00","date_gmt":"2007-11-25T15:38:00","guid":{"rendered":"https:\/\/blogs.ua.es\/diversitatfuncional\/2007\/11\/25\/la-razon-solo-tiene-un-camino\/"},"modified":"2007-11-25T17:38:00","modified_gmt":"2007-11-25T15:38:00","slug":"la-razon-solo-tiene-un-camino","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/diversitatfuncional\/2007\/11\/25\/la-razon-solo-tiene-un-camino\/","title":{"rendered":"La raz\u00f3n solo tiene un camino&#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/www.nortecastilla.es\/20071125\/vida\/manuel-recupera-sonrisa-20071125.html#comentarios\"><img decoding=\"async\" style=\"margin: 0px auto 10px;text-align: center\" src=\"http:\/\/bp1.blogger.com\/_Ti_EM1H5nCo\/R0mX0dONjoI\/AAAAAAAABOM\/1YBM4HNIqCU\/s400\/nortecastilla.gif\" alt=\"\" border=\"0\" \/><\/a><br \/><span style=\"font-weight: bold;font-family: verdana;font-size:180%\">Manuel recupera la sonrisa.<\/span><\/p>\n<div class=\"grouphead\">\n<div class=\"overhead\">\n<div class=\"ln\" id=\"story-antetitulo\"><\/div>\n<\/p><\/div>\n<div class=\"headline\">\n<div class=\"ln\" id=\"story-titulo\"><\/div>\n<\/p><\/div>\n<div class=\"subhead\">\n<div style=\"text-align: left\"> <\/div>\n<div class=\"ln\" id=\"story-subtitulo\">\n<div style=\"text-align: left\"><span style=\"font-weight: bold;font-size:180%\">Un enfermo de Esclerosis Lateral Amiotr\u00f3fica (ELA) recupera en los juzgados el derecho a ver a su hija de siete a\u00f1os, cuya madre no le dejaba viajar a Cantabria desde Madrid para estar con su padre.<\/span><\/div>\n<p><span style=\"font-weight: bold;font-size:180%\"> <\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"date\">25.11.07 &#8211;<\/p><\/div>\n<div class=\"byline\">\n<div class=\"author\">\n<div class=\"name\">CONSUELO DE LA PE\u00d1A<\/div>\n<div class=\"description\"> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"OpcArt\"><\/div>\n<p>   getEstrellas()getVotos()      if (window.document.getElementById(&#8216;num-comentarios&#8217;)) getNumComentarios(&#8216;5.0.40277593006&#8217;) <\/p>\n<div class=\"text\">\n<div class=\"pbox\">\n<div class=\"photo\"> <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.nortecastilla.es\/prensa\/noticias\/200711\/25\/fotos\/074D7VP1_1.jpg\" alt=\"Manuel recupera la sonrisa\" height=\"179\" width=\"253\" \/><\/p>\n<div class=\"photo-caption\"><span style=\"font-weight: bold;font-size:85%\">Manuel Gancedo, junto a su gato, tras conocer la sentencia del juez. <\/span><\/p>\n<p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"barhead\">\n<div class=\"ln\" id=\"story-entradilla\"> <\/div>\n<\/p><\/div>\n<div class=\"p\" id=\"story-texto\">\n<div style=\"text-align: justify\"><span style=\"font-weight: bold;font-size:130%\">Manuel Gancedo vive prisionero de su cuerpo. S\u00f3lo mueve los ojos, su \u00fanico instrumento de comunicaci\u00f3n, porque desde el 2003 sufre Esclerosis Lateral Amiotr\u00f3fica (ELA). Pero sus ganas de vivir y su ilusi\u00f3n son tan conmovedoras como su fortaleza. El viernes fue un gran d\u00eda para \u00e9l y Magdalena Roji, una madre coraje que est\u00e1 permanentemente a su lado. El Juzgado n\u00famero 3 de Colmenar Viejo acord\u00f3 restablecer el r\u00e9gimen de visitas de su hija de siete a\u00f1os, cuya madre, residente en la localidad madrile\u00f1a de Hoyo de Manzanares, no le dejaba viajar a El Astillero (Cantabria) para estar con Manuel. <\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">Lleva a\u00f1o y medio sin ver a la peque\u00f1a porque su ex esposa se neg\u00f3 a ello con argumentos m\u00e1s lacerantes que la propia enfermedad, que incluyeron denuncias falsas por maltrato. El viernes, el hogar de Manuel era puro j\u00fabilo y la familia se prepara para recibir a esa ni\u00f1a de siete a\u00f1os que es el mejor aliado para luchar contra la enfermedad.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">El doctor Julio Mir\u00f3, m\u00e9dico de cabecera de Manuel, y \u00abel padre que no tiene\u00bb, apostilla Magdalena, fue a visitarle y nos dio su visi\u00f3n del caso. \u00abLa relaci\u00f3n de Elena con su padre, seg\u00fan lo que he presenciado, es muy buena. Manuel tom\u00f3 una decisi\u00f3n muy importante en su vida, que fue conectarse a un respirador artificial, y el motivo fundamentalmente fue poder ver unos a\u00f1os m\u00e1s a su hija. Ps\u00edquicamente es una persona completamente normal; emocionalmente est\u00e1 bien y es un hombre muy fuerte. Domina su estado mental y su ilusi\u00f3n es ver a su hija. Mi opini\u00f3n es que no es una relaci\u00f3n negativa para la ni\u00f1a\u00bb.<\/span><\/div>\n<p><\/p>\n<div style=\"text-align: justify\"><span style=\"font-weight: bold;font-size:130%\">La ni\u00f1a ha ido viendo la evoluci\u00f3n de su padre desde que ten\u00eda tres a\u00f1os hasta que hace a\u00f1o y medio la madre de la peque\u00f1a impidi\u00f3 todo tipo de contacto. La lucha de Manuel fue desde entonces recuperar el contacto con su hija, a lo que su ex pareja \u00abse neg\u00f3 en redondo. De hecho no podemos ni hablar por tel\u00e9fono con la ni\u00f1a. Ha sido una lucha constante\u00bb, subraya Magdalena Roji, que agradece el apoyo recibido de la Confederaci\u00f3n de Hombres y Mujeres Separados de Sevilla, \u00abque son quienes de verdad nos han ayudado\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">La familia ahora reclama que la justicia sea m\u00e1s r\u00e1pida, que nadie tenga que esperar a\u00f1o y medio para que \u00abnos reconozcan este derecho\u00bb porque \u00abManuel no sabe el tiempo que le queda\u00bb, dice su madre con una entereza ejemplar. \u00abEs una enfermedad cruel, que no tiene cura, y estad\u00edsticamente dan cinco a\u00f1os de vida. Mi hijo va hacerlos ya. Intelectualmente est\u00e1 muy bien. Es psic\u00f3logo cl\u00ednico, sabe lo que hace y lo que dice. Si hubiese pensado en alg\u00fan momento que hac\u00eda da\u00f1o a su hija, hubiera sido el primero en no querer verla, pero no es el caso\u00bb, afirma Magdalena mientras su hijo esboza una sonrisa perenne. <\/span><\/p>\n<p><span style=\"font-weight: bold;font-size:130%\">\u00abEl juez ha decidido que la ni\u00f1a venga a ver a su padre un fin de semana al mes y las vacaciones compartidas. Hay que entender que esta ni\u00f1a no es que tenga solamente un padre; tiene una abuela y unos familiares, es mi \u00fanico hijo y ella es la \u00fanica nieta que tengo. Tengo que velar por ella, con y sin mi hijo, y tengo los mismos derechos que puede tener su abuela materna. Y estoy en la obligaci\u00f3n de tenerla\u00bb.<\/p>\n<p><\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Manuel recupera la sonrisa. Un enfermo de Esclerosis Lateral Amiotr\u00f3fica (ELA) recupera en los juzgados el derecho a ver a su hija de siete a\u00f1os, cuya madre no le dejaba viajar a Cantabria desde Madrid para estar con su padre. 25.11.07 &#8211; CONSUELO DE LA PE\u00d1A getEstrellas()getVotos() if (window.document.getElementById(&#8216;num-comentarios&#8217;)) getNumComentarios(&#8216;5.0.40277593006&#8217;) Manuel Gancedo, junto a su [&hellip;]<\/p>\n","protected":false},"author":791,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[306],"tags":[],"class_list":["post-474","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/users\/791"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/474\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/media?parent=474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/categories?post=474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/tags?post=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}