{"id":877,"date":"2008-03-06T18:04:00","date_gmt":"2008-03-06T16:04:00","guid":{"rendered":"https:\/\/blogs.ua.es\/diversitatfuncional\/2008\/03\/06\/camps-prefiere-la-formula-1-que-ayudar-a-sus-dependientes\/"},"modified":"2008-03-06T18:04:00","modified_gmt":"2008-03-06T16:04:00","slug":"camps-prefiere-la-formula-1-que-ayudar-a-sus-dependientes","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/diversitatfuncional\/2008\/03\/06\/camps-prefiere-la-formula-1-que-ayudar-a-sus-dependientes\/","title":{"rendered":"Camps prefiere la Formula 1 que ayudar a sus dependientes."},"content":{"rendered":"<p><a href=\"http:\/\/www.levante-emv.com\/servicios\/cartasdirector\/cartaLector.jsp?pIdCarta=5659&amp;pRef=2008030600_0_0\" target=\" blank\"><img decoding=\"async\" style=\"margin: 0px auto 10px;text-align: center\" src=\"http:\/\/bp3.blogger.com\/_Ti_EM1H5nCo\/R9AXT4IC_jI\/AAAAAAAACMo\/cO-uUzxDrwI\/s400\/logo_levante.jpg\" alt=\"\" border=\"0\" \/><\/a><\/p>\n<h3 style=\"font-family: trebuchet ms;text-align: justify;font-weight: bold\"><a href=\"http:\/\/bp2.blogger.com\/_Ti_EM1H5nCo\/R9AXHoIC_iI\/AAAAAAAACMg\/xsN1cGh3jpk\/s1600-h\/CampsRajoy.jpg\"><img decoding=\"async\" style=\"margin: 0pt 10px 10px 0pt;float: left\" src=\"http:\/\/bp2.blogger.com\/_Ti_EM1H5nCo\/R9AXHoIC_iI\/AAAAAAAACMg\/xsN1cGh3jpk\/s400\/CampsRajoy.jpg\" alt=\"\" border=\"0\" \/><\/a><a href=\"http:\/\/www.levante-emv.com\/servicios\/cartasdirector\/cartaLector.jsp?pIdCarta=5659&amp;pRef=2008030600_0_0\" target=\" blank\">Camps y la Ley de la Dependencia<\/a><\/h3>\n<div style=\"text-align: justify;font-weight: bold\">           <span style=\"font-family:trebuchet ms\"><br \/>Hace exactamente nueve meses solicitamos acogernos a la ley de dependencia ya que mi padre,con 85 a\u00f1os y varias enfermedades, carece de autonom\u00eda propia. Hasta la fecha nadie se ha dignado indicarme para cuando ser\u00e1 resuelta mi solicitud. Llamando a Avapsa me dicen que esta pendiente de evaluaci\u00f3n, sino eval\u00faan no hay dictamen y no podemos cobrar, as\u00ed es que las cosas se demoran en el tiempo. \u00bfComo pueden acumular tanto retraso? \u00bfNo tienen gente suficiente o cuando lo hagan sera con car\u00e1cter retroactivo?<\/p>\n<p><\/span><span style=\"font-family:trebuchet ms\"> Hay muchas familias en mi misma situaci\u00f3n que ven con angustia el futuro de sus seres queridos, ya que no saben hasta cuando podr\u00e1n seguir pagando de sus bolsillos las residencias.<\/p>\n<p><\/span><span style=\"font-family:trebuchet ms\"> Creo Sr. Camps, que atender a los mas desfavorecidos, no le encumbrar\u00e1 como el circuito de F-1, que para esto si hay dinero, pero solucionar\u00e1 la angustia de muchos ancianos y sus familias.-In\u00e9s Cosme. Massanassa.<\/p>\n<p><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Camps y la Ley de la Dependencia Hace exactamente nueve meses solicitamos acogernos a la ley de dependencia ya que mi padre,con 85 a\u00f1os y varias enfermedades, carece de autonom\u00eda propia. Hasta la fecha nadie se ha dignado indicarme para cuando ser\u00e1 resuelta mi solicitud. Llamando a Avapsa me dicen que esta pendiente de evaluaci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":791,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[306],"tags":[],"class_list":["post-877","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/users\/791"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/comments?post=877"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/posts\/877\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/categories?post=877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/diversitatfuncional\/wp-json\/wp\/v2\/tags?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}