{"id":170,"date":"2012-01-18T17:29:52","date_gmt":"2012-01-18T17:29:52","guid":{"rendered":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/?p=170"},"modified":"2012-01-18T17:29:52","modified_gmt":"2012-01-18T17:29:52","slug":"la-reforma-luterana","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/2012\/01\/18\/la-reforma-luterana\/","title":{"rendered":"La Reforma Luterana"},"content":{"rendered":"<p><em>La Reforma Luterana<\/em>. Unesco, 15 de Diciembre de 2010. Disponible en: <a href=\"http:\/\/www.youtube.com\/watch?v=roYS5wAcnEU&amp;list=PLB7CD35828349F349&amp;index=10&amp;feature=plpp_video\">http:\/\/www.youtube.com\/watch?v=roYS5wAcnEU&amp;list=PLB7CD35828349F349&amp;index=10&amp;feature=plpp_video<\/a><\/p>\n<p>En el siglo XVI numerosas personalidades intentaron llevar a cabo un cambio en las costumbres de la Iglesia Cat\u00f3lica. Este movimiento fue llamado Reforma Protestante.<\/p>\n<p><a href=\"https:\/\/blogs.ua.es\/documentalesedadmoderna\/files\/2012\/01\/200px-Luther46c.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-218\" src=\"https:\/\/blogs.ua.es\/documentalesedadmoderna\/files\/2012\/01\/200px-Luther46c.jpg\" alt=\"\" width=\"200\" height=\"215\" \/><\/a>El encargado de promover la reforma fue Mart\u00edn Lutero, un te\u00f3logo y religioso alem\u00e1n y uno de los mayores exponentes de este movimiento. Cre\u00f3 la doctrina luterana e influy\u00f3 en la tradici\u00f3n protestante.<\/p>\n<p>Su voluntad de que la Iglesia volviese a la doctrina de la Biblia impuls\u00f3 la transformaci\u00f3n del cristianismo y provoc\u00f3 la Contrarreforma, que es como conocemos a la reacci\u00f3n de la Iglesia Cat\u00f3lica Romana contra la Reforma Protestante. Contribuy\u00f3 con la civilizaci\u00f3n occidental mas all\u00e1 de la religi\u00f3n a que sus traducciones de la Biblia ayudaron a desarrollar una versi\u00f3n est\u00e1ndar de la lengua alemana y se convirtieron en un modelo en el arte de la traducci\u00f3n. Su matrimonio con Catalina de Bora el 13 de junio de 1525 inici\u00f3 un movimiento de apoyo al matrimonio sacerdotal dentro de muchas corrientes cristianas.<\/p>\n<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/roYS5wAcnEU\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Reforma Luterana. Unesco, 15 de Diciembre de 2010. Disponible en: http:\/\/www.youtube.com\/watch?v=roYS5wAcnEU&amp;list=PLB7CD35828349F349&amp;index=10&amp;feature=plpp_video En el siglo XVI numerosas personalidades intentaron llevar a cabo un cambio en las costumbres de la Iglesia Cat\u00f3lica. Este movimiento fue llamado Reforma Protestante. El encargado de promover la reforma fue Mart\u00edn Lutero, un te\u00f3logo y religioso alem\u00e1n y uno de los [&hellip;]<\/p>\n","protected":false},"author":2357,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86622],"tags":[1516,69,7036,4029,2088],"class_list":["post-170","post","type-post","status-publish","format-standard","hentry","category-audiovisuales","tag-alemania","tag-iglesia","tag-lutero","tag-reforma","tag-religion"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/posts\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/users\/2357"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/posts\/170\/revisions"}],"predecessor-version":[{"id":219,"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/posts\/170\/revisions\/219"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/media?parent=170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/categories?post=170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalesedadmoderna\/wp-json\/wp\/v2\/tags?post=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}