{"id":96,"date":"2012-01-03T19:42:00","date_gmt":"2012-01-03T19:42:00","guid":{"rendered":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/?p=96"},"modified":"2012-01-03T19:42:00","modified_gmt":"2012-01-03T19:42:00","slug":"las-lagrimas-del-presidente","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/2012\/01\/03\/las-lagrimas-del-presidente\/","title":{"rendered":"Las l\u00e1grimas del presidente"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><em>Las l\u00e1grimas del presidente. RTVE<\/em><span style=\"font-family: TimesNewRomanPS-ItalicMT\"><span style=\"font-family: TimesNewRomanPSMT\">, 2010.<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: TimesNewRomanPS-ItalicMT\"><span style=\"font-family: TimesNewRomanPSMT\">Documental sobre c\u00f3mo fue contada la transici\u00f3n en Televisi\u00f3n Espa\u00f1ola, elaborado no\u00a0\u00fanicamente mediante entrevistas a personajes relevantes sino\u00a0a partir, sobretodo, de materiales de archivo como\u00a0pel\u00edculas, espect\u00e1culos, canciones de la \u00e9poca y discursos de las diversas campa\u00f1as electorales de los partidos. Es una recopilaci\u00f3n de todo lo que pudo ofrecer rtve como elemento importante y fundamental en la comunicaci\u00f3n. <\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: TimesNewRomanPS-ItalicMT\"><span style=\"font-family: TimesNewRomanPSMT\"><\/span><\/span><\/p>\n<figure id=\"attachment_97\" aria-describedby=\"caption-attachment-97\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/files\/2012\/01\/ggggggggggggggggg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-97\" src=\"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/files\/2012\/01\/ggggggggggggggggg-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/files\/2012\/01\/ggggggggggggggggg-300x158.jpg 300w, https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/files\/2012\/01\/ggggggggggggggggg-150x79.jpg 150w, https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/files\/2012\/01\/ggggggggggggggggg.jpg 309w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-97\" class=\"wp-caption-text\">Portada del documental &quot;Las l\u00e1grimas del presidente&quot;<\/figcaption><\/figure>\n<p style=\"text-align: justify\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Las l\u00e1grimas del presidente. RTVE, 2010. Documental sobre c\u00f3mo fue contada la transici\u00f3n en Televisi\u00f3n Espa\u00f1ola, elaborado no\u00a0\u00fanicamente mediante entrevistas a personajes relevantes sino\u00a0a partir, sobretodo, de materiales de archivo como\u00a0pel\u00edculas, espect\u00e1culos, canciones de la \u00e9poca y discursos de las diversas campa\u00f1as electorales de los partidos. Es una recopilaci\u00f3n de todo lo que pudo [&hellip;]<\/p>\n","protected":false},"author":2341,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86622],"tags":[6037,89123],"class_list":["post-96","post","type-post","status-publish","format-standard","hentry","category-audiovisuales","tag-documental","tag-rtve"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/posts\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/users\/2341"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/posts\/96\/revisions"}],"predecessor-version":[{"id":99,"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/posts\/96\/revisions\/99"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/media?parent=96"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/categories?post=96"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/documentalespeliculastransicionespanola\/wp-json\/wp\/v2\/tags?post=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}