{"id":90,"date":"2010-11-26T16:57:49","date_gmt":"2010-11-26T15:57:49","guid":{"rendered":"https:\/\/blogs.ua.es\/drenajefantasma\/?p=90"},"modified":"2011-05-25T17:16:47","modified_gmt":"2011-05-25T16:16:47","slug":"a-titulo-personal-sobre-asociaciones","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/drenajefantasma\/2010\/11\/26\/a-titulo-personal-sobre-asociaciones\/","title":{"rendered":"A t\u00edtulo personal. Sobre asociaciones."},"content":{"rendered":"<p style=\"text-align: justify\">En \u00a0este blog se ofrecer\u00e1n, dentro de la capacidad humana de la autora, todas las <strong>noticias concernientes a la discapacidad y a la superdotaci\u00f3n<\/strong>, al igual que los art\u00edculos respectivos, pero<strong> incidiendo en las altas capacidades y en el s\u00edndrome de Asperger<\/strong>.<\/p>\n<p style=\"text-align: justify\">Tambi\u00e9n habr\u00e1 preferencia a la hora de seleccionar las noticias.<\/p>\n<p style=\"text-align: justify\">Se hablar\u00e1 y tratar\u00e1 con mayor detalle la informaci\u00f3n ofrecida por las siguientes asociaciones:<\/p>\n<p style=\"text-align: justify\"><strong><a href=\"http:\/\/www.asociacioniv.org\/\" target=\"_blank\">Asociaci\u00f3n Inteligencia y Vida<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify\"><strong><a href=\"http:\/\/www.mensa.es\/\" target=\"_blank\">Mensa Espa\u00f1a<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify\"><strong><a href=\"http:\/\/www.aspergeralicante.com\/\" target=\"_blank\">Asociaci\u00f3n Asperger Alicante. (Aspali)<\/a><\/strong><\/p>\n<p style=\"text-align: justify\">M\u00e1s adelante iremos ofreciendo detalles sobre distintos aspectos que conciernen a estas asociaciones.<\/p>\n<p style=\"text-align: justify\">El por qu\u00e9 se unen en este blog ambos conceptos, superdotaci\u00f3n y s\u00edndrome de Asperger. Porque <strong><a href=\"http:\/\/asperger.es\/publicaciones.php?id=3&amp;cap=123&amp;cat=3\" target=\"_blank\">muchos sujetos con Asperger son superdotados<\/a><\/strong> y al detectarse antes la discapacidad se pasar por alto su superdotaci\u00f3n y se les vuelve personas in\u00fatiles en lugar de usar esa capacidad para integrarlos.<\/p>\n<p style=\"text-align: justify\">Por otra parte <strong><a href=\"http:\/\/www.espaciologopedico.com\/tienda\/detalle?Id_articulo=6233\" target=\"_blank\">muchos superdotados tienen un s\u00edndrome de Asperger<\/a><\/strong> sin diagnosticar que se encuentra oculto debido a que han conseguido hacer de su tema central, en el que son expertos, su trabajo y procuran ce\u00f1irse a \u00e9l, ocultando sus debilidades en otros aspectos de su vida, sobre todo el de la socializaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Esperemos mostrar desde aqu\u00ed que, ante todo, son <strong>PERSONAS <\/strong>con defectos y virtudes como todo el mundo y que su integraci\u00f3n puede costar m\u00e1s o menos tiempo y esfuerzo pero son personas muy \u00fatiles para la sociedad.<\/p>\n<p style=\"text-align: justify\">Muchos de los ni\u00f1os \u00a0con superdotaci\u00f3n y\/o asperger entran dentro del campo de estudio y trabajo de las <strong><a href=\"http:\/\/www.conocimientosweb.net\/portal\/article1771.html\" target=\"_blank\">necesidades educativas especiales<\/a><\/strong>. Veremos, m\u00e1s adelante, el por qu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En \u00a0este blog se ofrecer\u00e1n, dentro de la capacidad humana de la autora, todas las noticias concernientes a la discapacidad y a la superdotaci\u00f3n, al igual que los art\u00edculos respectivos, pero incidiendo en las altas capacidades y en el s\u00edndrome de Asperger. Tambi\u00e9n habr\u00e1 preferencia a la hora de seleccionar las noticias. Se hablar\u00e1 y [&hellip;]<\/p>\n","protected":false},"author":909,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22800,22801,22796,22798],"tags":[22834,4462,22836,22835,22777],"class_list":["post-90","post","type-post","status-publish","format-standard","hentry","category-asociaciones-asperger","category-asociaciones-superdotacion-y-altas-capacidades","category-asperger-2","category-superdotacion-2","tag-asociacion-inteligencia-y-vida","tag-asperger","tag-asperger-alicante-aspali","tag-mensa-espana","tag-superdotacion"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/users\/909"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":3,"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"predecessor-version":[{"id":92,"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/posts\/90\/revisions\/92"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/drenajefantasma\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}