{"id":867,"date":"2021-05-13T09:00:37","date_gmt":"2021-05-13T08:00:37","guid":{"rendered":"https:\/\/blogs.ua.es\/eafe\/?p=867"},"modified":"2021-05-13T09:00:37","modified_gmt":"2021-05-13T08:00:37","slug":"cuando-es-momento-de-cambiar-el-perfil-inversor","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/eafe\/cuando-es-momento-de-cambiar-el-perfil-inversor\/","title":{"rendered":"CU\u00c1NDO ES MOMENTO DE CAMBIAR EL PERFIL INVERSOR"},"content":{"rendered":"<figure style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large\" src=\"https:\/\/fundspeople-multisite.s3.eu-west-1.amazonaws.com\/wp-content\/uploads\/sites\/2\/2020\/11\/3be086c1da1f433e.jpg\" alt=\"Wiertz S\u00e9bastien, Flickr, Creative Commons\" width=\"600\" height=\"340\" \/><figcaption class=\"wp-caption-text\">Wiertz S\u00e9bastien, Flickr, Creative Commons<\/figcaption><\/figure>\n<p>La alta volatilidad vista en los mercados en el \u00faltimo a\u00f1o de COVID-19 unida a la gran incertidumbre que ha tra\u00eddo consigo la pandemia ha puesto a prueba a los inversores. Los datos demuestran que a diferencia de lo sucedido en otras crisis, con \u00e9sta, han sido m\u00e1s los que se han optado por mantenerse invertidos en los peores momentos de mercado que los que optaron por deshacer posiciones, incluso aunque ello supusiera asumir p\u00e9rdidas puntuales. Y los primeros hicieron bien ya que\u00a0<a href=\"https:\/\/fundspeople.com\/es\/que-puedo-decirle-a-mi-cliente-cuando-pregunte-por-como-ha-ido-su-cartera-este-ano\/\" target=\"_blank\" rel=\"noreferrer noopener\">en 2020 fueron muchos m\u00e1s los activos que acabaron en positivo que los que lo hicieron en negativo<\/a>.<\/p>\n<p><!--more--><\/p>\n<p>Cala, por tanto,\u00a0 cada vez m\u00e1s la idea de que<a href=\"https:\/\/fundspeople.com\/es\/la-guia-definitiva-de-banqueros-privados-y-asesores-financieros-para-evitar-que-sus-clientes-entren-en-panico-ante-caidas-del-mercado\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0permanecer en el mercado es siempre la mejor opci\u00f3n para un inversor de largo plazo<\/a>\u00a0. Los vaivenes de mercado no son por si solos una excusa para cambiar el perfil de un inversor, pero s\u00ed hay casos en los que conviene revisar ese perfil.<\/p>\n<p>Ian Tam, CFA y director de Investment Research para\u00a0<a href=\"https:\/\/fundspeople.com\/es\/empresa\/morningstar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Morningstar<\/a>\u00a0Canad\u00e1, ha elaborado una lista de esos momentos que pueden constituir una buena causa para que un inversor se replantee la estructura de su cartera.<\/p>\n<p>Para ello identifica los\u00a0<strong>dos tipos de capital con los que cuenta cualquier persona: el capital humano, que es la capacidad de ganar dinero con el tiempo, y el capital financiero<\/strong>, que es la cantidad actual de dinero que se tiene disponible para invertir. En l\u00edneas generales, cuando m\u00e1s alto sean ambos mejor. Sin embargo, lo habitual es que los j\u00f3venes tengan mucho capital humano y poco financiero y los mayores, justo lo contrario. \u00abA la hora de elegir una estrategia de inversi\u00f3n, su capacidad de riesgo tiene mucho que ver con la suma de capital financiero y humano. Cuanto m\u00e1s capital tenga (humano o financiero), m\u00e1s riesgo podr\u00e1 asumir. Hay etapas de la vida en las que el equilibrio entre el capital humano y el financiero cambiar\u00e1, y en ese momento es posible que desee considerar la revisi\u00f3n de su estrategia de inversi\u00f3n\u00bb, afirma el autor.<\/p>\n<p>No hay un n\u00famero concreto de cu\u00e1ntas etapas vitales que puedan llevar a un cambio de estrategia financiera pero Ian Tam identifica las m\u00e1s frecuentes y las reproducimos a continuaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>P\u00e9rdida de empleo<\/strong>: Cuando se pierde el empleo, el capital humano potencial disminuye. Hay que sentarse a analizar si esa situaci\u00f3n puede extenderse mucho o poco en el tiempo. \u201cSi se trata de un cambio permanente, su capacidad para soportar el riesgo tambi\u00e9n disminuye y, por tanto, puede tener sentido una revisi\u00f3n de su estrategia de inversi\u00f3n hacia un enfoque m\u00e1s conservador\u201d, asegura.<\/li>\n<\/ul>\n<ul>\n<li><strong>Cambios en el c\u00edrculo familiar<\/strong>: No es lo mismo trabajar para uno mismo que trabajar para sustentar a uno mismo y a m\u00e1s miembros de la familia. \u201cSi ahora es usted responsable del cuidado econ\u00f3mico de un ser querido, puede que no tenga la misma capacidad de resistir el riesgo. Una vez m\u00e1s, puede valer la pena revisar su estrategia de inversi\u00f3n en favor de un enfoque m\u00e1s conservador\u201d, afirma.<\/li>\n<\/ul>\n<ul>\n<li><strong>Regalo \/ herencia<\/strong>: Si recibe un regalo en met\u00e1lico o una herencia de un familiar, es el capital financiero el que aumenta y eso puede justificar una estrategia de inversi\u00f3n m\u00e1s agresiva.<\/li>\n<\/ul>\n<ul>\n<li><strong>Jubilaci\u00f3n<\/strong>: Cuando uno se jubila, pasa de la fase de acumulaci\u00f3n de capital a la fase de rescate. Se trata de un acontecimiento importante que sin duda requiere una revisi\u00f3n del enfoque de inversi\u00f3n que implique una transici\u00f3n a inversiones m\u00e1s conservadoras.<\/li>\n<\/ul>\n<p>No obstante, hay que tener en cuenta que\u00a0<strong>el aumento de la esperanza de vida ha alargado el tiempo en el que pasamos jubilados, lo que exige que esa transici\u00f3n no sea muy brusca<\/strong>. M\u00e1s, en un contexto de tipos de inter\u00e9s al 0% e inflaci\u00f3n al alza que acaba repercutiendo muy negativamente en las rentabilidades reales de los productos m\u00e1s conservadores.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <a href=\"https:\/\/fundspeople.com\/es\/cuando-es-momento-de-cambiar-el-perfil-inversor\/?utm_source=sfmc&amp;utm_medium=email&amp;utm_campaign=Newsletter_Diaria_Spain_2021051308115\/13\/2021&amp;utm_term=https%3a%2f%2ffundspeople.com%2fes%2fcuando-es-momento-de-cambiar-el-perfil-inversor%2f\" target=\"_blank\" rel=\"noopener\">FundsPeople<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La alta volatilidad vista en los mercados en el \u00faltimo a\u00f1o de COVID-19 unida a la gran incertidumbre que ha tra\u00eddo consigo la pandemia ha puesto a prueba a los inversores. Los datos demuestran que a diferencia de lo sucedido en otras crisis, con \u00e9sta, han sido m\u00e1s los que se han optado por mantenerse [&hellip;]<\/p>\n","protected":false},"author":4210,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2234099,2191943],"tags":[],"class_list":["post-867","post","type-post","status-publish","format-standard","hentry","category-asesoramiento-financiero-eafi","category-pensiones-y-planificacion-de-la-jubilacion"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/posts\/867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/users\/4210"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/comments?post=867"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/posts\/867\/revisions"}],"predecessor-version":[{"id":868,"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/posts\/867\/revisions\/868"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/media?parent=867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/categories?post=867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/eafe\/wp-json\/wp\/v2\/tags?post=867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}