{"id":534,"date":"2009-04-05T14:34:51","date_gmt":"2009-04-05T14:34:51","guid":{"rendered":"http:\/\/educa06.wordpress.com\/?p=534"},"modified":"2009-04-05T14:34:51","modified_gmt":"2009-04-05T14:34:51","slug":"concurso-de-mascotas-don-peloto","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/educa06\/2009\/04\/05\/concurso-de-mascotas-don-peloto\/","title":{"rendered":"Concurso de Mascotas: Don Peloto"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-535\" title=\"screen-capture-1\" src=\"http:\/\/educa06.files.wordpress.com\/2009\/04\/screen-capture-1.png\" alt=\"screen-capture-1\" width=\"480\" height=\"437\" \/>NUESTRA MASCOTA: DON PELOTO<\/p>\n<p>Don Peloto es un se\u00f1orito muy flexible, capaz de convertirse en m\u00faltiples personajes.\u00a0 Puede llegar a ser desde un marinero hasta un torero.<br \/>\nSu f\u00edsico es muy atractivo. Tiene una cara redonda y muy manejable para poder moldearla a nuestro gusto; unos labios carnosos y jugosos de color fresa y\u00a0 unos colores muy llamativos en sus mejillas.<br \/>\nTodo su cuerpo se compone de diversas piezas, todas ellas desmontables, que se pueden quitar y poner libremente y con facilidad gracias al velcro que est\u00e1 incorporado en cada una de las piezas.<br \/>\nEs blandito, todo su cuerpo est\u00e1 relleno de bolitas, cosa que permite su elasticidad.<br \/>\nLe podemos poner desde una sonrisa con unos dientes radiantes hasta una cara tristona.\u00a0 Nuestro Don Peloto consta de una gran diversidad de artilugios adaptados a las distintas situaciones del d\u00eda en las que se encuentra y al tiempo que se presente; posee corbatas para los d\u00edas m\u00e1s glamurosos y hasta gorras y gafas de sol para los d\u00edas m\u00e1s veraniegos y relajantes.<br \/>\nDon Peloto puede convertirse en chica o en chico; su gran virtud es que le podemos poner desde vestidos hasta calzoncillos.\u00a0 De esta forma los ni\u00f1os m\u00e1s peque\u00f1os comenzar\u00e1n a asociar los rasgos caracter\u00edsticos de cada uno de ellos.<br \/>\nNuestra mascota es divertida, agradable y curiosa. Le encanta que le mimen y aprender cosas buenas le apasiona. Entre todos, maestras y ni\u00f1os,\u00a0 ayudaremos al Don Peloto a re\u00edr, so\u00f1ar e imaginar.<br \/>\nSe trata de una mascota que nos ayudar\u00e1 en nuestros proyectos del aula, en las unidades did\u00e1cticas y en los rincones. En general, estar\u00e1 presente en las actividades m\u00e1s significativas de los ni\u00f1os.<br \/>\nPor \u00faltimo, cabe destacar que el nombre de Don Peloto ser\u00e1 pactado por todos los alumnos. De esta forma dispondr\u00e1n de un gran amigo que les acompa\u00f1ar\u00e1 durante a lo largo del curso acad\u00e9mico y el primero de sus vidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUESTRA MASCOTA: DON PELOTO Don Peloto es un se\u00f1orito muy flexible, capaz de convertirse en m\u00faltiples personajes.\u00a0 Puede llegar a ser desde un marinero hasta un torero. Su f\u00edsico es muy atractivo. Tiene una cara redonda y muy manejable para &hellip; <a href=\"https:\/\/blogs.ua.es\/educa06\/2009\/04\/05\/concurso-de-mascotas-don-peloto\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1238,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5152],"class_list":["post-534","post","type-post","status-publish","format-standard","hentry","category-general","tag-concurso-de-mascotas"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/posts\/534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/users\/1238"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/comments?post=534"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/posts\/534\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/media?parent=534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/categories?post=534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/tags?post=534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}