{"id":587,"date":"2009-04-14T14:35:23","date_gmt":"2009-04-14T14:35:23","guid":{"rendered":"http:\/\/educa06.wordpress.com\/?p=587"},"modified":"2009-04-14T14:35:23","modified_gmt":"2009-04-14T14:35:23","slug":"la-expresion-plastica-en-educacion-infanrtil","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/educa06\/2009\/04\/14\/la-expresion-plastica-en-educacion-infanrtil\/","title":{"rendered":"La Expresi\u00f3n Pl\u00e1stica en Educaci\u00f3n Infantil"},"content":{"rendered":"<p style=\"text-align:justify\"><a href=\"http:\/\/expresionplasticainfantil.blogspot.com\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"plastica\" src=\"http:\/\/www.emprendedores.es\/var\/em\/storage\/images\/ideas_de_negocio\/tendencias_mercado\/ocio\/del_papel_pintado_al_papel_por_pintar\/61979-1-esl-ES\/del_papel_pintado_al_papel_por_pintar_articulo_landscape.jpg\" alt=\"\" width=\"377\" height=\"289\" \/><\/a>Muchos creen que la expresi\u00f3n pl\u00e1stica en educaci\u00f3n infantil se limita a colorear sobre un papel en blanco, no es as\u00ed, los ni\u00f1os disponen de una gran imaginaci\u00f3n y por ello el rinc\u00f3n de la Expresi\u00f3n Pl\u00e1stica puede ser un buen recurso para explotar toda esa imaginaci\u00f3n y plasmarla de 1000 formas posibles. Si ponemos al alcance de los ni\u00f1os materiales, tiempo, atenci\u00f3n&#8230; es sorprendete el resultado. En este blog <a href=\"http:\/\/expresionplasticainfantil.blogspot.com\/\" target=\"_blank\">La Expresi\u00f3n Pl\u00e1stica en Educaci\u00f3n Infantil,<\/a> realizado por David D\u00edaz \u00c1vila, Marina Garc\u00eda-Gal\u00e1n Ruiz y Rub\u00e9n Dom\u00ednguez Usero se describen algunos criterios organizativos y metodol\u00f3gicos de los rincones y talleres de expresi\u00f3n pl\u00e1stica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos creen que la expresi\u00f3n pl\u00e1stica en educaci\u00f3n infantil se limita a colorear sobre un papel en blanco, no es as\u00ed, los ni\u00f1os disponen de una gran imaginaci\u00f3n y por ello el rinc\u00f3n de la Expresi\u00f3n Pl\u00e1stica puede ser un &hellip; <a href=\"https:\/\/blogs.ua.es\/educa06\/2009\/04\/14\/la-expresion-plastica-en-educacion-infanrtil\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1238,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[412,5137,5141],"tags":[6455],"class_list":["post-587","post","type-post","status-publish","format-standard","hentry","category-actividades","category-organizacion-del-aula","category-talleres-y-rincones","tag-expresion-plastica"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/posts\/587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/users\/1238"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/comments?post=587"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/posts\/587\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/media?parent=587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/categories?post=587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/educa06\/wp-json\/wp\/v2\/tags?post=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}