{"id":29,"date":"2007-12-04T01:14:35","date_gmt":"2007-12-04T00:14:35","guid":{"rendered":"https:\/\/blogs.ua.es\/educacionfisica\/2007\/12\/04\/el-texto-del-anuncio-de-repsol-es-de-rudyard-kipling\/"},"modified":"2007-12-04T01:25:46","modified_gmt":"2007-12-04T00:25:46","slug":"el-texto-del-anuncio-de-repsol-es-de-rudyard-kipling","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/educacionfisica\/el-texto-del-anuncio-de-repsol-es-de-rudyard-kipling\/","title":{"rendered":"El texto del anuncio de Repsol es de Rudyard Kipling"},"content":{"rendered":"<p><code>[kml_flashembed movie=\"http:\/\/www.youtube.com\/v\/UMK3vezg6qA\" width=\"425\" height=\"350\" wmode=\"transparent\" \/]<\/code><\/p>\n<p>Si puedes mantener la cabeza sobre los hombros<br \/>\ncuando otros la pierden y te cargan su culpa,<br \/>\nSi conf\u00edas en ti mismo a\u00fan cuando todos de ti dudan,<br \/>\npero a\u00fan as\u00ed tomas en cuenta sus dudas;<\/p>\n<p>Si puedes so\u00f1ar y no hacer de tus sue\u00f1os tu gu\u00eda;<br \/>\nSi puedes pensar sin hacer de tus pensamientos tu meta;<br \/>\nSi Triunfo y Derrota se cruzan en tu camino<br \/>\ny tratas de igual manera a ambos impostores,<\/p>\n<p>Si puedes hacer un mont\u00f3n con todas tus victorias<br \/>\nSi puedes arrojarlas al capricho del azar,<br \/>\ny perder, y remontarte de nuevo a tus comienzos<br \/>\nsin que salga de tus labios una queja;<\/p>\n<p>Si logras que tus nervios y el coraz\u00f3n sean tu fiel compa\u00f1ero<br \/>\ny resistir aunque tus fuerzas se vean menguadas<br \/>\ncon la \u00fanica ayuda de la voluntad que dice: \u201c\u00a1Adelante!\u201d<\/p>\n<p>Si ante la multitud das a la virtud abrigo,<br \/>\nSi a\u00fan marchando con reyes guardas tu sencillez,<br \/>\nSi no pueden herirte ni amigos ni enemigos,<\/p>\n<p>Si todos te reclaman y ninguno te precisa;<br \/>\nSi puedes rellenar un implacable minuto<br \/>\ncon sesenta segundos de combate brav\u00edo,<br \/>\ntuya es la Tierra y sus codiciados frutos,<br \/>\nY, lo que es m\u00e1s, \u00a1ser\u00e1s un Hombre, hijo m\u00edo!<br \/>\n<a href=\"http:\/\/es.wikipedia.org\/wiki\/Rudyard_Kipling\" title=\"Rudyard Kipling - Biograf\ufffda en la wikipedia\"><em>Rudyard Kipling<\/em> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[kml_flashembed movie=&#8221;http:\/\/www.youtube.com\/v\/UMK3vezg6qA&#8221; width=&#8221;425&#8243; height=&#8221;350&#8243; wmode=&#8221;transparent&#8221; \/] Si puedes mantener la cabeza sobre los hombros cuando otros la pierden y te cargan su culpa, Si conf\u00edas en ti mismo a\u00fan cuando todos de ti dudan, pero a\u00fan as\u00ed tomas en cuenta sus dudas; Si puedes so\u00f1ar y no hacer de tus sue\u00f1os tu gu\u00eda; Si puedes [&hellip;]<\/p>\n","protected":false},"author":239,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[253],"tags":[],"class_list":["post-29","post","type-post","status-publish","format-standard","hentry","category-humor"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/educacionfisica\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}